{"id":678,"date":"2023-03-02T12:12:24","date_gmt":"2023-03-02T12:12:24","guid":{"rendered":"https:\/\/tirinha.com\/survival-kit-o-festival-de-arte-da-letonia-que-enfrenta-a-guerra\/"},"modified":"2023-03-02T12:12:24","modified_gmt":"2023-03-02T12:12:24","slug":"bo-dung-cu-sinh-ton-le-hoi-nghe-thuat-latvia-doi-mat-voi-chien-tranh","status":"publish","type":"post","link":"https:\/\/tirinha.com\/vi\/678\/survival-kit-o-festival-de-arte-da-letonia-que-enfrenta-a-guerra\/","title":{"rendered":"Survival Kit, l\u1ec5 h\u1ed9i ngh\u1ec7 thu\u1eadt Latvia \u0111\u1ed1i \u0111\u1ea7u v\u1edbi chi\u1ebfn tranh"},"content":{"rendered":"<p> [ad_1]<br \/>\n<\/p>\n<div id=\"article-body-content\" data-action=\"toggle\" data-status=\"on\">\n<p id=\"paragraph_1\">Chamam-lhe festival, mas \u00e9 uma \u00fanica exposi\u00e7\u00e3o acompanhada de um programa de atividades.  O or\u00e7amento \u00e9 apertado e os n\u00fameros s\u00e3o modestos: <strong>31 artistas, previs\u00e3o de 10.000 visitantes<\/strong>.  No entanto, duvido que um evento de arte mais significativo esteja ocorrendo na Europa hoje.<\/p>\n<p id=\"paragraph_2\">Se voc\u00ea ficou chocado com a invas\u00e3o da Ucr\u00e2nia, imagine o impacto que essa virada hist\u00f3rica teve sobre o B\u00e1ltico, ainda lutando contra um passado muito recente de domina\u00e7\u00e3o sovi\u00e9tica.<\/p>\n<p id=\"paragraph_3\">A Let\u00f4nia s\u00f3 \u00e9 um pa\u00eds independente desde 1991. Est\u00e1 em processo de reconstru\u00e7\u00e3o de uma identidade nacional na qual as artes e, acima de tudo, a l\u00edngua s\u00e3o cardeais.  Mas <strong>50% da popula\u00e7\u00e3o de Riga fala russo<\/strong> e o partido que representa esta comunidade, Saska\u0146a (Harmonia), \u00e9 o mais votado no parlamento estadual \u2013embora nunca tenha governado\u2013, tem quase um quarto das cadeiras.<\/p>\n<blockquote class=\"content__blockquote\">\n<p class=\"blockquote__quote\">A exposi\u00e7\u00e3o, concebida antes da agress\u00e3o russa, ganhou uma dimens\u00e3o inesperada depois de<\/p>\n<\/blockquote>\n<p id=\"paragraph_4\"><strong>O patrim\u00f4nio hist\u00f3rico pode ser palco de conflitos<\/strong>: Poucos dias antes do lan\u00e7amento do Kit de Sobreviv\u00eancia, o Monumento da Vit\u00f3ria (do Ex\u00e9rcito Vermelho contra os nazistas) foi demolido, para grande raiva dos pr\u00f3-russos e do Kremlin.<\/p>\n<p id=\"paragraph_5\">Tamb\u00e9m a cria\u00e7\u00e3o atual: a ambiciosa bienal que a cidade lan\u00e7ou h\u00e1 alguns anos e que deveria ter celebrado sua terceira edi\u00e7\u00e3o em 2022, a RIBOCA, talvez tenha sido &#8220;adiada&#8221; <em>seno morrer<\/em>: <strong>foi um projeto russo, implementado pela filha de um magnata<\/strong> da pesca e do metanol, Gennady Mirgorodsky, e desde o in\u00edcio levantou muitas suspeitas que agora se tornaram obst\u00e1culos dif\u00edceis de superar.<\/p>\n<div class=\"article-media \" itemscope=\"\" itemtype=\"http:\/\/schema.org\/ImageObject\">\n<p><img loading=\"lazy\" decoding=\"async\" alt=\"Andrius Arutiunian: 'Arizona Club'\" data-imgm=\"true\" height=\"180\" loading=\"lazy\" sizes=\"auto, (max-width: 479px) 100vw, (max-width: 1023px) 80vw, 40vw\" src=\"https:\/\/s1.eestatic.com\/2022\/09\/18\/el-cultural\/704189972_227280850_1024x576.jpg\" srcset=\"https:\/\/s1.eestatic.com\/2022\/09\/18\/el-cultural\/704189972_227280882_320x180.jpg 320w, https:\/\/s1.eestatic.com\/2022\/09\/18\/el-cultural\/704189972_227280881_640x360.jpg 640w, https:\/\/s1.eestatic.com\/2022\/09\/18\/el-cultural\/704189972_227280880_864x486.jpg 864w, https:\/\/s1.eestatic.com\/2022\/09\/18\/el-cultural\/704189972_227280879_1024x576.jpg 1024w, https:\/\/s1.eestatic.com\/2022\/09\/18\/el-cultural\/704189972_227280878_1706x960.jpg 1706w\" width=\"320\"\/><\/p>\n<div class=\"article-media__caption\">\n<p>\n                    <span class=\"article-media__caption-description\"><\/p>\n<p>                                    Andrius Arutiunian: &#8216;Arizona Club&#8217;<br \/>\n                            <\/span><\/p>\n<p>                    <span class=\"article-media__caption-author\">EV<\/span><\/p>\n<\/div><\/div>\n<p id=\"paragraph_6\"><strong>Kit de sobreviv\u00eancia<\/strong>que vai agora na sua 13\u00aa edi\u00e7\u00e3o e nasceu como um programa art\u00edstico para revitalizar os espa\u00e7os da cidade em tempos de crise econ\u00f3mica aguda, \u00e9 organizado pelo Centro de Arte Contempor\u00e2nea da Let\u00f3nia (sucessor aqui da funda\u00e7\u00e3o transnacional de George Soros) e \u00e9 quase como tudo em riga <strong>fruto da iniciativa privada<\/strong>.<\/p>\n<p id=\"paragraph_7\">Com um punhado de pequenas galerias, alguns centros de arte not\u00e1veis \u200b\u200b(Kim?, e um sal\u00e3o municipal, R\u012bgas m\u0101kslas telpa) e um museu criado por colecionadores, o Zuzeum, <strong>a cena art\u00edstica \u00e9 mais do que prec\u00e1ria<\/strong>.<\/p>\n<p id=\"paragraph_8\">N\u00e3o existe um museu p\u00fablico de arte contempor\u00e2nea \u2013 embora j\u00e1 esteja previsto \u2013 e as institui\u00e7\u00f5es existentes s\u00e3o dedicadas \u00e0 arte antiga \u2013 o dign\u00edssimo Museu Nacional, com v\u00e1rias filiais \u2013 ou \u00e0 mem\u00f3ria das duras vicissitudes do pa\u00eds no s\u00e9culo XX.  Em Riga existem museus sobre a guerra, a ocupa\u00e7\u00e3o sovi\u00e9tica, o KGB, as barricadas, os crimes dos nazis e colaboradores contra os judeus&#8230;<\/p>\n<p id=\"paragraph_9\">A a\u00e7\u00e3o cultural na Let\u00f3nia anda de m\u00e3os dadas com a afirma\u00e7\u00e3o nacional e a defesa da democracia e das liberdades.  E \u00e9 exatamente disso que ele cuida <em>O passarinho deve ser pego<\/em> (\u201cO passarinho deve ser capturado\u201d, verso de um poema de Oj\u0101rs V\u0101cietis), a exposi\u00e7\u00e3o que o curador grego <strong>iLiana Fokianaki<\/strong> Foi concebido antes da agress\u00e3o russa e ganhou um alcance inesperado depois dela.<\/p>\n<div class=\"article-media \" itemscope=\"\" itemtype=\"http:\/\/schema.org\/ImageObject\">\n<p><img loading=\"lazy\" decoding=\"async\" alt=\"Dora Garc\u00eda: 'O caf\u00e9 das vozes'\" data-imgm=\"true\" height=\"180\" loading=\"lazy\" sizes=\"auto, (max-width: 479px) 100vw, (max-width: 1023px) 80vw, 40vw\" src=\"https:\/\/s1.eestatic.com\/2022\/09\/18\/el-cultural\/704189975_227281023_1024x576.jpg\" srcset=\"https:\/\/s1.eestatic.com\/2022\/09\/18\/el-cultural\/704189975_227281026_320x180.jpg 320w, https:\/\/s1.eestatic.com\/2022\/09\/18\/el-cultural\/704189975_227281025_640x360.jpg 640w, https:\/\/s1.eestatic.com\/2022\/09\/18\/el-cultural\/704189975_227281024_864x486.jpg 864w, https:\/\/s1.eestatic.com\/2022\/09\/18\/el-cultural\/704189975_227281023_1024x576.jpg 1024w, https:\/\/s1.eestatic.com\/2022\/09\/18\/el-cultural\/704189975_227281022_1706x960.jpg 1706w\" width=\"320\"\/><\/p>\n<div class=\"article-media__caption\">\n<p>\n                    <span class=\"article-media__caption-description\"><\/p>\n<p>                                    Dora Garc\u00eda: &#8216;O caf\u00e9 das vozes&#8217;<br \/>\n                            <\/span><\/p>\n<\/div><\/div>\n<p id=\"paragraph_10\">O conceito \u00e9 muito bem feito e muito inspirador: <strong>a partir da \u201crevolu\u00e7\u00e3o cantada\u201d<\/strong> \u2013 a partir dos festivais de dan\u00e7as e can\u00e7\u00f5es folcl\u00f3ricas \u2013 que levaram \u00e0 independ\u00eancia em 1991, o objetivo \u00e9 mostrar como a resist\u00eancia \u00e0 opress\u00e3o e ao autoritarismo muitas vezes adota um pacote sonoro, seja na palavra ou na m\u00fasica, e como ressoa seu sil\u00eancio atrav\u00e9s da censura.<\/p>\n<p id=\"paragraph_11\">Mesmo com apenas tr\u00eas artistas let\u00f5es vivos (em compara\u00e7\u00e3o com quatro gregos, com obras nada dignas de nota) e um \u00fanico ucraniano, <strong>o conjunto alude abertamente \u00e0s atuais circunst\u00e2ncias na Ucr\u00e2nia e aos riscos no B\u00e1ltico<\/strong>mas tamb\u00e9m recolhe experi\u00eancias noutras \u00e1reas com liberdades cerceadas e deixa-nos ouvir a amargura do ex\u00edlio e a luta pela sobreviv\u00eancia das culturas.<\/p>\n<blockquote class=\"content__blockquote\">\n<p class=\"blockquote__quote\">O festival mostra como a resist\u00eancia \u00e0 opress\u00e3o e ao autoritarismo muitas vezes adota um pacote sonoro<\/p>\n<\/blockquote>\n<p id=\"paragraph_12\">No antigo pr\u00e9dio do Banco de la Bolsa (\u00e0 venda), as obras quase n\u00e3o conversam no t\u00e9rreo aberto, onde o <strong>uma nova edi\u00e7\u00e3o de <em>o caf\u00e9 das vozes<\/em> por Dora Garcia (Espanha)<\/strong> \u2013que ser\u00e1 um ponto de encontro, pretende-se, para a comunidade de refugiados ucranianos\u2013, mas no primeiro andar eles desfrutam de espa\u00e7os individualizados em escrit\u00f3rios e quartos, de cujo mobili\u00e1rio restam apenas os muitos cofres.<\/p>\n<p id=\"paragraph_13\">Poucas obras foram produzidas para a mostra, mas todas, exceto alguns artistas &#8220;pioneiros&#8221;, s\u00e3o recentes e em sua maioria relevantes.  Vou destacar alguns.  Puramente sonoros s\u00e3o apenas os de <strong>Lauren Prouvost (Fran\u00e7a)<\/strong>, <strong>Susan Philipsz (Esc\u00f3cia)<\/strong>que se encaixa mal pelo seu conte\u00fado mas \u00e9 t\u00e3o bonito&#8230;, e <strong>Kapwani Kiwanga (Canad\u00e1)<\/strong>.<\/p>\n<div class=\"article-media \" itemscope=\"\" itemtype=\"http:\/\/schema.org\/ImageObject\">\n<p><img loading=\"lazy\" decoding=\"async\" alt=\"Almagul Menlibayeva: 'Realismo IA.  Qantar'\" data-imgm=\"true\" height=\"180\" loading=\"lazy\" sizes=\"auto, (max-width: 479px) 100vw, (max-width: 1023px) 80vw, 40vw\" src=\"https:\/\/s1.eestatic.com\/2022\/09\/18\/el-cultural\/704189974_227280925_1024x576.jpg\" srcset=\"https:\/\/s1.eestatic.com\/2022\/09\/18\/el-cultural\/704189974_227280956_320x180.jpg 320w, https:\/\/s1.eestatic.com\/2022\/09\/18\/el-cultural\/704189974_227280955_640x360.jpg 640w, https:\/\/s1.eestatic.com\/2022\/09\/18\/el-cultural\/704189974_227280954_864x486.jpg 864w, https:\/\/s1.eestatic.com\/2022\/09\/18\/el-cultural\/704189974_227280953_1024x576.jpg 1024w, https:\/\/s1.eestatic.com\/2022\/09\/18\/el-cultural\/704189974_227280952_1706x960.jpg 1706w\" width=\"320\"\/><\/p>\n<div class=\"article-media__caption\">\n<p>\n                    <span class=\"article-media__caption-description\"><\/p>\n<p>                                    Almagul Menlibayeva: &#8216;Realismo IA.  Qantar&#8217;<br \/>\n                            <\/span><\/p>\n<p>                    <span class=\"article-media__caption-author\">EV<\/span><\/p>\n<\/div><\/div>\n<p id=\"paragraph_14\">A express\u00e3o em l\u00ednguas proibidas \u00e9 tratada por <strong>Anton Vidokle (R\u00fassia)<\/strong> num filme que transporta para os curdos e para a Turquia a epopeia de Gilgamesh, caprichosamente feminizada, e por <strong>Rojava Film Commune (S\u00edria)<\/strong>que documenta em tom l\u00edrico como a can\u00e7\u00e3o tradicional, tamb\u00e9m curda, \u00e9 protegida naquela regi\u00e3o \u2013 uma quest\u00e3o de vida ou morte cultural.<\/p>\n<p id=\"paragraph_15\">O papel da m\u00fasica e do canto nos processos coloniais \u00e9 abordado por <strong>Sammy Baloji (RD Congo)<\/strong>que relaciona a acultura\u00e7\u00e3o pela religi\u00e3o \u2013com uma de suas bases nos coros\u2013 e o extrativismo do cobre, e <strong>Andrius Arutiunian (Litu\u00e2nia)<\/strong> d\u00e1 forma a uma instala\u00e7\u00e3o escult\u00f3rica sonora a um caso de transfer\u00eancia cultural atrav\u00e9s da m\u00fasica: a \u201cimporta\u00e7\u00e3o\u201d de quarenta \u00f3rf\u00e3os do genoc\u00eddio arm\u00e9nio de Jerusal\u00e9m para Adis Abeba, onde fundaram uma tradi\u00e7\u00e3o de instrumentos de sopro que daria origem ao jazz et\u00edope.<\/p>\n<p id=\"paragraph_16\"><strong>Kristaps Epners (Let\u00f4nia)<\/strong> recolhe o canto eclesi\u00e1stico de uma comunidade religiosa, os Velhos Crentes, exilados da R\u00fassia no s\u00e9culo XVII, introduzindo na exposi\u00e7\u00e3o um necess\u00e1rio sotaque local, e <strong>Raed Yassin (L\u00edbano)<\/strong> afeta o potencial comunicativo da m\u00fasica mesmo quando \u00e9 apenas um zumbido.<\/p>\n<p id=\"paragraph_17\">Uma das obras mais impressionantes da mostra \u00e9 a de <strong>Indr\u0117 \u0160erpytyt\u0117 (Litu\u00e2nia)<\/strong>: a <em>colagem<\/em> de v\u00eddeos tirados das redes sociais de soldados \u2013 jovens com n\u00edveis elevados de testosterona \u2013 dan\u00e7ando provocativamente na frente da c\u00e2mera como se fossem dan\u00e7arinos go-go quando na verdade s\u00e3o bucha de canh\u00e3o.<\/p>\n<div class=\"article-media \" itemscope=\"\" itemtype=\"http:\/\/schema.org\/ImageObject\">\n<p><img loading=\"lazy\" decoding=\"async\" alt=\"No ch\u00e3o, obras de Hardijs Ledin\u0161 e Juris Boiko: 'Dr. Enesers's Binocular Dance Lessons' e 'Farewell to the Empire'.  Nas vitrines, Chrysanthi Koumianaki: 'Abaixo o abstrato.  Viva o ef\u00eamero!'\" data-imgm=\"true\" height=\"180\" loading=\"lazy\" sizes=\"auto, (max-width: 479px) 100vw, (max-width: 1023px) 80vw, 40vw\" src=\"https:\/\/s1.eestatic.com\/2022\/09\/18\/el-cultural\/704189977_227281082_1024x576.jpg\" srcset=\"https:\/\/s1.eestatic.com\/2022\/09\/18\/el-cultural\/704189977_227281115_320x180.jpg 320w, https:\/\/s1.eestatic.com\/2022\/09\/18\/el-cultural\/704189977_227281114_640x360.jpg 640w, https:\/\/s1.eestatic.com\/2022\/09\/18\/el-cultural\/704189977_227281113_864x486.jpg 864w, https:\/\/s1.eestatic.com\/2022\/09\/18\/el-cultural\/704189977_227281112_1024x576.jpg 1024w, https:\/\/s1.eestatic.com\/2022\/09\/18\/el-cultural\/704189977_227281111_1706x960.jpg 1706w\" width=\"320\"\/><\/p>\n<div class=\"article-media__caption\">\n<p>\n                    <span class=\"article-media__caption-description\"><\/p>\n<p>                                    No ch\u00e3o, obras de Hardijs Ledin\u0161 e Juris Boiko: &#8216;Dr. Enesers&#8217;s Binocular Dance Lessons&#8217; e &#8216;Farewell to the Empire&#8217;.  Nas vitrines, Chrysanthi Koumianaki: &#8216;Abaixo o abstrato.  Viva o ef\u00eamero!&#8217;<br \/>\n                            <\/span><\/p>\n<p>                    <span class=\"article-media__caption-author\">EV<\/span><\/p>\n<\/div><\/div>\n<p id=\"paragraph_18\">A superexposi\u00e7\u00e3o midi\u00e1tica tem seu contraponto na censura e no silenciamento de que se valem os regimes autorit\u00e1rios, desde a ca\u00e7a \u00e0s bruxas que evoca <strong>Sanja Ivekovic (Cro\u00e1cia)<\/strong> \u00e0s manifesta\u00e7\u00f5es extremamente comoventes das limita\u00e7\u00f5es impostas \u00e0 comunica\u00e7\u00e3o e ao contacto f\u00edsico entre homens e mulheres que detecta <strong>Maryam Tafakory (Ir\u00e3)<\/strong> no cinema de seu pa\u00eds.<\/p>\n<p id=\"paragraph_19\">Sil\u00eancio de informa\u00e7\u00e3o \u00e9 denunciado por <strong>Almagul Menlibayeva (Cazaquist\u00e3o)<\/strong> e por <strong>Arquitetura Forense (Reino Unido)<\/strong>e <strong>Candice Breitz (\u00c1frica do Sul)<\/strong> somatiza os discursos racistas direta e indiretamente que inundam as televis\u00f5es.<\/p>\n<p id=\"paragraph_20\">O que mais h\u00e1 a dizer? <strong>Kriss Salmanis (Let\u00f4nia)<\/strong>, como tantos, n\u00e3o tem palavras.  Sua resposta \u00e9 emocional e silenciosa.  Uma onda de sussurros e um gotejar quase inaud\u00edvel, muito lento, que traduz <strong>a espera ansiosa pelo fim da guerra<\/strong>.<\/p>\n<h3 class=\"follow-topics-title\"><span class=\"follow-topics-title__icon\"\/>Siga os t\u00f3picos que lhe interessam<\/h3>\n<\/p><\/div>\n","protected":false},"excerpt":{"rendered":"<p>[ad_1] Chamam-lhe festival, mas \u00e9 uma \u00fanica exposi\u00e7\u00e3o acompanhada de um programa de atividades. O or\u00e7amento \u00e9 apertado e os &hellip; <\/p>\n","protected":false},"author":1,"featured_media":679,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"fifu_image_url":"https:\/\/s1.eestatic.com\/2022\/09\/18\/el-cultural\/arte\/arte_internacional\/704189979_227411585_600x315.jpg","fifu_image_alt":"","footnotes":""},"categories":[34],"tags":[],"class_list":["post-678","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-arte","latest_post"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Survival Kit, o festival de arte da Let\u00f4nia que enfrenta a guerra - Tirinha.com<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/tirinha.com\/vi\/678\/bo-dung-cu-sinh-ton-le-hoi-nghe-thuat-latvia-doi-mat-voi-chien-tranh\/\" \/>\n<meta property=\"og:locale\" content=\"vi_VN\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Survival Kit, o festival de arte da Let\u00f4nia que enfrenta a guerra - Tirinha.com\" \/>\n<meta property=\"og:description\" content=\"[ad_1] Chamam-lhe festival, mas \u00e9 uma \u00fanica exposi\u00e7\u00e3o acompanhada de um programa de atividades. O or\u00e7amento \u00e9 apertado e os &hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/tirinha.com\/vi\/678\/bo-dung-cu-sinh-ton-le-hoi-nghe-thuat-latvia-doi-mat-voi-chien-tranh\/\" \/>\n<meta property=\"og:site_name\" content=\"Tirinha.com\" \/>\n<meta property=\"article:published_time\" content=\"2023-03-02T12:12:24+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/s1.eestatic.com\/2022\/09\/18\/el-cultural\/arte\/arte_internacional\/704189979_227411585_600x315.jpg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/s1.eestatic.com\/2022\/09\/18\/el-cultural\/arte\/arte_internacional\/704189979_227411585_600x315.jpg\" \/>\n<meta name=\"twitter:label1\" content=\"\u0110\u01b0\u1ee3c vi\u1ebft b\u1edfi\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"\u01af\u1edbc t\u00ednh th\u1eddi gian \u0111\u1ecdc\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 ph\u00fat\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/tirinha.com\\\/678\\\/survival-kit-o-festival-de-arte-da-letonia-que-enfrenta-a-guerra\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/tirinha.com\\\/678\\\/survival-kit-o-festival-de-arte-da-letonia-que-enfrenta-a-guerra\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/tirinha.com\\\/#\\\/schema\\\/person\\\/e22bdfbe17e0461f7e927e6a1208d4d9\"},\"headline\":\"Survival Kit, o festival de arte da Let\u00f4nia que enfrenta a guerra\",\"datePublished\":\"2023-03-02T12:12:24+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/tirinha.com\\\/678\\\/survival-kit-o-festival-de-arte-da-letonia-que-enfrenta-a-guerra\\\/\"},\"wordCount\":1278,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/tirinha.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/tirinha.com\\\/678\\\/survival-kit-o-festival-de-arte-da-letonia-que-enfrenta-a-guerra\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/s1.eestatic.com\\\/2022\\\/09\\\/18\\\/el-cultural\\\/arte\\\/arte_internacional\\\/704189979_227411585_600x315.jpg\",\"articleSection\":[\"Arte\"],\"inLanguage\":\"vi\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/tirinha.com\\\/678\\\/survival-kit-o-festival-de-arte-da-letonia-que-enfrenta-a-guerra\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/tirinha.com\\\/678\\\/survival-kit-o-festival-de-arte-da-letonia-que-enfrenta-a-guerra\\\/\",\"url\":\"https:\\\/\\\/tirinha.com\\\/678\\\/survival-kit-o-festival-de-arte-da-letonia-que-enfrenta-a-guerra\\\/\",\"name\":\"Survival Kit, o festival de arte da Let\u00f4nia que enfrenta a guerra - Tirinha.com\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/tirinha.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/tirinha.com\\\/678\\\/survival-kit-o-festival-de-arte-da-letonia-que-enfrenta-a-guerra\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/tirinha.com\\\/678\\\/survival-kit-o-festival-de-arte-da-letonia-que-enfrenta-a-guerra\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/s1.eestatic.com\\\/2022\\\/09\\\/18\\\/el-cultural\\\/arte\\\/arte_internacional\\\/704189979_227411585_600x315.jpg\",\"datePublished\":\"2023-03-02T12:12:24+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/tirinha.com\\\/678\\\/survival-kit-o-festival-de-arte-da-letonia-que-enfrenta-a-guerra\\\/#breadcrumb\"},\"inLanguage\":\"vi\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/tirinha.com\\\/678\\\/survival-kit-o-festival-de-arte-da-letonia-que-enfrenta-a-guerra\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"vi\",\"@id\":\"https:\\\/\\\/tirinha.com\\\/678\\\/survival-kit-o-festival-de-arte-da-letonia-que-enfrenta-a-guerra\\\/#primaryimage\",\"url\":\"https:\\\/\\\/s1.eestatic.com\\\/2022\\\/09\\\/18\\\/el-cultural\\\/arte\\\/arte_internacional\\\/704189979_227411585_600x315.jpg\",\"contentUrl\":\"https:\\\/\\\/s1.eestatic.com\\\/2022\\\/09\\\/18\\\/el-cultural\\\/arte\\\/arte_internacional\\\/704189979_227411585_600x315.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/tirinha.com\\\/678\\\/survival-kit-o-festival-de-arte-da-letonia-que-enfrenta-a-guerra\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/tirinha.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Survival Kit, o festival de arte da Let\u00f4nia que enfrenta a guerra\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/tirinha.com\\\/#website\",\"url\":\"https:\\\/\\\/tirinha.com\\\/\",\"name\":\"Tirinha.com\",\"description\":\"Arte e livros resenhas\",\"publisher\":{\"@id\":\"https:\\\/\\\/tirinha.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/tirinha.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"vi\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/tirinha.com\\\/#organization\",\"name\":\"Tirinha.com\",\"url\":\"https:\\\/\\\/tirinha.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"vi\",\"@id\":\"https:\\\/\\\/tirinha.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/tirinha.com\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/cropped-Logo-Tirinha.webp\",\"contentUrl\":\"https:\\\/\\\/tirinha.com\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/cropped-Logo-Tirinha.webp\",\"width\":512,\"height\":512,\"caption\":\"Tirinha.com\"},\"image\":{\"@id\":\"https:\\\/\\\/tirinha.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/tirinha.com\\\/#\\\/schema\\\/person\\\/e22bdfbe17e0461f7e927e6a1208d4d9\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"vi\",\"@id\":\"https:\\\/\\\/tirinha.com\\\/wp-content\\\/litespeed\\\/avatar\\\/d0068f7931cc87d7274eb0c3db1deb4b.jpg?ver=1778643959\",\"url\":\"https:\\\/\\\/tirinha.com\\\/wp-content\\\/litespeed\\\/avatar\\\/d0068f7931cc87d7274eb0c3db1deb4b.jpg?ver=1778643959\",\"contentUrl\":\"https:\\\/\\\/tirinha.com\\\/wp-content\\\/litespeed\\\/avatar\\\/d0068f7931cc87d7274eb0c3db1deb4b.jpg?ver=1778643959\",\"caption\":\"admin\"},\"sameAs\":[\"https:\\\/\\\/tirinha.com\"],\"url\":\"https:\\\/\\\/tirinha.com\\\/vi\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Survival Kit, l\u1ec5 h\u1ed9i ngh\u1ec7 thu\u1eadt Latvia \u0111\u1ed1i m\u1eb7t v\u1edbi chi\u1ebfn tranh - Tirinha.com","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/tirinha.com\/vi\/678\/bo-dung-cu-sinh-ton-le-hoi-nghe-thuat-latvia-doi-mat-voi-chien-tranh\/","og_locale":"vi_VN","og_type":"article","og_title":"Survival Kit, o festival de arte da Let\u00f4nia que enfrenta a guerra - Tirinha.com","og_description":"[ad_1] Chamam-lhe festival, mas \u00e9 uma \u00fanica exposi\u00e7\u00e3o acompanhada de um programa de atividades. O or\u00e7amento \u00e9 apertado e os &hellip;","og_url":"https:\/\/tirinha.com\/vi\/678\/bo-dung-cu-sinh-ton-le-hoi-nghe-thuat-latvia-doi-mat-voi-chien-tranh\/","og_site_name":"Tirinha.com","article_published_time":"2023-03-02T12:12:24+00:00","og_image":[{"url":"https:\/\/s1.eestatic.com\/2022\/09\/18\/el-cultural\/arte\/arte_internacional\/704189979_227411585_600x315.jpg","type":"","width":"","height":""}],"author":"admin","twitter_card":"summary_large_image","twitter_image":"https:\/\/s1.eestatic.com\/2022\/09\/18\/el-cultural\/arte\/arte_internacional\/704189979_227411585_600x315.jpg","twitter_misc":{"\u0110\u01b0\u1ee3c vi\u1ebft b\u1edfi":"admin","\u01af\u1edbc t\u00ednh th\u1eddi gian \u0111\u1ecdc":"6 ph\u00fat"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/tirinha.com\/678\/survival-kit-o-festival-de-arte-da-letonia-que-enfrenta-a-guerra\/#article","isPartOf":{"@id":"https:\/\/tirinha.com\/678\/survival-kit-o-festival-de-arte-da-letonia-que-enfrenta-a-guerra\/"},"author":{"name":"admin","@id":"https:\/\/tirinha.com\/#\/schema\/person\/e22bdfbe17e0461f7e927e6a1208d4d9"},"headline":"Survival Kit, o festival de arte da Let\u00f4nia que enfrenta a guerra","datePublished":"2023-03-02T12:12:24+00:00","mainEntityOfPage":{"@id":"https:\/\/tirinha.com\/678\/survival-kit-o-festival-de-arte-da-letonia-que-enfrenta-a-guerra\/"},"wordCount":1278,"commentCount":0,"publisher":{"@id":"https:\/\/tirinha.com\/#organization"},"image":{"@id":"https:\/\/tirinha.com\/678\/survival-kit-o-festival-de-arte-da-letonia-que-enfrenta-a-guerra\/#primaryimage"},"thumbnailUrl":"https:\/\/s1.eestatic.com\/2022\/09\/18\/el-cultural\/arte\/arte_internacional\/704189979_227411585_600x315.jpg","articleSection":["Arte"],"inLanguage":"vi","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/tirinha.com\/678\/survival-kit-o-festival-de-arte-da-letonia-que-enfrenta-a-guerra\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/tirinha.com\/678\/survival-kit-o-festival-de-arte-da-letonia-que-enfrenta-a-guerra\/","url":"https:\/\/tirinha.com\/678\/survival-kit-o-festival-de-arte-da-letonia-que-enfrenta-a-guerra\/","name":"Survival Kit, l\u1ec5 h\u1ed9i ngh\u1ec7 thu\u1eadt Latvia \u0111\u1ed1i m\u1eb7t v\u1edbi chi\u1ebfn tranh - Tirinha.com","isPartOf":{"@id":"https:\/\/tirinha.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/tirinha.com\/678\/survival-kit-o-festival-de-arte-da-letonia-que-enfrenta-a-guerra\/#primaryimage"},"image":{"@id":"https:\/\/tirinha.com\/678\/survival-kit-o-festival-de-arte-da-letonia-que-enfrenta-a-guerra\/#primaryimage"},"thumbnailUrl":"https:\/\/s1.eestatic.com\/2022\/09\/18\/el-cultural\/arte\/arte_internacional\/704189979_227411585_600x315.jpg","datePublished":"2023-03-02T12:12:24+00:00","breadcrumb":{"@id":"https:\/\/tirinha.com\/678\/survival-kit-o-festival-de-arte-da-letonia-que-enfrenta-a-guerra\/#breadcrumb"},"inLanguage":"vi","potentialAction":[{"@type":"ReadAction","target":["https:\/\/tirinha.com\/678\/survival-kit-o-festival-de-arte-da-letonia-que-enfrenta-a-guerra\/"]}]},{"@type":"ImageObject","inLanguage":"vi","@id":"https:\/\/tirinha.com\/678\/survival-kit-o-festival-de-arte-da-letonia-que-enfrenta-a-guerra\/#primaryimage","url":"https:\/\/s1.eestatic.com\/2022\/09\/18\/el-cultural\/arte\/arte_internacional\/704189979_227411585_600x315.jpg","contentUrl":"https:\/\/s1.eestatic.com\/2022\/09\/18\/el-cultural\/arte\/arte_internacional\/704189979_227411585_600x315.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/tirinha.com\/678\/survival-kit-o-festival-de-arte-da-letonia-que-enfrenta-a-guerra\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/tirinha.com\/"},{"@type":"ListItem","position":2,"name":"Survival Kit, o festival de arte da Let\u00f4nia que enfrenta a guerra"}]},{"@type":"WebSite","@id":"https:\/\/tirinha.com\/#website","url":"https:\/\/tirinha.com\/","name":"Truy\u1ec7n tranh.com","description":"\u0110\u00e1nh gi\u00e1 ngh\u1ec7 thu\u1eadt v\u00e0 s\u00e1ch","publisher":{"@id":"https:\/\/tirinha.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/tirinha.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"vi"},{"@type":"Organization","@id":"https:\/\/tirinha.com\/#organization","name":"Truy\u1ec7n tranh.com","url":"https:\/\/tirinha.com\/","logo":{"@type":"ImageObject","inLanguage":"vi","@id":"https:\/\/tirinha.com\/#\/schema\/logo\/image\/","url":"https:\/\/tirinha.com\/wp-content\/uploads\/2023\/08\/cropped-Logo-Tirinha.webp","contentUrl":"https:\/\/tirinha.com\/wp-content\/uploads\/2023\/08\/cropped-Logo-Tirinha.webp","width":512,"height":512,"caption":"Tirinha.com"},"image":{"@id":"https:\/\/tirinha.com\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/tirinha.com\/#\/schema\/person\/e22bdfbe17e0461f7e927e6a1208d4d9","name":"qu\u1ea3n tr\u1ecb vi\u00ean","image":{"@type":"ImageObject","inLanguage":"vi","@id":"https:\/\/tirinha.com\/wp-content\/litespeed\/avatar\/d0068f7931cc87d7274eb0c3db1deb4b.jpg?ver=1778643959","url":"https:\/\/tirinha.com\/wp-content\/litespeed\/avatar\/d0068f7931cc87d7274eb0c3db1deb4b.jpg?ver=1778643959","contentUrl":"https:\/\/tirinha.com\/wp-content\/litespeed\/avatar\/d0068f7931cc87d7274eb0c3db1deb4b.jpg?ver=1778643959","caption":"admin"},"sameAs":["https:\/\/tirinha.com"],"url":"https:\/\/tirinha.com\/vi\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/tirinha.com\/vi\/wp-json\/wp\/v2\/posts\/678","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tirinha.com\/vi\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tirinha.com\/vi\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tirinha.com\/vi\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/tirinha.com\/vi\/wp-json\/wp\/v2\/comments?post=678"}],"version-history":[{"count":0,"href":"https:\/\/tirinha.com\/vi\/wp-json\/wp\/v2\/posts\/678\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tirinha.com\/vi\/wp-json\/wp\/v2\/media\/679"}],"wp:attachment":[{"href":"https:\/\/tirinha.com\/vi\/wp-json\/wp\/v2\/media?parent=678"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tirinha.com\/vi\/wp-json\/wp\/v2\/categories?post=678"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tirinha.com\/vi\/wp-json\/wp\/v2\/tags?post=678"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}