{"id":1118,"date":"2023-04-11T11:34:46","date_gmt":"2023-04-11T11:34:46","guid":{"rendered":"https:\/\/tirinha.com\/terceira-jornada-sobre-o-artesanato-cinematografico-em-las-palmas-de-gran-canaria\/"},"modified":"2023-04-11T11:34:46","modified_gmt":"2023-04-11T11:34:46","slug":"terceira-jornada-sobre-o-artesanato-cinematografico-em-las-palmas-de-gran-canaria","status":"publish","type":"post","link":"https:\/\/tirinha.com\/pl\/1118\/terceira-jornada-sobre-o-artesanato-cinematografico-em-las-palmas-de-gran-canaria\/","title":{"rendered":"Trzeci dzie\u0144 rzemios\u0142a filmowego w Las Palmas de Gran Canaria"},"content":{"rendered":"<p><\/p>\n<div>\n<h2>Spotkanie z wielkimi nazwiskami kina hiszpa\u0144skiego powraca po raz kolejny do wizyt\u00f3wki Festiwalu Filmowego w stolicy Gran Canarii<\/h2>\n<p><strong>To ju\u017c trzecia ods\u0142ona <em>Konferencja na temat rzemios\u0142a filmowego<\/em> kt\u00f3re odb\u0119dzie si\u0119 14 i 15 kwietnia w Las Palmas de Gran Canaria. Przy czterech otwartych dla publiczno\u015bci okr\u0105g\u0142ych sto\u0142ach spotkaj\u0105 si\u0119 najwa\u017cniejsze nazwiska hiszpa\u0144skiej kinematografii. S\u0105 produkowane przez firm\u0119 18Chulos i sponsorowane przez Rad\u0119 Miasta. B\u0119d\u0105 cz\u0119\u015bci\u0105 r\u00f3wnoleg\u0142ego programu Festiwalu Filmowego w Las Palmas.<\/strong><\/p>\n<p>re\u017cyserzy lubi\u0105 <strong>Alejandro Amen\u00e1bar, \u00c1lex de la Iglesia, Carla Sim\u00f3n i Fernando Le\u00f3n de Aranoa<\/strong> b\u0119d\u0105 bohaterami wraz z innymi artystami, takimi jak <strong>\u00c1ngela Molina, Anna Castillo, Karra Elejalde, Macarena Garc\u00eda i Paco Le\u00f3n<\/strong>. Moderatorami czterech okr\u0105g\u0142ych sto\u0142\u00f3w b\u0119d\u0105 Greater Wyoming i Elena S\u00e1nchez, dyrektorka programu TVE \u201eHistoria de nuestro cine\u201d.<\/p>\n<p>Wydarzenie odb\u0119dzie si\u0119 o godz <strong>budynek m\u0142ynarza<\/strong> jest o godz <strong>Kino Dok<\/strong>kt\u00f3ra otworzy drzwi jednej ze swoich sal, w kt\u00f3rej odb\u0119dzie si\u0119 m.in. spotkanie z \u00c1ngel\u0105 Molin\u0105.<\/p>\n<h3>Program konferencji<\/h3>\n<p>Rozpoczn\u0105 si\u0119 w pi\u0105tek 14-go o godzinie 16:00 w Miller. <strong>Dyrektorzy:<\/strong> <strong>Oscar<sup>\u00a9<\/sup> i ponad 20 Goi przy tym samym stole. <\/strong>Czterech re\u017cyser\u00f3w, kt\u00f3rzy otworz\u0105 pierwszy dzie\u0144 festiwalu, zgromadzi nie tylko Oscara i ponad 20 nagr\u00f3d Goy, ale tak\u017ce Z\u0142oty Glob, Z\u0142ot\u0105 i Srebrn\u0105 Muszl\u0119 Festiwalu w San Sebastian, Nied\u017awiedzia Berli\u0144skiego, Lwa, Osell\u0119 i Wenecj\u0119 Nagroda Specjalna Jury, kilka Europejskich Nagr\u00f3d Filmowych oraz liczne nagrody w licznych konkursach filmowych na ca\u0142ym \u015bwiecie. I w ten spos\u00f3b imiona Alejandro Amen\u00e1bara, \u00c1lexa de la Iglesia, Carla Sim\u00f3n i Fernando Le\u00f3n de Aranoa maj\u0105 nawi\u0105zywa\u0107 do niekt\u00f3rych z najbardziej pami\u0119tnych moment\u00f3w ostatnich 30 lat hiszpa\u0144skiego kina.<\/p>\n<p style=\"font-weight: 400\">Od imponuj\u0105cego debiutu \u00c1lexa de la Iglesia z <em><strong>dzia\u0142anie mutant\u00f3w<\/strong><\/em>  (1993) i <strong><em>Dzie\u0144 Bestii<\/em><\/strong>  (1995), szok m\u0142odego Amen\u00e1bara i jego <em><strong>Praca dyplomowa<\/strong> <\/em>lub osobliwy <em><strong>Rodzina <\/strong><\/em>Fernando Le\u00f3na de Aranoa (oba 1996), ku delikatno\u015bci m\u0142odego re\u017cysera, kt\u00f3rego<em><strong>  lato 1993<\/strong><\/em>Nakr\u0119cony w j\u0119zyku katalo\u0144skim, w 2017 roku zosta\u0142 wybrany do reprezentowania Hiszpanii na ceremonii rozdania Oscar\u00f3w w Hollywood.<\/p>\n<p style=\"font-weight: 400\">z Oscar\u00f3w<sup>\u00a9<\/sup>  z Amen\u00e1bar do <strong><em>Na morze<\/em><\/strong>  do Z\u0142otej Muszli Aranoa <em><strong>Poniedzia\u0142ki w s\u0142o\u0144cu<\/strong><\/em>  lub materia\u0142 wybuchowy <em><strong>utracone durango<\/strong><\/em>, a wszystkie z udzia\u0142em ogromnego Javiera Bardema. Z <em><strong>smutna ballada na tr\u0105bk\u0119<\/strong><\/em>  Do <strong><em>Dop\u00f3ki trwa wojna<\/em><\/strong>; operator\u00f3w fabryk wag i ich <em><strong>dobry standard<\/strong><\/em>  do rolnik\u00f3w z <em><strong>alcarras<\/strong><\/em>. Wsp\u00f3lne tematy i aktorzy dla zupe\u0142nie innego kina z perspektywami wielo\u015bciennymi. Nasi czterej wielcy re\u017cyserzy b\u0119d\u0105 rozmawia\u0107 o tym wszystkim podczas pierwszego okr\u0105g\u0142ego sto\u0142u moderowanego przez Wyoming.<\/p>\n<figure id=\"attachment_85463\" aria-describedby=\"caption-attachment-85463\" style=\"width: 5760px\" class=\"wp-caption alignnone\"><img fetchpriority=\"high\" data-attachment-id=\"85463\" data-permalink=\"https:\/\/elgeneracionalpost.com\/cultura\/2023\/0411\/85460\/terceras-jornadas-del-oficio-cinematografico-en-las-palmas-de-gran-canaria.html\/attachment\/alejandro-amenabar-by-bernardo-doral\" data-orig-file=\"https:\/\/i0.wp.com\/elgeneracionalpost.com\/wp-content\/uploads\/2023\/04\/Alejandro-Amenabar-by-Bernardo-Doral.jpg?fit=5760%2C3840&amp;ssl=1\" data-orig-size=\"5760,3840\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;4.5&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;Canon EOS 5D Mark III&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1440590522&quot;,&quot;copyright&quot;:&quot;\\u00a9 bernardo doral&quot;,&quot;focal_length&quot;:&quot;70&quot;,&quot;iso&quot;:&quot;320&quot;,&quot;shutter_speed&quot;:&quot;0.008&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"Alejandro Amen\u00e1bar by Bernardo Doral\" data-image-description=\"\" data-image-caption=\"&lt;p&gt;Alejandro Amen\u00e1bar. | Fuente: 18Chulos&lt;\/p&gt;&#10;\" data-medium-file=\"https:\/\/i0.wp.com\/elgeneracionalpost.com\/wp-content\/uploads\/2023\/04\/Alejandro-Amenabar-by-Bernardo-Doral.jpg?fit=300%2C200&amp;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/elgeneracionalpost.com\/wp-content\/uploads\/2023\/04\/Alejandro-Amenabar-by-Bernardo-Doral.jpg?fit=696%2C464&amp;ssl=1\" decoding=\"async\" class=\"wp-image-85463 size-full jetpack-lazy-image\" src=\"https:\/\/i0.wp.com\/elgeneracionalpost.com\/wp-content\/uploads\/2023\/04\/Alejandro-Amenabar-by-Bernardo-Doral.jpg?resize=696%2C464&amp;ssl=1\" alt=\"\" width=\"696\" height=\"464\" data-recalc-dims=\"1\" data-lazy-srcset=\"https:\/\/i0.wp.com\/elgeneracionalpost.com\/wp-content\/uploads\/2023\/04\/Alejandro-Amenabar-by-Bernardo-Doral.jpg?w=5760&amp;ssl=1 5760w, https:\/\/i0.wp.com\/elgeneracionalpost.com\/wp-content\/uploads\/2023\/04\/Alejandro-Amenabar-by-Bernardo-Doral.jpg?resize=300%2C200&amp;ssl=1 300w, https:\/\/i0.wp.com\/elgeneracionalpost.com\/wp-content\/uploads\/2023\/04\/Alejandro-Amenabar-by-Bernardo-Doral.jpg?resize=1024%2C683&amp;ssl=1 1024w, https:\/\/i0.wp.com\/elgeneracionalpost.com\/wp-content\/uploads\/2023\/04\/Alejandro-Amenabar-by-Bernardo-Doral.jpg?resize=768%2C512&amp;ssl=1 768w, https:\/\/i0.wp.com\/elgeneracionalpost.com\/wp-content\/uploads\/2023\/04\/Alejandro-Amenabar-by-Bernardo-Doral.jpg?resize=1536%2C1024&amp;ssl=1 1536w, https:\/\/i0.wp.com\/elgeneracionalpost.com\/wp-content\/uploads\/2023\/04\/Alejandro-Amenabar-by-Bernardo-Doral.jpg?resize=2048%2C1365&amp;ssl=1 2048w, https:\/\/i0.wp.com\/elgeneracionalpost.com\/wp-content\/uploads\/2023\/04\/Alejandro-Amenabar-by-Bernardo-Doral.jpg?resize=150%2C100&amp;ssl=1 150w, https:\/\/i0.wp.com\/elgeneracionalpost.com\/wp-content\/uploads\/2023\/04\/Alejandro-Amenabar-by-Bernardo-Doral.jpg?resize=696%2C464&amp;ssl=1 696w, https:\/\/i0.wp.com\/elgeneracionalpost.com\/wp-content\/uploads\/2023\/04\/Alejandro-Amenabar-by-Bernardo-Doral.jpg?resize=1068%2C712&amp;ssl=1 1068w, https:\/\/i0.wp.com\/elgeneracionalpost.com\/wp-content\/uploads\/2023\/04\/Alejandro-Amenabar-by-Bernardo-Doral.jpg?resize=1920%2C1280&amp;ssl=1 1920w, https:\/\/i0.wp.com\/elgeneracionalpost.com\/wp-content\/uploads\/2023\/04\/Alejandro-Amenabar-by-Bernardo-Doral.jpg?w=1392&amp;ssl=1 1392w\" data-lazy-sizes=\"(max-width: 696px) 100vw, 696px\" data-lazy-src=\"https:\/\/i0.wp.com\/elgeneracionalpost.com\/wp-content\/uploads\/2023\/04\/Alejandro-Amenabar-by-Bernardo-Doral.jpg?resize=696%2C464&amp;is-pending-load=1#038;ssl=1\" srcset=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\"\/><noscript><img data-lazy-fallback=\"1\" data-attachment-id=\"85463\" data-permalink=\"https:\/\/elgeneracionalpost.com\/cultura\/2023\/0411\/85460\/terceras-jornadas-del-oficio-cinematografico-en-las-palmas-de-gran-canaria.html\/attachment\/alejandro-amenabar-by-bernardo-doral\" data-orig-file=\"https:\/\/i0.wp.com\/elgeneracionalpost.com\/wp-content\/uploads\/2023\/04\/Alejandro-Amenabar-by-Bernardo-Doral.jpg?fit=5760%2C3840&amp;ssl=1\" data-orig-size=\"5760,3840\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;4.5&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;Canon EOS 5D Mark III&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1440590522&quot;,&quot;copyright&quot;:&quot;\\u00a9 bernardo doral&quot;,&quot;focal_length&quot;:&quot;70&quot;,&quot;iso&quot;:&quot;320&quot;,&quot;shutter_speed&quot;:&quot;0.008&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"Alejandro Amen\u00e1bar by Bernardo Doral\" data-image-description=\"\" data-image-caption=\"&lt;p&gt;Alejandro Amen\u00e1bar. | Fuente: 18Chulos&lt;\/p&gt;&#10;\" data-medium-file=\"https:\/\/i0.wp.com\/elgeneracionalpost.com\/wp-content\/uploads\/2023\/04\/Alejandro-Amenabar-by-Bernardo-Doral.jpg?fit=300%2C200&amp;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/elgeneracionalpost.com\/wp-content\/uploads\/2023\/04\/Alejandro-Amenabar-by-Bernardo-Doral.jpg?fit=696%2C464&amp;ssl=1\" decoding=\"async\" class=\"wp-image-85463 size-full\" src=\"https:\/\/i0.wp.com\/elgeneracionalpost.com\/wp-content\/uploads\/2023\/04\/Alejandro-Amenabar-by-Bernardo-Doral.jpg?resize=696%2C464&amp;ssl=1\" alt=\"\" width=\"696\" height=\"464\" srcset=\"https:\/\/i0.wp.com\/elgeneracionalpost.com\/wp-content\/uploads\/2023\/04\/Alejandro-Amenabar-by-Bernardo-Doral.jpg?w=5760&amp;ssl=1 5760w, https:\/\/i0.wp.com\/elgeneracionalpost.com\/wp-content\/uploads\/2023\/04\/Alejandro-Amenabar-by-Bernardo-Doral.jpg?resize=300%2C200&amp;ssl=1 300w, https:\/\/i0.wp.com\/elgeneracionalpost.com\/wp-content\/uploads\/2023\/04\/Alejandro-Amenabar-by-Bernardo-Doral.jpg?resize=1024%2C683&amp;ssl=1 1024w, https:\/\/i0.wp.com\/elgeneracionalpost.com\/wp-content\/uploads\/2023\/04\/Alejandro-Amenabar-by-Bernardo-Doral.jpg?resize=768%2C512&amp;ssl=1 768w, https:\/\/i0.wp.com\/elgeneracionalpost.com\/wp-content\/uploads\/2023\/04\/Alejandro-Amenabar-by-Bernardo-Doral.jpg?resize=1536%2C1024&amp;ssl=1 1536w, https:\/\/i0.wp.com\/elgeneracionalpost.com\/wp-content\/uploads\/2023\/04\/Alejandro-Amenabar-by-Bernardo-Doral.jpg?resize=2048%2C1365&amp;ssl=1 2048w, https:\/\/i0.wp.com\/elgeneracionalpost.com\/wp-content\/uploads\/2023\/04\/Alejandro-Amenabar-by-Bernardo-Doral.jpg?resize=150%2C100&amp;ssl=1 150w, https:\/\/i0.wp.com\/elgeneracionalpost.com\/wp-content\/uploads\/2023\/04\/Alejandro-Amenabar-by-Bernardo-Doral.jpg?resize=696%2C464&amp;ssl=1 696w, https:\/\/i0.wp.com\/elgeneracionalpost.com\/wp-content\/uploads\/2023\/04\/Alejandro-Amenabar-by-Bernardo-Doral.jpg?resize=1068%2C712&amp;ssl=1 1068w, https:\/\/i0.wp.com\/elgeneracionalpost.com\/wp-content\/uploads\/2023\/04\/Alejandro-Amenabar-by-Bernardo-Doral.jpg?resize=1920%2C1280&amp;ssl=1 1920w, https:\/\/i0.wp.com\/elgeneracionalpost.com\/wp-content\/uploads\/2023\/04\/Alejandro-Amenabar-by-Bernardo-Doral.jpg?w=1392&amp;ssl=1 1392w\" sizes=\"(max-width: 696px) 100vw, 696px\" data-recalc-dims=\"1\"\/><\/noscript><figcaption id=\"caption-attachment-85463\" class=\"wp-caption-text\">Alejandro Amenabar | \u0179r\u00f3d\u0142o: 18Pimps<\/figcaption><\/figure>\n<p>Tego samego dnia o 19:00 w Cinesa El Muelle \u00c1ngela Molina dokona przegl\u0105du swojej kariery z Elen\u0105 S\u00e1nchez.<\/p>\n<p style=\"font-weight: 400\"><strong>Angela Molina:<\/strong> <strong>Rentgen \u017cycia filmowego. <\/strong>Powiedzie\u0107 o \u00c1ngeli Molinie to tak, jakby pisa\u0107 wielkimi literami o historii naszego kina. Oznacza to m\u00f3wienie o Bu\u00f1uelu, Almod\u00f3varze, Picazo, Armi\u00f1anie, Guti\u00e9rrezie Arag\u00f3nie, Jaime Camino, Ricardo Franco, Borau, Uribe\u2026<\/p>\n<p style=\"font-weight: 400\">Uznany za <strong>Krajowa Nagroda Filmowa, Honorowa Nagroda Goya, Z\u0142oty Medal Akademii i Z\u0142oty Medal za Zas\u0142ugi w Sztukach Pi\u0119knych<\/strong>Skarby \u00c1ngeli Moliny <strong>liczne nagrody mi\u0119dzynarodowe<\/strong> takie jak Dawid Donatello nagrodzony przez Akademi\u0119 W\u0142osk\u0105, Srebrna Muszla na Festiwalu w San Sebastian czy Grand Prix New York Critics, ale tak\u017ce Honorowy Spike Seminci, a nawet 5 Srebrnych Ramek\u2026<\/p>\n<figure id=\"attachment_85467\" aria-describedby=\"caption-attachment-85467\" style=\"width: 850px\" class=\"wp-caption alignnone\"><img data-attachment-id=\"85467\" data-permalink=\"https:\/\/elgeneracionalpost.com\/cultura\/2023\/0411\/85460\/terceras-jornadas-del-oficio-cinematografico-en-las-palmas-de-gran-canaria.html\/attachment\/angela-molina-by-javier-salas\" data-orig-file=\"https:\/\/i0.wp.com\/elgeneracionalpost.com\/wp-content\/uploads\/2023\/04\/angela-molina-by-Javier-Salas.jpg?fit=850%2C1135&amp;ssl=1\" data-orig-size=\"850,1135\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;PENTAX 645D&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1383134384&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;200&quot;,&quot;shutter_speed&quot;:&quot;0.0125&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"angela molina-by Javier Salas\" data-image-description=\"\" data-image-caption=\"&lt;p&gt;\u00c1ngela Molina | Fuente: 18Chulos&lt;\/p&gt;&#10;\" data-medium-file=\"https:\/\/i0.wp.com\/elgeneracionalpost.com\/wp-content\/uploads\/2023\/04\/angela-molina-by-Javier-Salas.jpg?fit=225%2C300&amp;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/elgeneracionalpost.com\/wp-content\/uploads\/2023\/04\/angela-molina-by-Javier-Salas.jpg?fit=696%2C929&amp;ssl=1\" decoding=\"async\" class=\"size-full wp-image-85467 jetpack-lazy-image\" src=\"https:\/\/i0.wp.com\/elgeneracionalpost.com\/wp-content\/uploads\/2023\/04\/angela-molina-by-Javier-Salas.jpg?resize=696%2C929&amp;ssl=1\" alt=\"\" width=\"696\" height=\"929\" data-recalc-dims=\"1\" data-lazy-srcset=\"https:\/\/i0.wp.com\/elgeneracionalpost.com\/wp-content\/uploads\/2023\/04\/angela-molina-by-Javier-Salas.jpg?w=850&amp;ssl=1 850w, https:\/\/i0.wp.com\/elgeneracionalpost.com\/wp-content\/uploads\/2023\/04\/angela-molina-by-Javier-Salas.jpg?resize=225%2C300&amp;ssl=1 225w, https:\/\/i0.wp.com\/elgeneracionalpost.com\/wp-content\/uploads\/2023\/04\/angela-molina-by-Javier-Salas.jpg?resize=767%2C1024&amp;ssl=1 767w, https:\/\/i0.wp.com\/elgeneracionalpost.com\/wp-content\/uploads\/2023\/04\/angela-molina-by-Javier-Salas.jpg?resize=768%2C1026&amp;ssl=1 768w, https:\/\/i0.wp.com\/elgeneracionalpost.com\/wp-content\/uploads\/2023\/04\/angela-molina-by-Javier-Salas.jpg?resize=150%2C200&amp;ssl=1 150w, https:\/\/i0.wp.com\/elgeneracionalpost.com\/wp-content\/uploads\/2023\/04\/angela-molina-by-Javier-Salas.jpg?resize=300%2C401&amp;ssl=1 300w, https:\/\/i0.wp.com\/elgeneracionalpost.com\/wp-content\/uploads\/2023\/04\/angela-molina-by-Javier-Salas.jpg?resize=696%2C929&amp;ssl=1 696w\" data-lazy-sizes=\"(max-width: 696px) 100vw, 696px\" data-lazy-src=\"https:\/\/i0.wp.com\/elgeneracionalpost.com\/wp-content\/uploads\/2023\/04\/angela-molina-by-Javier-Salas.jpg?resize=696%2C929&amp;is-pending-load=1#038;ssl=1\" srcset=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\"\/><noscript><img loading=\"lazy\" data-lazy-fallback=\"1\" data-attachment-id=\"85467\" data-permalink=\"https:\/\/elgeneracionalpost.com\/cultura\/2023\/0411\/85460\/terceras-jornadas-del-oficio-cinematografico-en-las-palmas-de-gran-canaria.html\/attachment\/angela-molina-by-javier-salas\" data-orig-file=\"https:\/\/i0.wp.com\/elgeneracionalpost.com\/wp-content\/uploads\/2023\/04\/angela-molina-by-Javier-Salas.jpg?fit=850%2C1135&amp;ssl=1\" data-orig-size=\"850,1135\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;PENTAX 645D&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1383134384&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;200&quot;,&quot;shutter_speed&quot;:&quot;0.0125&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"angela molina-by Javier Salas\" data-image-description=\"\" data-image-caption=\"&lt;p&gt;\u00c1ngela Molina | Fuente: 18Chulos&lt;\/p&gt;&#10;\" data-medium-file=\"https:\/\/i0.wp.com\/elgeneracionalpost.com\/wp-content\/uploads\/2023\/04\/angela-molina-by-Javier-Salas.jpg?fit=225%2C300&amp;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/elgeneracionalpost.com\/wp-content\/uploads\/2023\/04\/angela-molina-by-Javier-Salas.jpg?fit=696%2C929&amp;ssl=1\" decoding=\"async\" class=\"size-full wp-image-85467\" src=\"https:\/\/i0.wp.com\/elgeneracionalpost.com\/wp-content\/uploads\/2023\/04\/angela-molina-by-Javier-Salas.jpg?resize=696%2C929&amp;ssl=1\" alt=\"\" width=\"696\" height=\"929\" srcset=\"https:\/\/i0.wp.com\/elgeneracionalpost.com\/wp-content\/uploads\/2023\/04\/angela-molina-by-Javier-Salas.jpg?w=850&amp;ssl=1 850w, https:\/\/i0.wp.com\/elgeneracionalpost.com\/wp-content\/uploads\/2023\/04\/angela-molina-by-Javier-Salas.jpg?resize=225%2C300&amp;ssl=1 225w, https:\/\/i0.wp.com\/elgeneracionalpost.com\/wp-content\/uploads\/2023\/04\/angela-molina-by-Javier-Salas.jpg?resize=767%2C1024&amp;ssl=1 767w, https:\/\/i0.wp.com\/elgeneracionalpost.com\/wp-content\/uploads\/2023\/04\/angela-molina-by-Javier-Salas.jpg?resize=768%2C1026&amp;ssl=1 768w, https:\/\/i0.wp.com\/elgeneracionalpost.com\/wp-content\/uploads\/2023\/04\/angela-molina-by-Javier-Salas.jpg?resize=150%2C200&amp;ssl=1 150w, https:\/\/i0.wp.com\/elgeneracionalpost.com\/wp-content\/uploads\/2023\/04\/angela-molina-by-Javier-Salas.jpg?resize=300%2C401&amp;ssl=1 300w, https:\/\/i0.wp.com\/elgeneracionalpost.com\/wp-content\/uploads\/2023\/04\/angela-molina-by-Javier-Salas.jpg?resize=696%2C929&amp;ssl=1 696w\" sizes=\"auto, (max-width: 696px) 100vw, 696px\" data-recalc-dims=\"1\"\/><\/noscript><figcaption id=\"caption-attachment-85467\" class=\"wp-caption-text\">Angela Molina | \u0179r\u00f3d\u0142o: 18Pimps<\/figcaption><\/figure>\n<p>W sobot\u0119 15-tego w Millerze okr\u0105g\u0142y st\u00f3\u0142 rozpocznie si\u0119 o godzinie 12:00 <strong>Karr\u0119 Elejalde i Paco Leona. Aktorzy i autorzy. Od komedii po dramat.<\/strong><\/p>\n<p style=\"font-weight: 400\">Obaj s\u0105 niezwykle znani ze swojego talentu komediowego i zaimponowali nam swoimi wspania\u0142ymi, dramatycznymi postaciami. Karra Elejalde i Paco Le\u00f3n reprezentuj\u0105 dwa pokolenia uwielbianych przez publiczno\u015b\u0107 aktor\u00f3w, ale \u0142\u0105czy ich znacznie wi\u0119cej. Jego ogromne zdolno\u015bci tw\u00f3rcze zapewni\u0142y nam wyj\u0105tkowe chwile: od uderzenia pi\u0142ki <strong><em>poduszka powietrzna<\/em> <\/strong>dla wci\u0105gaj\u0105cych <em><strong>szkar\u0142at lub eksplozja<\/strong><\/em>. Oba s\u0105 <strong>tw\u00f3rcy, scenarzy\u015bci i re\u017cyserzy r\u00f3\u017cnorodnych tytu\u0142\u00f3w.<\/strong><\/p>\n<p style=\"font-weight: 400\">ze \u015bmiechu <em><strong>Osiem baskijskich nazwisk<\/strong><\/em>  do rekonstrukcji historycznej w <em><strong>Dop\u00f3ki trwa wojna<\/strong><\/em>dramatu Ismaela de <em><strong>zmar\u0142a matka<\/strong><\/em>  do samotnego Alfredo de <em><strong>naczynie<\/strong><\/em>, Elejalde bra\u0142 udzia\u0142 w ponad 60 tytu\u0142ach. Zdobywca 2 nagr\u00f3d Goya, 2 nagr\u00f3d Gaudiego czy ostatniej nagrody dla najlepszego aktora pierwszoplanowego za film Seminci.<\/p>\n<p style=\"font-weight: 400\">Paco Le\u00f3n zyska\u0142 popularno\u015b\u0107 w telewizji. Jej charyzmatyczna Luisma w mitycznym serialu <em><strong>pomoc<\/strong><\/em>, wci\u0105\u017c cieszy si\u0119 uznaniem rzeszy fan\u00f3w. Jednak skok w stron\u0119 re\u017cyserii przyni\u00f3s\u0142 mu szacunek krytyk\u00f3w filmowych. Od tego momentu Paco Le\u00f3n na przemian tworzy i re\u017cyseruje dzie\u0142a audiowizualne, pracuj\u0105c jako aktor, wyst\u0119puj\u0105c w \u015bwietnych komediach i postaciach dramatycznych, takich jak tajemniczy Dami\u00e1n w niedawnym filmie <em><strong>nie patrz w oczy<\/strong><\/em>w swojej d\u0142ugiej karierze, kt\u00f3ra przynios\u0142a mu nagrod\u0119 Ondas, trzy Fotogramas de Plata i wiele innych nominacji do Goya.<\/p>\n<figure id=\"attachment_85473\" aria-describedby=\"caption-attachment-85473\" style=\"width: 827px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" data-attachment-id=\"85473\" data-permalink=\"https:\/\/elgeneracionalpost.com\/cultura\/2023\/0411\/85460\/terceras-jornadas-del-oficio-cinematografico-en-las-palmas-de-gran-canaria.html\/attachment\/img-1238\" data-orig-file=\"https:\/\/i0.wp.com\/elgeneracionalpost.com\/wp-content\/uploads\/2023\/04\/IMG-1238.jpg?fit=827%2C681&amp;ssl=1\" data-orig-size=\"827,681\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"IMG-1238\" data-image-description=\"\" data-image-caption=\"&lt;p&gt;Paco Le\u00f3n | Fuente: Instagram (@pacoleon)&lt;\/p&gt;&#10;\" data-medium-file=\"https:\/\/i0.wp.com\/elgeneracionalpost.com\/wp-content\/uploads\/2023\/04\/IMG-1238.jpg?fit=300%2C247&amp;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/elgeneracionalpost.com\/wp-content\/uploads\/2023\/04\/IMG-1238.jpg?fit=696%2C573&amp;ssl=1\" decoding=\"async\" class=\"size-full wp-image-85473 jetpack-lazy-image\" src=\"https:\/\/i0.wp.com\/elgeneracionalpost.com\/wp-content\/uploads\/2023\/04\/IMG-1238.jpg?resize=696%2C573&amp;ssl=1\" alt=\"\" width=\"696\" height=\"573\" data-recalc-dims=\"1\" data-lazy-srcset=\"https:\/\/i0.wp.com\/elgeneracionalpost.com\/wp-content\/uploads\/2023\/04\/IMG-1238.jpg?w=827&amp;ssl=1 827w, https:\/\/i0.wp.com\/elgeneracionalpost.com\/wp-content\/uploads\/2023\/04\/IMG-1238.jpg?resize=300%2C247&amp;ssl=1 300w, https:\/\/i0.wp.com\/elgeneracionalpost.com\/wp-content\/uploads\/2023\/04\/IMG-1238.jpg?resize=768%2C632&amp;ssl=1 768w, https:\/\/i0.wp.com\/elgeneracionalpost.com\/wp-content\/uploads\/2023\/04\/IMG-1238.jpg?resize=150%2C124&amp;ssl=1 150w, https:\/\/i0.wp.com\/elgeneracionalpost.com\/wp-content\/uploads\/2023\/04\/IMG-1238.jpg?resize=696%2C573&amp;ssl=1 696w\" data-lazy-sizes=\"(max-width: 696px) 100vw, 696px\" data-lazy-src=\"https:\/\/i0.wp.com\/elgeneracionalpost.com\/wp-content\/uploads\/2023\/04\/IMG-1238.jpg?resize=696%2C573&amp;is-pending-load=1#038;ssl=1\" srcset=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\"\/><noscript><img loading=\"lazy\" data-lazy-fallback=\"1\" data-attachment-id=\"85473\" data-permalink=\"https:\/\/elgeneracionalpost.com\/cultura\/2023\/0411\/85460\/terceras-jornadas-del-oficio-cinematografico-en-las-palmas-de-gran-canaria.html\/attachment\/img-1238\" data-orig-file=\"https:\/\/i0.wp.com\/elgeneracionalpost.com\/wp-content\/uploads\/2023\/04\/IMG-1238.jpg?fit=827%2C681&amp;ssl=1\" data-orig-size=\"827,681\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"IMG-1238\" data-image-description=\"\" data-image-caption=\"&lt;p&gt;Paco Le\u00f3n | Fuente: Instagram (@pacoleon)&lt;\/p&gt;&#10;\" data-medium-file=\"https:\/\/i0.wp.com\/elgeneracionalpost.com\/wp-content\/uploads\/2023\/04\/IMG-1238.jpg?fit=300%2C247&amp;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/elgeneracionalpost.com\/wp-content\/uploads\/2023\/04\/IMG-1238.jpg?fit=696%2C573&amp;ssl=1\" decoding=\"async\" class=\"size-full wp-image-85473\" src=\"https:\/\/i0.wp.com\/elgeneracionalpost.com\/wp-content\/uploads\/2023\/04\/IMG-1238.jpg?resize=696%2C573&amp;ssl=1\" alt=\"\" width=\"696\" height=\"573\" srcset=\"https:\/\/i0.wp.com\/elgeneracionalpost.com\/wp-content\/uploads\/2023\/04\/IMG-1238.jpg?w=827&amp;ssl=1 827w, https:\/\/i0.wp.com\/elgeneracionalpost.com\/wp-content\/uploads\/2023\/04\/IMG-1238.jpg?resize=300%2C247&amp;ssl=1 300w, https:\/\/i0.wp.com\/elgeneracionalpost.com\/wp-content\/uploads\/2023\/04\/IMG-1238.jpg?resize=768%2C632&amp;ssl=1 768w, https:\/\/i0.wp.com\/elgeneracionalpost.com\/wp-content\/uploads\/2023\/04\/IMG-1238.jpg?resize=150%2C124&amp;ssl=1 150w, https:\/\/i0.wp.com\/elgeneracionalpost.com\/wp-content\/uploads\/2023\/04\/IMG-1238.jpg?resize=696%2C573&amp;ssl=1 696w\" sizes=\"auto, (max-width: 696px) 100vw, 696px\" data-recalc-dims=\"1\"\/><\/noscript><figcaption id=\"caption-attachment-85473\" class=\"wp-caption-text\">Pa\u00e7o Le\u00e3o | \u0179r\u00f3d\u0142o: Instagram (@pacoleon)<\/figcaption><\/figure>\n<p style=\"font-weight: 400\"><strong>Karra Elejalde i Paco Le\u00f3n b\u0119d\u0105 rami\u0119 w rami\u0119 z Wyoming<\/strong> porozmawia\u0107 z publiczno\u015bci\u0105 przy okr\u0105g\u0142ym stole, kt\u00f3ry nie zapowiada si\u0119 nudno.<\/p>\n<p>Wreszcie w sobot\u0119 o 16:00:<strong>Anna Castillo i Macarena Garc\u00eda: M\u0142ode i ju\u017c niezb\u0119dne.<\/strong><\/p>\n<figure id=\"attachment_85476\" aria-describedby=\"caption-attachment-85476\" style=\"width: 1000px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" data-attachment-id=\"85476\" data-permalink=\"https:\/\/elgeneracionalpost.com\/cultura\/2023\/0411\/85460\/terceras-jornadas-del-oficio-cinematografico-en-las-palmas-de-gran-canaria.html\/attachment\/macarena-garcia\" data-orig-file=\"https:\/\/i0.wp.com\/elgeneracionalpost.com\/wp-content\/uploads\/2023\/04\/Macarena-Garcia.jpg?fit=1000%2C1386&amp;ssl=1\" data-orig-size=\"1000,1386\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Macarena Garc\u00eda\" data-image-description=\"\" data-image-caption=\"&lt;p&gt;Macarena Garc\u00eda | Fuente: 18Chulos&lt;\/p&gt;&#10;\" data-medium-file=\"https:\/\/i0.wp.com\/elgeneracionalpost.com\/wp-content\/uploads\/2023\/04\/Macarena-Garcia.jpg?fit=216%2C300&amp;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/elgeneracionalpost.com\/wp-content\/uploads\/2023\/04\/Macarena-Garcia.jpg?fit=696%2C964&amp;ssl=1\" decoding=\"async\" class=\"size-full wp-image-85476 jetpack-lazy-image\" src=\"https:\/\/i0.wp.com\/elgeneracionalpost.com\/wp-content\/uploads\/2023\/04\/Macarena-Garcia.jpg?resize=696%2C965&amp;ssl=1\" alt=\"\" width=\"696\" height=\"965\" data-recalc-dims=\"1\" data-lazy-srcset=\"https:\/\/i0.wp.com\/elgeneracionalpost.com\/wp-content\/uploads\/2023\/04\/Macarena-Garcia.jpg?w=1000&amp;ssl=1 1000w, https:\/\/i0.wp.com\/elgeneracionalpost.com\/wp-content\/uploads\/2023\/04\/Macarena-Garcia.jpg?resize=216%2C300&amp;ssl=1 216w, https:\/\/i0.wp.com\/elgeneracionalpost.com\/wp-content\/uploads\/2023\/04\/Macarena-Garcia.jpg?resize=739%2C1024&amp;ssl=1 739w, https:\/\/i0.wp.com\/elgeneracionalpost.com\/wp-content\/uploads\/2023\/04\/Macarena-Garcia.jpg?resize=768%2C1064&amp;ssl=1 768w, https:\/\/i0.wp.com\/elgeneracionalpost.com\/wp-content\/uploads\/2023\/04\/Macarena-Garcia.jpg?resize=150%2C208&amp;ssl=1 150w, https:\/\/i0.wp.com\/elgeneracionalpost.com\/wp-content\/uploads\/2023\/04\/Macarena-Garcia.jpg?resize=300%2C416&amp;ssl=1 300w, https:\/\/i0.wp.com\/elgeneracionalpost.com\/wp-content\/uploads\/2023\/04\/Macarena-Garcia.jpg?resize=696%2C965&amp;ssl=1 696w\" data-lazy-sizes=\"(max-width: 696px) 100vw, 696px\" data-lazy-src=\"https:\/\/i0.wp.com\/elgeneracionalpost.com\/wp-content\/uploads\/2023\/04\/Macarena-Garcia.jpg?resize=696%2C965&amp;is-pending-load=1#038;ssl=1\" srcset=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\"\/><noscript><img loading=\"lazy\" data-lazy-fallback=\"1\" data-attachment-id=\"85476\" data-permalink=\"https:\/\/elgeneracionalpost.com\/cultura\/2023\/0411\/85460\/terceras-jornadas-del-oficio-cinematografico-en-las-palmas-de-gran-canaria.html\/attachment\/macarena-garcia\" data-orig-file=\"https:\/\/i0.wp.com\/elgeneracionalpost.com\/wp-content\/uploads\/2023\/04\/Macarena-Garcia.jpg?fit=1000%2C1386&amp;ssl=1\" data-orig-size=\"1000,1386\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Macarena Garc\u00eda\" data-image-description=\"\" data-image-caption=\"&lt;p&gt;Macarena Garc\u00eda | Fuente: 18Chulos&lt;\/p&gt;&#10;\" data-medium-file=\"https:\/\/i0.wp.com\/elgeneracionalpost.com\/wp-content\/uploads\/2023\/04\/Macarena-Garcia.jpg?fit=216%2C300&amp;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/elgeneracionalpost.com\/wp-content\/uploads\/2023\/04\/Macarena-Garcia.jpg?fit=696%2C964&amp;ssl=1\" decoding=\"async\" class=\"size-full wp-image-85476\" src=\"https:\/\/i0.wp.com\/elgeneracionalpost.com\/wp-content\/uploads\/2023\/04\/Macarena-Garcia.jpg?resize=696%2C965&amp;ssl=1\" alt=\"\" width=\"696\" height=\"965\" srcset=\"https:\/\/i0.wp.com\/elgeneracionalpost.com\/wp-content\/uploads\/2023\/04\/Macarena-Garcia.jpg?w=1000&amp;ssl=1 1000w, https:\/\/i0.wp.com\/elgeneracionalpost.com\/wp-content\/uploads\/2023\/04\/Macarena-Garcia.jpg?resize=216%2C300&amp;ssl=1 216w, https:\/\/i0.wp.com\/elgeneracionalpost.com\/wp-content\/uploads\/2023\/04\/Macarena-Garcia.jpg?resize=739%2C1024&amp;ssl=1 739w, https:\/\/i0.wp.com\/elgeneracionalpost.com\/wp-content\/uploads\/2023\/04\/Macarena-Garcia.jpg?resize=768%2C1064&amp;ssl=1 768w, https:\/\/i0.wp.com\/elgeneracionalpost.com\/wp-content\/uploads\/2023\/04\/Macarena-Garcia.jpg?resize=150%2C208&amp;ssl=1 150w, https:\/\/i0.wp.com\/elgeneracionalpost.com\/wp-content\/uploads\/2023\/04\/Macarena-Garcia.jpg?resize=300%2C416&amp;ssl=1 300w, https:\/\/i0.wp.com\/elgeneracionalpost.com\/wp-content\/uploads\/2023\/04\/Macarena-Garcia.jpg?resize=696%2C965&amp;ssl=1 696w\" sizes=\"auto, (max-width: 696px) 100vw, 696px\" data-recalc-dims=\"1\"\/><\/noscript><figcaption id=\"caption-attachment-85476\" class=\"wp-caption-text\">Macarena Garcia | \u0179r\u00f3d\u0142o: 18Pimps<\/figcaption><\/figure>\n<p style=\"font-weight: 400\">Reprezentuj\u0105 m\u0142odsze pokolenie w tych trzecich dniach, ale kino gromadz\u0105 pod dostatkiem. Zdobywcy dw\u00f3ch nagr\u00f3d Goy za <em><strong>Kr\u00f3lewna \u015anie\u017cka<\/strong><\/em>  To jest <em><strong>oliwka<\/strong><\/em>Do\u0142\u0105czy\u0142y Macarena Garc\u00eda i Anna Castillo <em><strong>Telefon<\/strong><\/em>, komedia muzyczna, kt\u00f3ra by\u0142a ma\u0142\u0105 rewolucj\u0105 w naszym kinie. Z jednym <strong>bogate do\u015bwiadczenie filmowe, teatralne i telewizyjne<\/strong>Te dwie m\u0142ode aktorki sta\u0142y si\u0119 ju\u017c niezb\u0119dnymi twarzami naszych ekran\u00f3w. Obaj zdradz\u0105 nam sekret swojego sukcesu w rozmowie o sposobie rozumienia interpretacji prowadzonej przez Elen\u0119 S\u00e1nchez.<\/p>\n<div class=\"sharedaddy sd-block sd-like jetpack-likes-widget-wrapper jetpack-likes-widget-unloaded\" id=\"like-post-wrapper-153844979-85460-64354587189de\" data-src=\"https:\/\/widgets.wp.com\/likes\/#blog_id=153844979&amp;post_id=85460&amp;origin=elgeneracionalpost.com&amp;obj_id=153844979-85460-64354587189de\" data-name=\"like-post-frame-153844979-85460-64354587189de\" data-title=\"Me gusta o Compartir\">\n<h3 class=\"sd-title\">Lubi\u0119 to:<\/h3>\n<p><span class=\"button\"><span>lubi\u0119<\/span><\/span> <span class=\"loading\">\u0141adowanie\u2026<\/span><\/p>\n<p><span class=\"sd-text-color\"\/><\/div>\n<p><h3 class=\"jp-relatedposts-headline\"><em>Powi\u0105zany<\/em><\/h3>\n<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Spotkanie z wielkimi nazwiskami kina hiszpa\u0144skiego powraca po raz kolejny na sto\u0142eczny Festiwal Filmowy... <\/p>","protected":false},"author":1,"featured_media":1119,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"fifu_image_url":"https:\/\/elgeneracionalpost.com\/wp-content\/uploads\/2023\/04\/30_05-161-foto-Teresa-Isasi.jpg","fifu_image_alt":"","footnotes":""},"categories":[35],"tags":[],"class_list":["post-1118","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cultura-e-lazer","latest_post"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Terceira Jornada sobre o Artesanato Cinematogr\u00e1fico em Las Palmas de Gran Canaria - Tirinha.com<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/tirinha.com\/pl\/1118\/terceira-jornada-sobre-o-artesanato-cinematografico-em-las-palmas-de-gran-canaria\/\" \/>\n<meta property=\"og:locale\" content=\"pl_PL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Terceira Jornada sobre o Artesanato Cinematogr\u00e1fico em Las Palmas de Gran Canaria - Tirinha.com\" \/>\n<meta property=\"og:description\" content=\"O encontro com grandes nomes do cinema espanhol volta mais um ano ao marco do Festival de Cinema da capital &hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/tirinha.com\/pl\/1118\/terceira-jornada-sobre-o-artesanato-cinematografico-em-las-palmas-de-gran-canaria\/\" \/>\n<meta property=\"og:site_name\" content=\"Tirinha.com\" \/>\n<meta property=\"article:published_time\" content=\"2023-04-11T11:34:46+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/elgeneracionalpost.com\/wp-content\/uploads\/2023\/04\/30_05-161-foto-Teresa-Isasi.jpg\" \/>\n<meta name=\"author\" content=\"Admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/elgeneracionalpost.com\/wp-content\/uploads\/2023\/04\/30_05-161-foto-Teresa-Isasi.jpg\" \/>\n<meta name=\"twitter:label1\" content=\"Napisane przez\" \/>\n\t<meta name=\"twitter:data1\" content=\"Admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Szacowany czas czytania\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minut\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/tirinha.com\\\/ja\\\/1118\\\/terceira-jornada-sobre-o-artesanato-cinematografico-em-las-palmas-de-gran-canaria\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/tirinha.com\\\/ja\\\/1118\\\/terceira-jornada-sobre-o-artesanato-cinematografico-em-las-palmas-de-gran-canaria\\\/\"},\"author\":{\"name\":\"Admin\",\"@id\":\"https:\\\/\\\/tirinha.com\\\/hr\\\/#\\\/schema\\\/person\\\/e22bdfbe17e0461f7e927e6a1208d4d9\"},\"headline\":\"Terceira Jornada sobre o Artesanato Cinematogr\u00e1fico em Las Palmas de Gran Canaria\",\"datePublished\":\"2023-04-11T11:34:46+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/tirinha.com\\\/ja\\\/1118\\\/terceira-jornada-sobre-o-artesanato-cinematografico-em-las-palmas-de-gran-canaria\\\/\"},\"wordCount\":1084,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/tirinha.com\\\/hr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/tirinha.com\\\/ja\\\/1118\\\/terceira-jornada-sobre-o-artesanato-cinematografico-em-las-palmas-de-gran-canaria\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/elgeneracionalpost.com\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/30_05-161-foto-Teresa-Isasi.jpg\",\"articleSection\":[\"Cultura e lazer\"],\"inLanguage\":\"pl-PL\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/tirinha.com\\\/ja\\\/1118\\\/terceira-jornada-sobre-o-artesanato-cinematografico-em-las-palmas-de-gran-canaria\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/tirinha.com\\\/ja\\\/1118\\\/terceira-jornada-sobre-o-artesanato-cinematografico-em-las-palmas-de-gran-canaria\\\/\",\"url\":\"https:\\\/\\\/tirinha.com\\\/ja\\\/1118\\\/terceira-jornada-sobre-o-artesanato-cinematografico-em-las-palmas-de-gran-canaria\\\/\",\"name\":\"Terceira Jornada sobre o Artesanato Cinematogr\u00e1fico em Las Palmas de Gran Canaria - Tirinha.com\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/tirinha.com\\\/hr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/tirinha.com\\\/ja\\\/1118\\\/terceira-jornada-sobre-o-artesanato-cinematografico-em-las-palmas-de-gran-canaria\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/tirinha.com\\\/ja\\\/1118\\\/terceira-jornada-sobre-o-artesanato-cinematografico-em-las-palmas-de-gran-canaria\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/elgeneracionalpost.com\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/30_05-161-foto-Teresa-Isasi.jpg\",\"datePublished\":\"2023-04-11T11:34:46+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/tirinha.com\\\/ja\\\/1118\\\/terceira-jornada-sobre-o-artesanato-cinematografico-em-las-palmas-de-gran-canaria\\\/#breadcrumb\"},\"inLanguage\":\"pl-PL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/tirinha.com\\\/ja\\\/1118\\\/terceira-jornada-sobre-o-artesanato-cinematografico-em-las-palmas-de-gran-canaria\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pl-PL\",\"@id\":\"https:\\\/\\\/tirinha.com\\\/ja\\\/1118\\\/terceira-jornada-sobre-o-artesanato-cinematografico-em-las-palmas-de-gran-canaria\\\/#primaryimage\",\"url\":\"https:\\\/\\\/elgeneracionalpost.com\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/30_05-161-foto-Teresa-Isasi.jpg\",\"contentUrl\":\"https:\\\/\\\/elgeneracionalpost.com\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/30_05-161-foto-Teresa-Isasi.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/tirinha.com\\\/ja\\\/1118\\\/terceira-jornada-sobre-o-artesanato-cinematografico-em-las-palmas-de-gran-canaria\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/tirinha.com\\\/hr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Terceira Jornada sobre o Artesanato Cinematogr\u00e1fico em Las Palmas de Gran Canaria\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/tirinha.com\\\/hr\\\/#website\",\"url\":\"https:\\\/\\\/tirinha.com\\\/hr\\\/\",\"name\":\"Tirinha.com\",\"description\":\"Arte e livros resenhas\",\"publisher\":{\"@id\":\"https:\\\/\\\/tirinha.com\\\/hr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/tirinha.com\\\/hr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pl-PL\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/tirinha.com\\\/hr\\\/#organization\",\"name\":\"Tirinha.com\",\"url\":\"https:\\\/\\\/tirinha.com\\\/hr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pl-PL\",\"@id\":\"https:\\\/\\\/tirinha.com\\\/hr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/tirinha.com\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/cropped-Logo-Tirinha.webp\",\"contentUrl\":\"https:\\\/\\\/tirinha.com\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/cropped-Logo-Tirinha.webp\",\"width\":512,\"height\":512,\"caption\":\"Tirinha.com\"},\"image\":{\"@id\":\"https:\\\/\\\/tirinha.com\\\/hr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/tirinha.com\\\/hr\\\/#\\\/schema\\\/person\\\/e22bdfbe17e0461f7e927e6a1208d4d9\",\"name\":\"Admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pl-PL\",\"@id\":\"https:\\\/\\\/tirinha.com\\\/wp-content\\\/litespeed\\\/avatar\\\/394da628e0e367b1790570a93fe58e9b.jpg?ver=1784126721\",\"url\":\"https:\\\/\\\/tirinha.com\\\/wp-content\\\/litespeed\\\/avatar\\\/394da628e0e367b1790570a93fe58e9b.jpg?ver=1784126721\",\"contentUrl\":\"https:\\\/\\\/tirinha.com\\\/wp-content\\\/litespeed\\\/avatar\\\/394da628e0e367b1790570a93fe58e9b.jpg?ver=1784126721\",\"caption\":\"Admin\"},\"url\":\"https:\\\/\\\/tirinha.com\\\/pl\\\/author\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Terceira Jornada sobre o Artesanato Cinematogr\u00e1fico em Las Palmas de Gran Canaria - Tirinha.com","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/tirinha.com\/pl\/1118\/terceira-jornada-sobre-o-artesanato-cinematografico-em-las-palmas-de-gran-canaria\/","og_locale":"pl_PL","og_type":"article","og_title":"Terceira Jornada sobre o Artesanato Cinematogr\u00e1fico em Las Palmas de Gran Canaria - Tirinha.com","og_description":"O encontro com grandes nomes do cinema espanhol volta mais um ano ao marco do Festival de Cinema da capital &hellip;","og_url":"https:\/\/tirinha.com\/pl\/1118\/terceira-jornada-sobre-o-artesanato-cinematografico-em-las-palmas-de-gran-canaria\/","og_site_name":"Tirinha.com","article_published_time":"2023-04-11T11:34:46+00:00","og_image":[{"url":"https:\/\/elgeneracionalpost.com\/wp-content\/uploads\/2023\/04\/30_05-161-foto-Teresa-Isasi.jpg","type":"","width":"","height":""}],"author":"Admin","twitter_card":"summary_large_image","twitter_image":"https:\/\/elgeneracionalpost.com\/wp-content\/uploads\/2023\/04\/30_05-161-foto-Teresa-Isasi.jpg","twitter_misc":{"Napisane przez":"Admin","Szacowany czas czytania":"5 minut"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/tirinha.com\/ja\/1118\/terceira-jornada-sobre-o-artesanato-cinematografico-em-las-palmas-de-gran-canaria\/#article","isPartOf":{"@id":"https:\/\/tirinha.com\/ja\/1118\/terceira-jornada-sobre-o-artesanato-cinematografico-em-las-palmas-de-gran-canaria\/"},"author":{"name":"Admin","@id":"https:\/\/tirinha.com\/hr\/#\/schema\/person\/e22bdfbe17e0461f7e927e6a1208d4d9"},"headline":"Terceira Jornada sobre o Artesanato Cinematogr\u00e1fico em Las Palmas de Gran Canaria","datePublished":"2023-04-11T11:34:46+00:00","mainEntityOfPage":{"@id":"https:\/\/tirinha.com\/ja\/1118\/terceira-jornada-sobre-o-artesanato-cinematografico-em-las-palmas-de-gran-canaria\/"},"wordCount":1084,"commentCount":0,"publisher":{"@id":"https:\/\/tirinha.com\/hr\/#organization"},"image":{"@id":"https:\/\/tirinha.com\/ja\/1118\/terceira-jornada-sobre-o-artesanato-cinematografico-em-las-palmas-de-gran-canaria\/#primaryimage"},"thumbnailUrl":"https:\/\/elgeneracionalpost.com\/wp-content\/uploads\/2023\/04\/30_05-161-foto-Teresa-Isasi.jpg","articleSection":["Cultura e lazer"],"inLanguage":"pl-PL","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/tirinha.com\/ja\/1118\/terceira-jornada-sobre-o-artesanato-cinematografico-em-las-palmas-de-gran-canaria\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/tirinha.com\/ja\/1118\/terceira-jornada-sobre-o-artesanato-cinematografico-em-las-palmas-de-gran-canaria\/","url":"https:\/\/tirinha.com\/ja\/1118\/terceira-jornada-sobre-o-artesanato-cinematografico-em-las-palmas-de-gran-canaria\/","name":"Terceira Jornada sobre o Artesanato Cinematogr\u00e1fico em Las Palmas de Gran Canaria - Tirinha.com","isPartOf":{"@id":"https:\/\/tirinha.com\/hr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/tirinha.com\/ja\/1118\/terceira-jornada-sobre-o-artesanato-cinematografico-em-las-palmas-de-gran-canaria\/#primaryimage"},"image":{"@id":"https:\/\/tirinha.com\/ja\/1118\/terceira-jornada-sobre-o-artesanato-cinematografico-em-las-palmas-de-gran-canaria\/#primaryimage"},"thumbnailUrl":"https:\/\/elgeneracionalpost.com\/wp-content\/uploads\/2023\/04\/30_05-161-foto-Teresa-Isasi.jpg","datePublished":"2023-04-11T11:34:46+00:00","breadcrumb":{"@id":"https:\/\/tirinha.com\/ja\/1118\/terceira-jornada-sobre-o-artesanato-cinematografico-em-las-palmas-de-gran-canaria\/#breadcrumb"},"inLanguage":"pl-PL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/tirinha.com\/ja\/1118\/terceira-jornada-sobre-o-artesanato-cinematografico-em-las-palmas-de-gran-canaria\/"]}]},{"@type":"ImageObject","inLanguage":"pl-PL","@id":"https:\/\/tirinha.com\/ja\/1118\/terceira-jornada-sobre-o-artesanato-cinematografico-em-las-palmas-de-gran-canaria\/#primaryimage","url":"https:\/\/elgeneracionalpost.com\/wp-content\/uploads\/2023\/04\/30_05-161-foto-Teresa-Isasi.jpg","contentUrl":"https:\/\/elgeneracionalpost.com\/wp-content\/uploads\/2023\/04\/30_05-161-foto-Teresa-Isasi.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/tirinha.com\/ja\/1118\/terceira-jornada-sobre-o-artesanato-cinematografico-em-las-palmas-de-gran-canaria\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/tirinha.com\/hr\/"},{"@type":"ListItem","position":2,"name":"Terceira Jornada sobre o Artesanato Cinematogr\u00e1fico em Las Palmas de Gran Canaria"}]},{"@type":"WebSite","@id":"https:\/\/tirinha.com\/hr\/#website","url":"https:\/\/tirinha.com\/hr\/","name":"Tirinha.com","description":"Recenzje dzie\u0142 sztuki i ksi\u0105\u017cek","publisher":{"@id":"https:\/\/tirinha.com\/hr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/tirinha.com\/hr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pl-PL"},{"@type":"Organization","@id":"https:\/\/tirinha.com\/hr\/#organization","name":"Tirinha.com","url":"https:\/\/tirinha.com\/hr\/","logo":{"@type":"ImageObject","inLanguage":"pl-PL","@id":"https:\/\/tirinha.com\/hr\/#\/schema\/logo\/image\/","url":"https:\/\/tirinha.com\/wp-content\/uploads\/2023\/08\/cropped-Logo-Tirinha.webp","contentUrl":"https:\/\/tirinha.com\/wp-content\/uploads\/2023\/08\/cropped-Logo-Tirinha.webp","width":512,"height":512,"caption":"Tirinha.com"},"image":{"@id":"https:\/\/tirinha.com\/hr\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/tirinha.com\/hr\/#\/schema\/person\/e22bdfbe17e0461f7e927e6a1208d4d9","name":"Admin","image":{"@type":"ImageObject","inLanguage":"pl-PL","@id":"https:\/\/tirinha.com\/wp-content\/litespeed\/avatar\/394da628e0e367b1790570a93fe58e9b.jpg?ver=1784126721","url":"https:\/\/tirinha.com\/wp-content\/litespeed\/avatar\/394da628e0e367b1790570a93fe58e9b.jpg?ver=1784126721","contentUrl":"https:\/\/tirinha.com\/wp-content\/litespeed\/avatar\/394da628e0e367b1790570a93fe58e9b.jpg?ver=1784126721","caption":"Admin"},"url":"https:\/\/tirinha.com\/pl\/author\/"}]}},"_links":{"self":[{"href":"https:\/\/tirinha.com\/pl\/wp-json\/wp\/v2\/posts\/1118","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tirinha.com\/pl\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tirinha.com\/pl\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tirinha.com\/pl\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/tirinha.com\/pl\/wp-json\/wp\/v2\/comments?post=1118"}],"version-history":[{"count":0,"href":"https:\/\/tirinha.com\/pl\/wp-json\/wp\/v2\/posts\/1118\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tirinha.com\/pl\/wp-json\/wp\/v2\/media\/1119"}],"wp:attachment":[{"href":"https:\/\/tirinha.com\/pl\/wp-json\/wp\/v2\/media?parent=1118"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tirinha.com\/pl\/wp-json\/wp\/v2\/categories?post=1118"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tirinha.com\/pl\/wp-json\/wp\/v2\/tags?post=1118"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}