{"id":686,"date":"2023-03-02T12:14:20","date_gmt":"2023-03-02T12:14:20","guid":{"rendered":"https:\/\/tirinha.com\/400-obras-que-cobrem-7-000-anos-da-natureza-na-arte\/"},"modified":"2023-03-02T12:14:20","modified_gmt":"2023-03-02T12:14:20","slug":"%e0%a4%95%e0%a4%b2%e0%a4%be-%e0%a4%ae%e0%a5%87%e0%a4%82-%e0%a4%aa%e0%a5%8d%e0%a4%b0%e0%a4%95%e0%a5%83%e0%a4%a4%e0%a4%bf-%e0%a4%95%e0%a5%87-7000-%e0%a4%b5%e0%a4%b0%e0%a5%8d%e0%a4%b7%e0%a5%8b%e0%a4%82","status":"publish","type":"post","link":"https:\/\/tirinha.com\/hi\/686\/400-obras-que-cobrem-7-000-anos-da-natureza-na-arte\/","title":{"rendered":"\u0915\u0932\u093e \u092e\u0947\u0902 \u092a\u094d\u0930\u0915\u0943\u0924\u093f \u0915\u0947 7,000 \u0935\u0930\u094d\u0937\u094b\u0902 \u0915\u094b \u0915\u0935\u0930 \u0915\u0930\u0928\u0947 \u0935\u093e\u0932\u0940 400 \u0915\u0943\u0924\u093f\u092f\u093e\u0901"},"content":{"rendered":"<p> [ad_1]<br \/>\n<\/p>\n<div id=\"article-body-content\" data-action=\"toggle\" data-status=\"on\">\n<p id=\"paragraph_1\">\u201cMeu desejo \u00e9 ficar sempre assim, morando tranquilamente em um cantinho da natureza.  Sigo a natureza sem poder apreend\u00ea-la;  talvez eu deva \u00e0s flores ter me tornado pintor\u201d, disse Claude Monet, o grande mestre da pintura impressionista, para quem a natureza se tornou sua grande refer\u00eancia, e cuja obra est\u00e1 presente em uma exposi\u00e7\u00e3o in\u00e9dita intitulada <strong><em>Vegetal &#8211; A escola da beleza<\/em><\/strong>que acaba de estrear no<strong> Belas-Artes de Paris<\/strong>sob os ausp\u00edcios da Chaumet Jewellery House.<\/p>\n<p id=\"paragraph_2\">A espl\u00eandida e ambiciosa exposi\u00e7\u00e3o, que pode ser vista at\u00e9 4 de setembro, tem curadoria do bot\u00e2nico Marc Jeanson, ex-diretor do Herb\u00e1rio do Museu Nacional de Hist\u00f3ria Natural de Paris e atual diretor bot\u00e2nico do Jardim Majorelle de Marrakech.  \u201cA exposi\u00e7\u00e3o nasceu da necessidade de demonstrar a extraordin\u00e1ria beleza das plantas em um mundo que atualmente n\u00e3o para para olh\u00e1-las\u201d, explica Jeanson. \u201cEla explora a natureza como fonte de inspira\u00e7\u00e3o e <strong>celebra a beleza absolutamente extraordin\u00e1ria e atemporal das plantas<\/strong>sua infinidade de formas, suas texturas e cores cruzando diferentes vis\u00f5es, \u00e9pocas e m\u00eddias, e convidando o visitante a olhar a natureza pelo prisma universal da arte\u201d.<\/p>\n<p id=\"paragraph_3\">E acrescenta: \u201ca beleza \u00e9 universal e a exposi\u00e7\u00e3o pretende mostrar a import\u00e2ncia que os seres vivos e as plantas tiveram na forma\u00e7\u00e3o dos artistas, embora esta tradi\u00e7\u00e3o esteja a perder-se\u201d.  a exposi\u00e7\u00e3o \u00e9 <strong>uma jornada extraordin\u00e1ria de nada menos que 7.000 anos de arte e ci\u00eancia atrav\u00e9s de 400 obras<\/strong> chaves de artistas e cientistas, relacionadas atrav\u00e9s do di\u00e1logo entre pintura, escultura, t\u00eaxteis, fotografia, mobili\u00e1rio e uma centena de objetos de joalharia Chaumet.<\/p>\n<p id=\"paragraph_4\">\u201c<strong>\u00c9 uma imers\u00e3o no bot\u00e2nico que justap\u00f5e a criatividade primitiva e contempor\u00e2nea.<\/strong>diz Marc Jeanson.  \u201cUma das obras mais antigas \u00e9 a das flores de nen\u00fafar extra\u00eddas da m\u00famia de Rams\u00e9s II, que s\u00e3o as plantas secas mais antigas do mundo, datadas de cerca de 3.500 anos.  No entanto, o objeto mais antigo \u00e9 um f\u00f3ssil de samambaia que data de cerca de 300 milh\u00f5es de anos atr\u00e1s.  Isso permite ancorar o tempo da exposi\u00e7\u00e3o na origem da vida, e mostrar ao p\u00fablico o tempo de cria\u00e7\u00e3o da flora atual, bem como dos metais, pedras e elementos que comp\u00f5em as joias\u201d.  A exposi\u00e7\u00e3o chega at\u00e9 o presente com obras de cerca de trinta artistas contempor\u00e2neos, como Anselm Kiefer, e cria\u00e7\u00f5es especiais para a exposi\u00e7\u00e3o de Patrick Blanc e Zimoun.<\/p>\n<div class=\"article-media \" itemscope=\"\" itemtype=\"http:\/\/schema.org\/ImageObject\">\n<p><img loading=\"lazy\" decoding=\"async\" alt=\"Vis\u00e3o da exposi\u00e7\u00e3o\" data-imgm=\"true\" height=\"180\" loading=\"lazy\" sizes=\"auto, (max-width: 479px) 100vw, (max-width: 1023px) 80vw, 40vw\" src=\"https:\/\/s1.eestatic.com\/2022\/07\/01\/actualidad\/684442301_225515744_1024x576.jpg\" srcset=\"https:\/\/s1.eestatic.com\/2022\/07\/01\/actualidad\/684442301_225515747_320x180.jpg 320w, https:\/\/s1.eestatic.com\/2022\/07\/01\/actualidad\/684442301_225515746_640x360.jpg 640w, https:\/\/s1.eestatic.com\/2022\/07\/01\/actualidad\/684442301_225515745_864x486.jpg 864w, https:\/\/s1.eestatic.com\/2022\/07\/01\/actualidad\/684442301_225515744_1024x576.jpg 1024w, https:\/\/s1.eestatic.com\/2022\/07\/01\/actualidad\/684442301_225515743_1706x960.jpg 1706w\" width=\"320\"\/><\/p><\/div>\n<p id=\"paragraph_5\">\u201cDesde o in\u00edcio recebemos rea\u00e7\u00f5es entusi\u00e1sticas \u00e0 ideia da exposi\u00e7\u00e3o\u201d, conta o curador.  &#8220;Por isso, com muita generosidade e confian\u00e7a, obtivemos <strong>empr\u00e9stimos excepcionais de mais de 70 museus, funda\u00e7\u00f5es, galerias e colecionadores particulares<\/strong>, franceses e estrangeiros, estudos infinitamente precisos do mundo vegetal\u201d.  Para citar alguns, o Museu Nacional de Hist\u00f3ria Natural, os museus Orsay e Louvre, o Institut de France, o Victoria and Albert Museum, o Pistoia Musei, o Nancy School Museum, o Royal Botanical Gardens em Kew, o Kunsthalle em Hamburgo, ou a Albion Art Collection em T\u00f3quio.<\/p>\n<p id=\"paragraph_6\">Algumas das obras mais extraordin\u00e1rias s\u00e3o as<em> Primavera<\/em> e ele<em> Ver\u00e3o<\/em> por Giuseppe Arcimboldo do Museu do Louvre, <em>l\u00edrios brancos<\/em> por Henri Fantin-Latour do Victoria &#038; Albert Museum, <em>Almofadas de l\u00edrio<\/em> e<em> l\u00edrios<\/em> por Claude Monet, <em>Cadeiras pintadas com motivos florais<\/em> por \u00c9mile Galle, <em>amores-perfeitos (flores)<\/em> pinturas de Eliot Hodgkin, um vestido de Christian Dior bordado com l\u00edrios do vale, os narcisos que florescem no corpo de um vaso Daum ou os cravos de Bartolomeo Bimbi, aluno de Lorenzo Lippi, ativo na corte dos M\u00e9dici.<\/p>\n<p id=\"paragraph_7\">Junto com essas obras de arte, <strong>uma infinidade de cria\u00e7\u00f5es de joias de cole\u00e7\u00f5es particulares<\/strong> real\u00e7am a singularidade da amostra, como: a tiara Bedford, uma pulseira de nen\u00fafar, broches galo e rei, <em>bandeau<\/em>&#8211; tiara de folha de carvalho, <em>parar<\/em> andorinha, tiara de cravo ou o magn\u00edfico broche Rainha Hort\u00eansia.  Todas estas pe\u00e7as excepcionais dialogam com outras obras inesperadas, como as fotografias de jacintos de Dora Maar, os pistilos de tulipas de Brassa\u00ef ou as fotografias de pe\u00f3nias de Robert Mapplethorpe;  ou com outros igualmente surpreendentes, como os estudos de cardos de Eug\u00e8ne Delacroix, os esbo\u00e7os de hera de Le Corbusier, a pintura de l\u00edrios de Otto Dix ou as flores de Gustave Courbet.<\/p>\n<h3 class=\"content__summary-title\">Chaumet, o joalheiro naturalista<\/h3>\n<p id=\"paragraph_8\">A Chaumet House, associada \u00e0 Beaux Arts por uma d\u00e9cada, foi a iniciadora do projeto.<strong> Chaumet foi fundada em 1780 por Marie-\u00c9tienne Nitot<\/strong>, que se descrevia como um \u201cjoalheiro naturalista\u201d.  Na verdade, as formas art\u00edsticas de suas joias incorporam sua vis\u00e3o bot\u00e2nica.  Possui um dos arquivos mais importantes da hist\u00f3ria da joalheria na Europa, que inclui tamb\u00e9m desenhos e fotografias.<\/p>\n<p id=\"paragraph_9\">\u201cChaumet\u201d, explica o curador, \u201c<strong>\u00e9 um joalheiro cujas fontes de inspira\u00e7\u00e3o v\u00e3o muito al\u00e9m do registro da simbologia floral<\/strong> como as rosas ou as cl\u00e1ssicas flores da joalharia, como tamb\u00e9m integra algas, cereais, trigo, \u00e1rvores, fetos, cardos, louros, umbel\u00edferas&#8230; oferecendo um amplo panorama\u201d.  Nitot foi nomeado joalheiro oficial do imp\u00e9rio e de Napole\u00e3o, e a paix\u00e3o de sua esposa Josephine por plantas e p\u00e1ssaros influenciou todo o gosto de uma era da joalheria no s\u00e9culo XIX.<\/p>\n<div class=\"article-media \" itemscope=\"\" itemtype=\"http:\/\/schema.org\/ImageObject\">\n<p><img loading=\"lazy\" decoding=\"async\" alt=\"Joias Chaumet na exposi\u00e7\u00e3o\" data-imgm=\"true\" height=\"180\" loading=\"lazy\" sizes=\"auto, (max-width: 479px) 100vw, (max-width: 1023px) 80vw, 40vw\" src=\"https:\/\/s1.eestatic.com\/2022\/07\/01\/actualidad\/684442303_225515802_1024x576.jpg\" srcset=\"https:\/\/s1.eestatic.com\/2022\/07\/01\/actualidad\/684442303_225515805_320x180.jpg 320w, https:\/\/s1.eestatic.com\/2022\/07\/01\/actualidad\/684442303_225515804_640x360.jpg 640w, https:\/\/s1.eestatic.com\/2022\/07\/01\/actualidad\/684442303_225515803_864x486.jpg 864w, https:\/\/s1.eestatic.com\/2022\/07\/01\/actualidad\/684442303_225515802_1024x576.jpg 1024w, https:\/\/s1.eestatic.com\/2022\/07\/01\/actualidad\/684442303_225515801_1706x960.jpg 1706w\" width=\"320\"\/><\/p>\n<div class=\"article-media__caption\">\n<p>\n                    <span class=\"article-media__caption-description\"><\/p>\n<p>                                    Joias Chaumet na exposi\u00e7\u00e3o<br \/>\n                            <\/span><\/p>\n<\/div><\/div>\n<p id=\"paragraph_10\">Na exposi\u00e7\u00e3o, tiaras de Marie-\u00c9tienne Nitot convivem com uma paisagem de campo de Raoul Dufy e uma jaqueta bordada com espigas de milho de Yves Saint Laurent, tudo embalado por uma escultura sonora especialmente composta por Zimoun.  Outro exemplo de di\u00e1logo \u00fanico na mostra s\u00e3o os braceletes em forma de l\u00edrio de Joseph Chaumet (diretor vision\u00e1rio que deu nome \u00e0 joalheria em 1907) com a pintura de um l\u00edrio de Monet.  Al\u00e9m disso, tr\u00eas projetos de joalheria de espartilho (bojo) da d\u00e9cada de 1890 dialogam com as fotografias <em>rabo de gato<\/em> por Robert Mapplethorpe.<\/p>\n<p id=\"paragraph_11\">Tudo na exposi\u00e7\u00e3o \u00e9 t\u00e3o surpreendente quanto a pr\u00f3pria natureza, inclusive o cen\u00e1rio em que a exposi\u00e7\u00e3o foi instalada. <strong>Marc Jeanson concebeu o percurso da exposi\u00e7\u00e3o do ponto de vista de um bot\u00e2nico<\/strong>como um herb\u00e1rio constitu\u00eddo pelas esp\u00e9cies presentes nas cria\u00e7\u00f5es de Chaumet, como um passeio por paisagens, desde a floresta e a orla mar\u00edtima at\u00e9 \u00e0 lagoa e ao campo de trigo.<\/p>\n<h3 class=\"content__summary-title\">Passeie junto ao mar, ao jardim, ao bosque&#8230;<\/h3>\n<p id=\"paragraph_12\">Para iniciar a \u201cviagem imersiva na natureza\u201d da exposi\u00e7\u00e3o, o visitante \u00e9 confrontado com um desenho do fresco parietal de Andr\u00e9 Vila feito nas grutas rochosas de Oued Djerat (Arg\u00e9lia).  A exposi\u00e7\u00e3o articula-se em n\u00facleos tem\u00e1ticos: o mar, as flores, o jardim ornamental, a mata, a orla, o canavial, o trigal&#8230;<\/p>\n<p id=\"paragraph_13\">\u201cIsso permite que o visitante caminhe livremente por sucessivas paisagens, indo do tra\u00e7ado de uma pintura rupestre de quase 5.000 anos a uma floresta de papel\u00e3o da artista contempor\u00e2nea Eva Jospin\u201d, explica o curador da exposi\u00e7\u00e3o.  \u201c<strong>Cada se\u00e7\u00e3o \u00e9 anunciada por uma pe\u00e7a que apresenta ao p\u00fablico o universo em que est\u00e1 entrando.<\/strong>\u00e0s vezes uma obra-chave, outras menos conhecida\u201d.<\/p>\n<p id=\"paragraph_14\">Ent\u00e3o, <em>l\u00edrios<\/em> de Monet est\u00e3o obviamente presentes, mas tamb\u00e9m <em>os l\u00edrios<\/em>, menos esperado.  O mesmo com Le Corbusier, de quem apresentam estudos surpreendentes de brotos e folhas.  As duas pinturas de Giuseppe Arcimboldo,<em> Primavera<\/em> e <em>Ver\u00e3o<\/em> S\u00e3o as \u00fanicas obras da mostra com representa\u00e7\u00e3o humana.  fechar <em>A mesa do colar de p\u00e9rolas,<\/em> Presenteado a Louis XIV pelo cardeal Barberini, um testemunho espetacular da idade de ouro do mobili\u00e1rio florentino em marchetaria de pedra dura.  Nesta mesa, que ser\u00e1 restaurada por Chaumet, l\u00edrios, narcisos, trepadeiras ou jacintos s\u00e3o reunidos e ligados entre si, servindo de met\u00e1fora para a nossa vis\u00e3o atual dos seres vivos e servindo de espelho para a tape\u00e7aria. <em>millefleurs<\/em> que est\u00e1 na frente dela.<\/p>\n<h3 class=\"content__summary-title\">Josefina Bonaparte: reabilitar o papel da mulher<\/h3>\n<p id=\"paragraph_15\">A multiplicidade de pontos de vista contidos na exposi\u00e7\u00e3o convida tamb\u00e9m \u00e0 (re)descoberta e reabilita\u00e7\u00e3o de grandes figuras femininas da bot\u00e2nica ao longo da hist\u00f3ria.  Entre eles, a imperatriz Jos\u00e9phine ocupa um lugar especial.  Cliente fiel da Casa de Chaumet desde 1805<strong>a imperatriz era apaixonada por ci\u00eancias naturais<\/strong>a ponto de ser reconhecida por suas contribui\u00e7\u00f5es inovadoras \u00e0 bot\u00e2nica e \u00e0 horticultura.<\/p>\n<p id=\"paragraph_16\">Mecenas, ajudou a firmar a reputa\u00e7\u00e3o de Pierre-Joseph Redout\u00e9, o artista conhecido como o <em>Rafael das flores<\/em>, como atestam as suas representa\u00e7\u00f5es de rosas, l\u00edrios e papoulas que se apresentam na exposi\u00e7\u00e3o.  \u201c<strong>N\u00e3o \u00e9 um gesto feminista, mas um reflexo da import\u00e2ncia hist\u00f3rica que as mulheres tiveram<\/strong> no estudo e representa\u00e7\u00e3o das plantas\u201d, esclarece Marc Jeanson. \u201c\u00c9 fascinante! Muito diferente do que acontece no campo da zoologia ou da mineralogia\u201d.<\/p>\n<div class=\"article-media \" itemscope=\"\" itemtype=\"http:\/\/schema.org\/ImageObject\">\n<p><img loading=\"lazy\" decoding=\"async\" alt=\"Detalhe de 'Rosa Tempestuosa', de Pierre-Joseph Redoute e Claude Antoine Thory.  Foto: Museu de Belas Artes de Paris\" data-imgm=\"true\" height=\"180\" loading=\"lazy\" sizes=\"auto, (max-width: 479px) 100vw, (max-width: 1023px) 80vw, 40vw\" src=\"https:\/\/s1.eestatic.com\/2022\/07\/01\/actualidad\/684442308_225515963_1024x576.jpg\" srcset=\"https:\/\/s1.eestatic.com\/2022\/07\/01\/actualidad\/684442308_225515994_320x180.jpg 320w, https:\/\/s1.eestatic.com\/2022\/07\/01\/actualidad\/684442308_225515993_640x360.jpg 640w, https:\/\/s1.eestatic.com\/2022\/07\/01\/actualidad\/684442308_225515992_864x486.jpg 864w, https:\/\/s1.eestatic.com\/2022\/07\/01\/actualidad\/684442308_225515991_1024x576.jpg 1024w, https:\/\/s1.eestatic.com\/2022\/07\/01\/actualidad\/684442308_225515990_1706x960.jpg 1706w\" width=\"320\"\/><\/p>\n<div class=\"article-media__caption\">\n<p>\n                    <span class=\"article-media__caption-description\"><\/p>\n<p>                                    Detalhe de &#8216;Rosa Tempestuosa&#8217;, de Pierre-Joseph Redoute e Claude Antoine Thory.  Foto: Museu de Belas Artes de Paris<br \/>\n                            <\/span><\/p>\n<\/div><\/div>\n<p id=\"paragraph_17\">Assim, da floresta de Eva Jospin que acolhe os visitantes com a m\u00fasica especialmente concebida para o evento por Laurence Equilbey \/ Insula Orchestra, as mulheres exercem uma presen\u00e7a poderosa na exposi\u00e7\u00e3o: cachos de uva de S\u00e9raphine de Senlis, algas de Yvonne Jean-Ha, tulipas de Barbara Regina Dietzsch e Berthe Morisot, l\u00edrios de Laure Albin-Guillot, cravos das irm\u00e3s Marthe e Juliette Vesque, sem esquecer um bronze de Sarah Bernhardt em di\u00e1logo com plantas de algas de Anna Atki&#8230;<\/p>\n<p id=\"paragraph_18\">Em certos momentos da hist\u00f3ria, como ocorreu na \u00e9poca do imperador Napole\u00e3o e Josefina, as grandes expedi\u00e7\u00f5es naturalistas e, portanto, a natureza exerceram um verdadeiro fasc\u00ednio.  \u201cEnt\u00e3o\u201d, observa Jeanson, \u201celes sabiam como olhar para ela, <strong>perceberam sua beleza e cuidaram dela como n\u00e3o sabemos mais fazer hoje<\/strong>;  ali\u00e1s, outro objetivo da exposi\u00e7\u00e3o \u00e9 que o visitante possa, atrav\u00e9s do olhar dos artistas, questionar seus conhecimentos sobre as plantas, e possa compreend\u00ea-los\u201d.<\/p>\n<p id=\"paragraph_19\">A natureza \u00e9 uma quest\u00e3o chave no cora\u00e7\u00e3o do nosso tempo, pois o nosso mundo est\u00e1 a ser moldado por um novo despertar para o meio ambiente, mas, paradoxalmente, nunca sofremos tanto com este enfraquecimento do mundo vivo, dos sistemas naturais e do desaparecimento alarmante de esp\u00e9cies vivas.<\/p>\n<p id=\"paragraph_20\">Marc Jeanson, que dedicou sua vida ao estudo da natureza, conclui: \u201ca natureza \u00e9 a for\u00e7a criativa mais antiga, mas tamb\u00e9m a mais incr\u00edvel e poderosa.  Preservar os vivos \u00e9 tamb\u00e9m preservar a beleza do mundo.  A beleza \u00e9 uma das experi\u00eancias mais poderosas para se relacionar com os seres, e <strong>a natureza nos diz: devemos levar a s\u00e9rio a beleza do mundo<\/strong>.  Cada flor que nos parece bela \u00e9 o eco de seres que nos precederam nesta terra.<\/p>\n<h3 class=\"follow-topics-title\"><span class=\"follow-topics-title__icon\"\/>Siga os t\u00f3picos que lhe interessam<\/h3>\n<\/p><\/div>\n","protected":false},"excerpt":{"rendered":"<p>[ad_1] \u201cMeu desejo \u00e9 ficar sempre assim, morando tranquilamente em um cantinho da natureza. Sigo a natureza sem poder apreend\u00ea-la; &hellip; <\/p>\n","protected":false},"author":1,"featured_media":687,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"fifu_image_url":"https:\/\/s1.eestatic.com\/2022\/07\/01\/el-cultural\/arte\/arte_internacional\/684442305_225529034_600x315.jpg","fifu_image_alt":"","footnotes":""},"categories":[34],"tags":[],"class_list":["post-686","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-arte","latest_post"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>400 obras que cobrem 7.000 anos da natureza na arte - Tirinha.com<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/tirinha.com\/hi\/686\/\u0915\u0932\u093e-\u092e\u0947\u0902-\u092a\u094d\u0930\u0915\u0943\u0924\u093f-\u0915\u0947-7000-\u0935\u0930\u094d\u0937\u094b\u0902\/\" \/>\n<meta property=\"og:locale\" content=\"hi_IN\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"400 obras que cobrem 7.000 anos da natureza na arte - Tirinha.com\" \/>\n<meta property=\"og:description\" content=\"[ad_1] \u201cMeu desejo \u00e9 ficar sempre assim, morando tranquilamente em um cantinho da natureza. Sigo a natureza sem poder apreend\u00ea-la; &hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/tirinha.com\/hi\/686\/\u0915\u0932\u093e-\u092e\u0947\u0902-\u092a\u094d\u0930\u0915\u0943\u0924\u093f-\u0915\u0947-7000-\u0935\u0930\u094d\u0937\u094b\u0902\/\" \/>\n<meta property=\"og:site_name\" content=\"Tirinha.com\" \/>\n<meta property=\"article:published_time\" content=\"2023-03-02T12:14:20+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/s1.eestatic.com\/2022\/07\/01\/el-cultural\/arte\/arte_internacional\/684442305_225529034_600x315.jpg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/s1.eestatic.com\/2022\/07\/01\/el-cultural\/arte\/arte_internacional\/684442305_225529034_600x315.jpg\" \/>\n<meta name=\"twitter:label1\" content=\"\u0926\u094d\u0935\u093e\u0930\u093e \u0932\u093f\u0916\u093f\u0924\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"\u0905\u0928\u0941\u092e\u093e\u0928\u093f\u0924 \u092a\u0922\u093c\u0928\u0947 \u0915\u093e \u0938\u092e\u092f\" \/>\n\t<meta name=\"twitter:data2\" content=\"9 \u092e\u093f\u0928\u091f\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/tirinha.com\\\/686\\\/400-obras-que-cobrem-7-000-anos-da-natureza-na-arte\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/tirinha.com\\\/686\\\/400-obras-que-cobrem-7-000-anos-da-natureza-na-arte\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/tirinha.com\\\/#\\\/schema\\\/person\\\/e22bdfbe17e0461f7e927e6a1208d4d9\"},\"headline\":\"400 obras que cobrem 7.000 anos da natureza na arte\",\"datePublished\":\"2023-03-02T12:14:20+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/tirinha.com\\\/686\\\/400-obras-que-cobrem-7-000-anos-da-natureza-na-arte\\\/\"},\"wordCount\":1810,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/tirinha.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/tirinha.com\\\/686\\\/400-obras-que-cobrem-7-000-anos-da-natureza-na-arte\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/s1.eestatic.com\\\/2022\\\/07\\\/01\\\/el-cultural\\\/arte\\\/arte_internacional\\\/684442305_225529034_600x315.jpg\",\"articleSection\":[\"Arte\"],\"inLanguage\":\"hi-IN\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/tirinha.com\\\/686\\\/400-obras-que-cobrem-7-000-anos-da-natureza-na-arte\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/tirinha.com\\\/686\\\/400-obras-que-cobrem-7-000-anos-da-natureza-na-arte\\\/\",\"url\":\"https:\\\/\\\/tirinha.com\\\/686\\\/400-obras-que-cobrem-7-000-anos-da-natureza-na-arte\\\/\",\"name\":\"400 obras que cobrem 7.000 anos da natureza na arte - Tirinha.com\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/tirinha.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/tirinha.com\\\/686\\\/400-obras-que-cobrem-7-000-anos-da-natureza-na-arte\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/tirinha.com\\\/686\\\/400-obras-que-cobrem-7-000-anos-da-natureza-na-arte\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/s1.eestatic.com\\\/2022\\\/07\\\/01\\\/el-cultural\\\/arte\\\/arte_internacional\\\/684442305_225529034_600x315.jpg\",\"datePublished\":\"2023-03-02T12:14:20+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/tirinha.com\\\/686\\\/400-obras-que-cobrem-7-000-anos-da-natureza-na-arte\\\/#breadcrumb\"},\"inLanguage\":\"hi-IN\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/tirinha.com\\\/686\\\/400-obras-que-cobrem-7-000-anos-da-natureza-na-arte\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"hi-IN\",\"@id\":\"https:\\\/\\\/tirinha.com\\\/686\\\/400-obras-que-cobrem-7-000-anos-da-natureza-na-arte\\\/#primaryimage\",\"url\":\"https:\\\/\\\/s1.eestatic.com\\\/2022\\\/07\\\/01\\\/el-cultural\\\/arte\\\/arte_internacional\\\/684442305_225529034_600x315.jpg\",\"contentUrl\":\"https:\\\/\\\/s1.eestatic.com\\\/2022\\\/07\\\/01\\\/el-cultural\\\/arte\\\/arte_internacional\\\/684442305_225529034_600x315.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/tirinha.com\\\/686\\\/400-obras-que-cobrem-7-000-anos-da-natureza-na-arte\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/tirinha.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"400 obras que cobrem 7.000 anos da natureza na arte\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/tirinha.com\\\/#website\",\"url\":\"https:\\\/\\\/tirinha.com\\\/\",\"name\":\"Tirinha.com\",\"description\":\"Arte e livros resenhas\",\"publisher\":{\"@id\":\"https:\\\/\\\/tirinha.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/tirinha.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"hi-IN\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/tirinha.com\\\/#organization\",\"name\":\"Tirinha.com\",\"url\":\"https:\\\/\\\/tirinha.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"hi-IN\",\"@id\":\"https:\\\/\\\/tirinha.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/tirinha.com\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/cropped-Logo-Tirinha.webp\",\"contentUrl\":\"https:\\\/\\\/tirinha.com\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/cropped-Logo-Tirinha.webp\",\"width\":512,\"height\":512,\"caption\":\"Tirinha.com\"},\"image\":{\"@id\":\"https:\\\/\\\/tirinha.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/tirinha.com\\\/#\\\/schema\\\/person\\\/e22bdfbe17e0461f7e927e6a1208d4d9\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"hi-IN\",\"@id\":\"https:\\\/\\\/tirinha.com\\\/wp-content\\\/litespeed\\\/avatar\\\/d0068f7931cc87d7274eb0c3db1deb4b.jpg?ver=1778039150\",\"url\":\"https:\\\/\\\/tirinha.com\\\/wp-content\\\/litespeed\\\/avatar\\\/d0068f7931cc87d7274eb0c3db1deb4b.jpg?ver=1778039150\",\"contentUrl\":\"https:\\\/\\\/tirinha.com\\\/wp-content\\\/litespeed\\\/avatar\\\/d0068f7931cc87d7274eb0c3db1deb4b.jpg?ver=1778039150\",\"caption\":\"admin\"},\"sameAs\":[\"https:\\\/\\\/tirinha.com\"],\"url\":\"https:\\\/\\\/tirinha.com\\\/hi\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u0915\u0932\u093e \u092e\u0947\u0902 \u092a\u094d\u0930\u0915\u0943\u0924\u093f \u0915\u0947 7,000 \u0935\u0930\u094d\u0937\u094b\u0902 \u0915\u094b \u0926\u0930\u094d\u0936\u093e\u0928\u0947 \u0935\u093e\u0932\u0940 400 \u0915\u0943\u0924\u093f\u092f\u093e\u0901 - Tirinha.com","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/tirinha.com\/hi\/686\/\u0915\u0932\u093e-\u092e\u0947\u0902-\u092a\u094d\u0930\u0915\u0943\u0924\u093f-\u0915\u0947-7000-\u0935\u0930\u094d\u0937\u094b\u0902\/","og_locale":"hi_IN","og_type":"article","og_title":"400 obras que cobrem 7.000 anos da natureza na arte - Tirinha.com","og_description":"[ad_1] \u201cMeu desejo \u00e9 ficar sempre assim, morando tranquilamente em um cantinho da natureza. Sigo a natureza sem poder apreend\u00ea-la; &hellip;","og_url":"https:\/\/tirinha.com\/hi\/686\/\u0915\u0932\u093e-\u092e\u0947\u0902-\u092a\u094d\u0930\u0915\u0943\u0924\u093f-\u0915\u0947-7000-\u0935\u0930\u094d\u0937\u094b\u0902\/","og_site_name":"Tirinha.com","article_published_time":"2023-03-02T12:14:20+00:00","og_image":[{"url":"https:\/\/s1.eestatic.com\/2022\/07\/01\/el-cultural\/arte\/arte_internacional\/684442305_225529034_600x315.jpg","type":"","width":"","height":""}],"author":"admin","twitter_card":"summary_large_image","twitter_image":"https:\/\/s1.eestatic.com\/2022\/07\/01\/el-cultural\/arte\/arte_internacional\/684442305_225529034_600x315.jpg","twitter_misc":{"\u0926\u094d\u0935\u093e\u0930\u093e \u0932\u093f\u0916\u093f\u0924":"admin","\u0905\u0928\u0941\u092e\u093e\u0928\u093f\u0924 \u092a\u0922\u093c\u0928\u0947 \u0915\u093e \u0938\u092e\u092f":"9 \u092e\u093f\u0928\u091f"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/tirinha.com\/686\/400-obras-que-cobrem-7-000-anos-da-natureza-na-arte\/#article","isPartOf":{"@id":"https:\/\/tirinha.com\/686\/400-obras-que-cobrem-7-000-anos-da-natureza-na-arte\/"},"author":{"name":"admin","@id":"https:\/\/tirinha.com\/#\/schema\/person\/e22bdfbe17e0461f7e927e6a1208d4d9"},"headline":"400 obras que cobrem 7.000 anos da natureza na arte","datePublished":"2023-03-02T12:14:20+00:00","mainEntityOfPage":{"@id":"https:\/\/tirinha.com\/686\/400-obras-que-cobrem-7-000-anos-da-natureza-na-arte\/"},"wordCount":1810,"commentCount":0,"publisher":{"@id":"https:\/\/tirinha.com\/#organization"},"image":{"@id":"https:\/\/tirinha.com\/686\/400-obras-que-cobrem-7-000-anos-da-natureza-na-arte\/#primaryimage"},"thumbnailUrl":"https:\/\/s1.eestatic.com\/2022\/07\/01\/el-cultural\/arte\/arte_internacional\/684442305_225529034_600x315.jpg","articleSection":["Arte"],"inLanguage":"hi-IN","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/tirinha.com\/686\/400-obras-que-cobrem-7-000-anos-da-natureza-na-arte\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/tirinha.com\/686\/400-obras-que-cobrem-7-000-anos-da-natureza-na-arte\/","url":"https:\/\/tirinha.com\/686\/400-obras-que-cobrem-7-000-anos-da-natureza-na-arte\/","name":"\u0915\u0932\u093e \u092e\u0947\u0902 \u092a\u094d\u0930\u0915\u0943\u0924\u093f \u0915\u0947 7,000 \u0935\u0930\u094d\u0937\u094b\u0902 \u0915\u094b \u0926\u0930\u094d\u0936\u093e\u0928\u0947 \u0935\u093e\u0932\u0940 400 \u0915\u0943\u0924\u093f\u092f\u093e\u0901 - Tirinha.com","isPartOf":{"@id":"https:\/\/tirinha.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/tirinha.com\/686\/400-obras-que-cobrem-7-000-anos-da-natureza-na-arte\/#primaryimage"},"image":{"@id":"https:\/\/tirinha.com\/686\/400-obras-que-cobrem-7-000-anos-da-natureza-na-arte\/#primaryimage"},"thumbnailUrl":"https:\/\/s1.eestatic.com\/2022\/07\/01\/el-cultural\/arte\/arte_internacional\/684442305_225529034_600x315.jpg","datePublished":"2023-03-02T12:14:20+00:00","breadcrumb":{"@id":"https:\/\/tirinha.com\/686\/400-obras-que-cobrem-7-000-anos-da-natureza-na-arte\/#breadcrumb"},"inLanguage":"hi-IN","potentialAction":[{"@type":"ReadAction","target":["https:\/\/tirinha.com\/686\/400-obras-que-cobrem-7-000-anos-da-natureza-na-arte\/"]}]},{"@type":"ImageObject","inLanguage":"hi-IN","@id":"https:\/\/tirinha.com\/686\/400-obras-que-cobrem-7-000-anos-da-natureza-na-arte\/#primaryimage","url":"https:\/\/s1.eestatic.com\/2022\/07\/01\/el-cultural\/arte\/arte_internacional\/684442305_225529034_600x315.jpg","contentUrl":"https:\/\/s1.eestatic.com\/2022\/07\/01\/el-cultural\/arte\/arte_internacional\/684442305_225529034_600x315.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/tirinha.com\/686\/400-obras-que-cobrem-7-000-anos-da-natureza-na-arte\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/tirinha.com\/"},{"@type":"ListItem","position":2,"name":"400 obras que cobrem 7.000 anos da natureza na arte"}]},{"@type":"WebSite","@id":"https:\/\/tirinha.com\/#website","url":"https:\/\/tirinha.com\/","name":"\u0924\u093f\u0930\u093f\u0928\u094d\u0939\u093e.\u0915\u0949\u092e","description":"\u0915\u0932\u093e \u0914\u0930 \u092a\u0941\u0938\u094d\u0924\u0915 \u0938\u092e\u0940\u0915\u094d\u0937\u093e\u090f\u0901","publisher":{"@id":"https:\/\/tirinha.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/tirinha.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"hi-IN"},{"@type":"Organization","@id":"https:\/\/tirinha.com\/#organization","name":"\u0924\u093f\u0930\u093f\u0928\u094d\u0939\u093e.\u0915\u0949\u092e","url":"https:\/\/tirinha.com\/","logo":{"@type":"ImageObject","inLanguage":"hi-IN","@id":"https:\/\/tirinha.com\/#\/schema\/logo\/image\/","url":"https:\/\/tirinha.com\/wp-content\/uploads\/2023\/08\/cropped-Logo-Tirinha.webp","contentUrl":"https:\/\/tirinha.com\/wp-content\/uploads\/2023\/08\/cropped-Logo-Tirinha.webp","width":512,"height":512,"caption":"Tirinha.com"},"image":{"@id":"https:\/\/tirinha.com\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/tirinha.com\/#\/schema\/person\/e22bdfbe17e0461f7e927e6a1208d4d9","name":"\u0935\u094d\u092f\u0935\u0938\u094d\u0925\u093e\u092a\u0915","image":{"@type":"ImageObject","inLanguage":"hi-IN","@id":"https:\/\/tirinha.com\/wp-content\/litespeed\/avatar\/d0068f7931cc87d7274eb0c3db1deb4b.jpg?ver=1778039150","url":"https:\/\/tirinha.com\/wp-content\/litespeed\/avatar\/d0068f7931cc87d7274eb0c3db1deb4b.jpg?ver=1778039150","contentUrl":"https:\/\/tirinha.com\/wp-content\/litespeed\/avatar\/d0068f7931cc87d7274eb0c3db1deb4b.jpg?ver=1778039150","caption":"admin"},"sameAs":["https:\/\/tirinha.com"],"url":"https:\/\/tirinha.com\/hi\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/tirinha.com\/hi\/wp-json\/wp\/v2\/posts\/686","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tirinha.com\/hi\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tirinha.com\/hi\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tirinha.com\/hi\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/tirinha.com\/hi\/wp-json\/wp\/v2\/comments?post=686"}],"version-history":[{"count":0,"href":"https:\/\/tirinha.com\/hi\/wp-json\/wp\/v2\/posts\/686\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tirinha.com\/hi\/wp-json\/wp\/v2\/media\/687"}],"wp:attachment":[{"href":"https:\/\/tirinha.com\/hi\/wp-json\/wp\/v2\/media?parent=686"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tirinha.com\/hi\/wp-json\/wp\/v2\/categories?post=686"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tirinha.com\/hi\/wp-json\/wp\/v2\/tags?post=686"}],"curies":[{"name":"\u0921\u092c\u094d\u0932\u094d\u092f\u0942\u092a\u0940","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}