{"id":661,"date":"2023-03-02T11:53:59","date_gmt":"2023-03-02T11:53:59","guid":{"rendered":"https:\/\/tirinha.com\/retornar-a-sua-arte-mais-reconhecida\/"},"modified":"2023-03-02T11:53:59","modified_gmt":"2023-03-02T11:53:59","slug":"revenir-a-son-art-le-plus-reconnu","status":"publish","type":"post","link":"https:\/\/tirinha.com\/fr\/661\/retornar-a-sua-arte-mais-reconhecida\/","title":{"rendered":"revenez \u00e0 votre art le plus reconnu"},"content":{"rendered":"<p> [ad_1]<br \/>\n<\/p>\n<div id=\"article-body-content\" data-action=\"toggle\" data-status=\"on\">\n<p class=\"paragraph\" id=\"paragraph_1\">n\u00f3s somos antes <strong>um retorno art\u00edstico de significado intenso<\/strong>.  Manuel Segade volta a trazer-nos a obra de <strong>Juan Munoz<\/strong> (1953-2001) quando completaria 70 anos e 22 anos ap\u00f3s sua morte prematura, com apenas 48 anos.  O primeiro passo \u00e9 a apresenta\u00e7\u00e3o de um conjunto de 21 excelentes pe\u00e7as, instala\u00e7\u00f5es escult\u00f3ricas de diversos formatos e extens\u00f5es, em um cen\u00e1rio que dialoga com as caracter\u00edsticas arquitet\u00f4nicas do edif\u00edcio que as abriga.<\/p>\n<p class=\"paragraph\" id=\"paragraph_2\">O t\u00edtulo do show <em>Tudo o que vejo vai sobreviver a mim<\/em>\u00e9 uma cita\u00e7\u00e3o da poetisa russa Anna Akhmatova que Juan Mu\u00f1oz recolheu numa das \u00faltimas notas dos seus cadernos de prepara\u00e7\u00e3o para aquela que foi a sua \u00faltima exposi\u00e7\u00e3o, na Tate Modern de Londres em 2001. O t\u00edtulo \u00e9 aqui utilizado como <strong>uma bela alus\u00e3o po\u00e9tica \u00e0 sobreviv\u00eancia das obras<\/strong>al\u00e9m da expira\u00e7\u00e3o da vida dos artistas.<\/p>\n<p class=\"paragraph\" id=\"paragraph_3\">A data\u00e7\u00e3o das pe\u00e7as \u00e9 basicamente da d\u00e9cada de 1990, embora tamb\u00e9m haja uma de 1989 e outra de 2001. Estamos na fase final da carreira criativa de Juan Mu\u00f1oz, na qual chegou a <strong>forte reconhecimento internacional<\/strong>.  O pr\u00f3ximo passo deste regresso ser\u00e1 uma outra exposi\u00e7\u00e3o, no CA2M de M\u00f3stoles, que inaugurar\u00e1 em junho, coincidindo com a data de nascimento do artista, na qual veremos o percurso das suas obras desde o in\u00edcio at\u00e9 aos anos oitenta.<\/p>\n<p class=\"paragraph\" id=\"paragraph_4\"><em>[Juan Mu\u00f1oz, dibujante o trilero]<\/em><\/p>\n<p class=\"paragraph\" id=\"paragraph_5\">Este jogo com o passar do tempo \u2013 recuperando a obra de Juan Mu\u00f1oz, o grande artista que partiu t\u00e3o cedo, em duas fases que v\u00e3o no sentido contr\u00e1rio ao de seu desenvolvimento temporal, da \u00faltima para as primeiras fases \u2013 \u00e9 <strong>um sinal alusivo sobre o qu\u00e3o vivas e radiantes as suas obras continuam a ser<\/strong>.  Todos eles s\u00e3o determinados pela intera\u00e7\u00e3o que provocam ao olhar para eles, aspecto enfatizado por Mu\u00f1oz com o uso de espelhos que refletem tanto suas esculturas quanto quem as olha, que s\u00e3o assim introduzidos na instala\u00e7\u00e3o interativa que os constitui.<\/p>\n<p class=\"paragraph\" id=\"paragraph_6\">Aqui, na galeria Alcal\u00e1 31, as pe\u00e7as remetem-nos explicitamente para esta quest\u00e3o. <em>Sara com vestido azul<\/em> [Sara con vestido azul]  (1996) e <em>alo specchio<\/em> [En el espejo]  (1997).  E isso \u00e9 o que Juan Mu\u00f1oz escreveu sobre o que podemos ver neles e como o vemos: &#8220;Meus personagens \u00e0s vezes se comportam como um espelho que n\u00e3o pode refletir. Eles est\u00e3o l\u00e1 para dizer algo sobre o seu olhar, mas n\u00e3o podem porque n\u00e3o querem t deix\u00e1-lo ver a si mesmo.&#8221;  A\u00ed estamos n\u00f3s: olhando, querendo ver tudo, e <strong>esse fluxo leva voc\u00ea a ser olhado, visto, no reflexo dos diversos<\/strong>.<\/p>\n<div class=\"article-media \" itemscope=\"\" itemtype=\"http:\/\/schema.org\/ImageObject\">\n<p><img loading=\"lazy\" decoding=\"async\" alt=\"'Loaded Car', 1998, e, ao fundo, 'Blotter Figures: Coming Towards', 1999\" data-imgm=\"true\" height=\"180\" loading=\"lazy\" sizes=\"auto, (max-width: 479px) 100vw, (max-width: 1023px) 80vw, 40vw\" src=\"https:\/\/s1.eestatic.com\/2023\/02\/22\/actualidad\/743436248_231133381_1706x960.jpg\" srcset=\"https:\/\/s1.eestatic.com\/2023\/02\/22\/actualidad\/743436248_231133385_320x180.jpg 320w, https:\/\/s1.eestatic.com\/2023\/02\/22\/actualidad\/743436248_231133384_640x360.jpg 640w, https:\/\/s1.eestatic.com\/2023\/02\/22\/actualidad\/743436248_231133383_864x486.jpg 864w, https:\/\/s1.eestatic.com\/2023\/02\/22\/actualidad\/743436248_231133382_1024x576.jpg 1024w, https:\/\/s1.eestatic.com\/2023\/02\/22\/actualidad\/743436248_231133381_1706x960.jpg 1706w\" width=\"320\"\/><\/p>\n<div class=\"article-media__caption\">\n<p>\n                    <span class=\"article-media__caption-description\"><\/p>\n<p>                                    &#8216;Loaded Car&#8217;, 1998, e, ao fundo, &#8216;Blotter Figures: Coming Towards&#8217;, 1999<br \/>\n                            <\/span><\/p>\n<\/div><\/div>\n<p class=\"paragraph\" id=\"paragraph_7\">Um problema que continua na instala\u00e7\u00e3o <em>Duas sentinelas em terreno \u00f3tico<\/em> (1990), localizadas na entrada, figuras de sombra com armas, que nos remetem ao controle de nossos olhares.  E tamb\u00e9m nas pe\u00e7as da varanda: <em>sacada<\/em> [Balc\u00f3n]  (1991) e <em>Varanda Nimes<\/em> [Balc\u00f3n de Nimes]  (1994), em ambos os casos varandas sem nada ou ningu\u00e9m sobre elas, vazias.  &#8220;N\u00e3o se mostra o vazio. Mostra-se o desejo de que ele seja preenchido. [&#8230;] N\u00e3o vejo as varandas vazias agora;  Eles falam sobre qualquer coisa, menos sobre si mesmos.  S\u00e3o imagens que j\u00e1 est\u00e3o a\u00ed, que j\u00e1 foram utilizadas\u201d, afirmou. <strong>Nosso olhar elimina o vazio&#8230;<\/strong><\/p>\n<p class=\"paragraph\" id=\"paragraph_8\">Indo e vindo no olhar, na vis\u00e3o, \u00e9 a\u00ed que se situa o n\u00facleo referencial das obras de Juan Mu\u00f1oz: <strong>nada est\u00e1 fechado no imediatismo das pe\u00e7as<\/strong>, tudo permanece aberto ao fluxo interativo que eles provocam quando nosso olhar se aproxima deles.  Al\u00e9m de provocarem o \u201cpreenchimento\u201d do vazio, os personagens nos aproximam da semelhan\u00e7a \u00e0 dist\u00e2ncia.  Na segunda metade da d\u00e9cada de 1990 isso se concretizou nas figuras caricatas de an\u00f5es, bonecos ventr\u00edloquos e &#8220;chineses&#8221;, como o pr\u00f3prio Mu\u00f1oz os identificou.<\/p>\n<blockquote class=\"content__blockquote\">\n<p class=\"blockquote__quote\">O passo seguinte neste regresso ser\u00e1 mais uma exposi\u00e7\u00e3o, no CA2M de M\u00f3stoles, que inaugura em junho, coincidindo com a data de nascimento do artista.<\/p>\n<\/blockquote>\n<p class=\"paragraph\" id=\"paragraph_9\">Relacionada com esta \u00faltima est\u00e1 a recupera\u00e7\u00e3o da en\u00e9rgica instala\u00e7\u00e3o escult\u00f3rica <em>Quadrado<\/em> (1996), que se pode rever pela primeira vez desde a sua apresenta\u00e7\u00e3o no Pal\u00e1cio de Vel\u00e1zquez del Retiro, no \u00e2mbito da exposi\u00e7\u00e3o que o Museo Reina Sof\u00eda dedicou \u00e0 \u00e9poca ao artista.  \u00c9 um conjunto de 27 figuras de tons de cinza, de &#8220;chineses&#8221; que riem.  Voc\u00ea n\u00e3o pode entrar dentro do c\u00edrculo aberto que eles formam, e assim <strong>o tema do espelho, da identidade e da diferen\u00e7a, abre-se \u00e0 medida que te aproximas<\/strong>voc\u00ea os contorna de fora e acaba percebendo os outros de si mesmo.<\/p>\n<p class=\"paragraph\" id=\"paragraph_10\">A figura pendurada pela boca no teto da sala: <em>Com a corda alla bocca<\/em> [Con la cuerda en la boca]  (1997) e as duas figuras de papel absorvente com persianas de 1999 nos falam sobre <strong>o paradoxo da representa\u00e7\u00e3o<\/strong>: n\u00e3o conseguimos entender a motiva\u00e7\u00e3o do que vemos.<\/p>\n<p class=\"paragraph\" id=\"paragraph_11\"><em>[Juan Mu\u00f1oz. Sospechar del ojo]<\/em><\/p>\n<p class=\"paragraph\" id=\"paragraph_12\">J\u00e1 estamos na fase final da jornada criativa de Juan Mu\u00f1oz.  Mas, como encerramento, \u00e9 significativo o retorno ao riso das figuras penduradas na parede em cadeiras na pe\u00e7a datada do ano de sua morte, em 2001: <em>Dois sentados na parede<\/em> [Dos sentados en el muro].  Eles riem de sua poss\u00edvel queda? <strong>A resposta permanece em aberto, como a pr\u00f3pria vida<\/strong>, antes do nosso desejo de olhar e conseguir ver para onde vamos.  Juan Mu\u00f1oz: olhando de fora, conseguindo ver em profundidade.<\/p>\n<p><span class=\"follow-topics-title__icon\"\/>Siga os t\u00f3picos que lhe interessam<\/p>\n<\/p><\/div>\n","protected":false},"excerpt":{"rendered":"<p>[ad_1] n\u00f3s somos antes um retorno art\u00edstico de significado intenso. Manuel Segade volta a trazer-nos a obra de Juan Munoz &hellip; <\/p>\n","protected":false},"author":1,"featured_media":662,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"fifu_image_url":"https:\/\/s1.eestatic.com\/2023\/02\/22\/el-cultural\/arte\/743436241_231264512_1200x630.jpg","fifu_image_alt":"","footnotes":""},"categories":[34],"tags":[],"class_list":["post-661","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-arte","latest_post"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>retornar \u00e0 sua arte mais reconhecida - Tirinha.com<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/tirinha.com\/fr\/661\/revenir-a-son-art-le-plus-reconnu\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"retornar \u00e0 sua arte mais reconhecida - Tirinha.com\" \/>\n<meta property=\"og:description\" content=\"[ad_1] n\u00f3s somos antes um retorno art\u00edstico de significado intenso. Manuel Segade volta a trazer-nos a obra de Juan Munoz &hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/tirinha.com\/fr\/661\/revenir-a-son-art-le-plus-reconnu\/\" \/>\n<meta property=\"og:site_name\" content=\"Tirinha.com\" \/>\n<meta property=\"article:published_time\" content=\"2023-03-02T11:53:59+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/s1.eestatic.com\/2023\/02\/22\/el-cultural\/arte\/743436241_231264512_1200x630.jpg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/s1.eestatic.com\/2023\/02\/22\/el-cultural\/arte\/743436241_231264512_1200x630.jpg\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/tirinha.com\\\/661\\\/retornar-a-sua-arte-mais-reconhecida\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/tirinha.com\\\/661\\\/retornar-a-sua-arte-mais-reconhecida\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/tirinha.com\\\/#\\\/schema\\\/person\\\/e22bdfbe17e0461f7e927e6a1208d4d9\"},\"headline\":\"retornar \u00e0 sua arte mais reconhecida\",\"datePublished\":\"2023-03-02T11:53:59+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/tirinha.com\\\/661\\\/retornar-a-sua-arte-mais-reconhecida\\\/\"},\"wordCount\":942,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/tirinha.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/tirinha.com\\\/661\\\/retornar-a-sua-arte-mais-reconhecida\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/s1.eestatic.com\\\/2023\\\/02\\\/22\\\/el-cultural\\\/arte\\\/743436241_231264512_1200x630.jpg\",\"articleSection\":[\"Arte\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/tirinha.com\\\/661\\\/retornar-a-sua-arte-mais-reconhecida\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/tirinha.com\\\/661\\\/retornar-a-sua-arte-mais-reconhecida\\\/\",\"url\":\"https:\\\/\\\/tirinha.com\\\/661\\\/retornar-a-sua-arte-mais-reconhecida\\\/\",\"name\":\"retornar \u00e0 sua arte mais reconhecida - Tirinha.com\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/tirinha.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/tirinha.com\\\/661\\\/retornar-a-sua-arte-mais-reconhecida\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/tirinha.com\\\/661\\\/retornar-a-sua-arte-mais-reconhecida\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/s1.eestatic.com\\\/2023\\\/02\\\/22\\\/el-cultural\\\/arte\\\/743436241_231264512_1200x630.jpg\",\"datePublished\":\"2023-03-02T11:53:59+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/tirinha.com\\\/661\\\/retornar-a-sua-arte-mais-reconhecida\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/tirinha.com\\\/661\\\/retornar-a-sua-arte-mais-reconhecida\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/tirinha.com\\\/661\\\/retornar-a-sua-arte-mais-reconhecida\\\/#primaryimage\",\"url\":\"https:\\\/\\\/s1.eestatic.com\\\/2023\\\/02\\\/22\\\/el-cultural\\\/arte\\\/743436241_231264512_1200x630.jpg\",\"contentUrl\":\"https:\\\/\\\/s1.eestatic.com\\\/2023\\\/02\\\/22\\\/el-cultural\\\/arte\\\/743436241_231264512_1200x630.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/tirinha.com\\\/661\\\/retornar-a-sua-arte-mais-reconhecida\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/tirinha.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"retornar \u00e0 sua arte mais reconhecida\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/tirinha.com\\\/#website\",\"url\":\"https:\\\/\\\/tirinha.com\\\/\",\"name\":\"Tirinha.com\",\"description\":\"Arte e livros resenhas\",\"publisher\":{\"@id\":\"https:\\\/\\\/tirinha.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/tirinha.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/tirinha.com\\\/#organization\",\"name\":\"Tirinha.com\",\"url\":\"https:\\\/\\\/tirinha.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/tirinha.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/tirinha.com\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/cropped-Logo-Tirinha.webp\",\"contentUrl\":\"https:\\\/\\\/tirinha.com\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/cropped-Logo-Tirinha.webp\",\"width\":512,\"height\":512,\"caption\":\"Tirinha.com\"},\"image\":{\"@id\":\"https:\\\/\\\/tirinha.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/tirinha.com\\\/#\\\/schema\\\/person\\\/e22bdfbe17e0461f7e927e6a1208d4d9\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/tirinha.com\\\/wp-content\\\/litespeed\\\/avatar\\\/d0068f7931cc87d7274eb0c3db1deb4b.jpg?ver=1778643959\",\"url\":\"https:\\\/\\\/tirinha.com\\\/wp-content\\\/litespeed\\\/avatar\\\/d0068f7931cc87d7274eb0c3db1deb4b.jpg?ver=1778643959\",\"contentUrl\":\"https:\\\/\\\/tirinha.com\\\/wp-content\\\/litespeed\\\/avatar\\\/d0068f7931cc87d7274eb0c3db1deb4b.jpg?ver=1778643959\",\"caption\":\"admin\"},\"sameAs\":[\"https:\\\/\\\/tirinha.com\"],\"url\":\"https:\\\/\\\/tirinha.com\\\/fr\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Il revient \u00e0 sa forme d&#039;art la plus reconnue\u00a0: Tirinha.com","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/tirinha.com\/fr\/661\/revenir-a-son-art-le-plus-reconnu\/","og_locale":"fr_FR","og_type":"article","og_title":"retornar \u00e0 sua arte mais reconhecida - Tirinha.com","og_description":"[ad_1] n\u00f3s somos antes um retorno art\u00edstico de significado intenso. Manuel Segade volta a trazer-nos a obra de Juan Munoz &hellip;","og_url":"https:\/\/tirinha.com\/fr\/661\/revenir-a-son-art-le-plus-reconnu\/","og_site_name":"Tirinha.com","article_published_time":"2023-03-02T11:53:59+00:00","og_image":[{"url":"https:\/\/s1.eestatic.com\/2023\/02\/22\/el-cultural\/arte\/743436241_231264512_1200x630.jpg","type":"","width":"","height":""}],"author":"admin","twitter_card":"summary_large_image","twitter_image":"https:\/\/s1.eestatic.com\/2023\/02\/22\/el-cultural\/arte\/743436241_231264512_1200x630.jpg","twitter_misc":{"\u00c9crit par":"admin","Dur\u00e9e de lecture estim\u00e9e":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/tirinha.com\/661\/retornar-a-sua-arte-mais-reconhecida\/#article","isPartOf":{"@id":"https:\/\/tirinha.com\/661\/retornar-a-sua-arte-mais-reconhecida\/"},"author":{"name":"admin","@id":"https:\/\/tirinha.com\/#\/schema\/person\/e22bdfbe17e0461f7e927e6a1208d4d9"},"headline":"retornar \u00e0 sua arte mais reconhecida","datePublished":"2023-03-02T11:53:59+00:00","mainEntityOfPage":{"@id":"https:\/\/tirinha.com\/661\/retornar-a-sua-arte-mais-reconhecida\/"},"wordCount":942,"commentCount":0,"publisher":{"@id":"https:\/\/tirinha.com\/#organization"},"image":{"@id":"https:\/\/tirinha.com\/661\/retornar-a-sua-arte-mais-reconhecida\/#primaryimage"},"thumbnailUrl":"https:\/\/s1.eestatic.com\/2023\/02\/22\/el-cultural\/arte\/743436241_231264512_1200x630.jpg","articleSection":["Arte"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/tirinha.com\/661\/retornar-a-sua-arte-mais-reconhecida\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/tirinha.com\/661\/retornar-a-sua-arte-mais-reconhecida\/","url":"https:\/\/tirinha.com\/661\/retornar-a-sua-arte-mais-reconhecida\/","name":"Il revient \u00e0 sa forme d&#039;art la plus reconnue\u00a0: Tirinha.com","isPartOf":{"@id":"https:\/\/tirinha.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/tirinha.com\/661\/retornar-a-sua-arte-mais-reconhecida\/#primaryimage"},"image":{"@id":"https:\/\/tirinha.com\/661\/retornar-a-sua-arte-mais-reconhecida\/#primaryimage"},"thumbnailUrl":"https:\/\/s1.eestatic.com\/2023\/02\/22\/el-cultural\/arte\/743436241_231264512_1200x630.jpg","datePublished":"2023-03-02T11:53:59+00:00","breadcrumb":{"@id":"https:\/\/tirinha.com\/661\/retornar-a-sua-arte-mais-reconhecida\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/tirinha.com\/661\/retornar-a-sua-arte-mais-reconhecida\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/tirinha.com\/661\/retornar-a-sua-arte-mais-reconhecida\/#primaryimage","url":"https:\/\/s1.eestatic.com\/2023\/02\/22\/el-cultural\/arte\/743436241_231264512_1200x630.jpg","contentUrl":"https:\/\/s1.eestatic.com\/2023\/02\/22\/el-cultural\/arte\/743436241_231264512_1200x630.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/tirinha.com\/661\/retornar-a-sua-arte-mais-reconhecida\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/tirinha.com\/"},{"@type":"ListItem","position":2,"name":"retornar \u00e0 sua arte mais reconhecida"}]},{"@type":"WebSite","@id":"https:\/\/tirinha.com\/#website","url":"https:\/\/tirinha.com\/","name":"Tirinha.com","description":"Critiques d&#039;art et de livres","publisher":{"@id":"https:\/\/tirinha.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/tirinha.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/tirinha.com\/#organization","name":"Tirinha.com","url":"https:\/\/tirinha.com\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/tirinha.com\/#\/schema\/logo\/image\/","url":"https:\/\/tirinha.com\/wp-content\/uploads\/2023\/08\/cropped-Logo-Tirinha.webp","contentUrl":"https:\/\/tirinha.com\/wp-content\/uploads\/2023\/08\/cropped-Logo-Tirinha.webp","width":512,"height":512,"caption":"Tirinha.com"},"image":{"@id":"https:\/\/tirinha.com\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/tirinha.com\/#\/schema\/person\/e22bdfbe17e0461f7e927e6a1208d4d9","name":"administrateur","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/tirinha.com\/wp-content\/litespeed\/avatar\/d0068f7931cc87d7274eb0c3db1deb4b.jpg?ver=1778643959","url":"https:\/\/tirinha.com\/wp-content\/litespeed\/avatar\/d0068f7931cc87d7274eb0c3db1deb4b.jpg?ver=1778643959","contentUrl":"https:\/\/tirinha.com\/wp-content\/litespeed\/avatar\/d0068f7931cc87d7274eb0c3db1deb4b.jpg?ver=1778643959","caption":"admin"},"sameAs":["https:\/\/tirinha.com"],"url":"https:\/\/tirinha.com\/fr\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/tirinha.com\/fr\/wp-json\/wp\/v2\/posts\/661","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tirinha.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tirinha.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tirinha.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/tirinha.com\/fr\/wp-json\/wp\/v2\/comments?post=661"}],"version-history":[{"count":0,"href":"https:\/\/tirinha.com\/fr\/wp-json\/wp\/v2\/posts\/661\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tirinha.com\/fr\/wp-json\/wp\/v2\/media\/662"}],"wp:attachment":[{"href":"https:\/\/tirinha.com\/fr\/wp-json\/wp\/v2\/media?parent=661"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tirinha.com\/fr\/wp-json\/wp\/v2\/categories?post=661"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tirinha.com\/fr\/wp-json\/wp\/v2\/tags?post=661"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}