{"id":609,"date":"2022-06-23T21:34:58","date_gmt":"2022-06-23T21:34:58","guid":{"rendered":"https:\/\/tirinha.com\/revisao-de-starr-muito-tempo-marc-ross-no-trabalho\/"},"modified":"2022-12-27T12:08:03","modified_gmt":"2022-12-27T12:08:03","slug":"muito-tempo-marc-ross-no-trabalho","status":"publish","type":"post","link":"https:\/\/tirinha.com\/es\/609\/muito-tempo-marc-ross-no-trabalho\/","title":{"rendered":"Mucho tiempo: Marc Ross en el trabajo"},"content":{"rendered":"<div id=\"post-body-8552530608944071443\">\n<div dir=\"ltr\" style=\"text-align: left;\" trbidi=\"on\">\n<table cellpadding=\"0\" cellspacing=\"0\" class=\"tr-caption-container\" style=\"float: left; margin-right: 1em; text-align: left;\">\n<tbody>\n<tr>\n<td style=\"text-align: center;\"><img fetchpriority=\"high\" decoding=\"async\" border=\"0\" height=\"265\" src=\"http:\/\/2.bp.blogspot.com\/-ige99U1PXT0\/VeRvPyB9ngI\/AAAAAAAAHOM\/YqJAGAzXGLQ\/s400\/CCAC%2B1-1.jpg\" width=\"400\"\/><\/td>\n<\/tr>\n<tr>\n<td class=\"tr-caption\" style=\"text-align: center;\"><span style=\"font-family: Arial, Helvetica, sans-serif; font-size: xx-small;\">Marcos Ross, <i>No se necesita explicaci\u00f3n<\/i> instalado en el Centro de Artes Culturales, agosto de 2015<\/span><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><span style=\"font-family: Arial, Helvetica, sans-serif;\">El Centro de Artes Culturales de Columbus parec\u00eda el interior de un joyero cuando visit\u00e9 la exposici\u00f3n de pintura de Marc Ross, que cerr\u00f3 el 29 de agosto. El espacio era perfecto para exhibir pinturas luminosas de gran escala dominadas por colores \u00fanicos. Cada uno ten\u00eda espacio para respirar y espacio para brillar, para la pintura de Ross, ambos, como organismos vivos.<\/span><br \/>\n<span style=\"font-family: Arial, Helvetica, sans-serif;\"><br \/><\/span><br \/>\n<span style=\"font-family: Arial, Helvetica, sans-serif;\">\u00bfCu\u00e1l es la diferencia entre algo vivo y algo que no lo est\u00e1? eso es un <i>Villa Sesamo<\/i> concepto, \u00bfno es as\u00ed, una distinci\u00f3n fundamental que aprendemos en nuestros primeros a\u00f1os? Las pinturas caen en la categor\u00eda de inanimados, a pesar de las met\u00e1foras que cualquier escritor de arte o visitante de una galer\u00eda podr\u00eda fabricar. <\/span><span style=\"font-family: Arial, Helvetica, sans-serif;\">Pero el trabajo de Marc Ross invita a una reconsideraci\u00f3n seria del espacio entre lo animado y lo inanimado en el arte. <\/span><br \/>\n<span style=\"font-family: Arial, Helvetica, sans-serif;\"><br \/><\/span><\/p>\n<table align=\"center\" cellpadding=\"0\" cellspacing=\"0\" class=\"tr-caption-container\" style=\"margin-left: auto; margin-right: auto; text-align: center;\">\n<tbody>\n<tr>\n<td style=\"text-align: center;\"><img decoding=\"async\" border=\"0\" height=\"478\" src=\"http:\/\/1.bp.blogspot.com\/-GzTY4g7Rfdg\/VeWN_odpIbI\/AAAAAAAAHOs\/Cmfy2WEx-j0\/s640\/Memento%2B%25231%2B.jpg\" width=\"640\"\/><\/td>\n<\/tr>\n<tr>\n<td class=\"tr-caption\" style=\"text-align: center;\"><span style=\"font-family: Arial, Helvetica, sans-serif; font-size: xx-small;\">Marcos Ross, <i>Memoria #1, <\/i>62 x 84\u201d. Acr\u00edlico, pastel, l\u00e1pices de colores.<\/span><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><span style=\"font-family: Arial, Helvetica, sans-serif;\">En la conversaci\u00f3n de la galer\u00eda que cerr\u00f3 esta muestra, <i>No se necesita explicaci\u00f3n, <\/i>el artista me confes\u00f3 que odia dar conferencias porque tiene muy poco que decir. Se sinti\u00f3 aliviado de la necesidad de hablar al hacer preguntas a su audiencia, que revelaron mucho. <\/span><br \/>\n<span style=\"font-family: Arial, Helvetica, sans-serif;\"><br \/><\/span><\/p>\n<table cellpadding=\"0\" cellspacing=\"0\" class=\"tr-caption-container\" style=\"float: left; text-align: left;\">\n<tbody>\n<tr>\n<td style=\"text-align: center;\"><img decoding=\"async\" border=\"0\" height=\"212\" src=\"http:\/\/4.bp.blogspot.com\/-HBC66TCVdMM\/VeWSMYvtFVI\/AAAAAAAAHPI\/4ImOtbf998U\/s320\/Memento%2B%25231%2BDetail.jpg\" width=\"320\"\/><\/td>\n<\/tr>\n<tr>\n<td class=\"tr-caption\" style=\"text-align: center;\"><span style=\"font-size: xx-small;\"><span style=\"font-family: Arial, Helvetica, sans-serif;\">Marcos Ross, <\/span><span style=\"font-family: Arial, Helvetica, sans-serif;\"><i>Memoria #1, <\/i>Detalle<i>.<\/i><\/span><\/span><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><span style=\"font-family: Arial, Helvetica, sans-serif;\">Lo m\u00e1s importante que nos dijo Ross es que cada una de estas obras tarda mucho en completarse, y esa finalizaci\u00f3n se marca de una forma sencilla y pr\u00e1ctica: se hace cuando ve que no tiene nada m\u00e1s que a\u00f1adir. <\/span><br \/>\n<span style=\"font-family: Arial, Helvetica, sans-serif;\"><br \/><\/span><br \/>\n<span style=\"font-family: Arial, Helvetica, sans-serif;\">Si lo examinamos detenidamente, queda claro cu\u00e1nto ha invertido para crear obras enga\u00f1osamente simples. En este detalle de <i>Memoria #1, <\/i>se ve la infinita variedad de estr\u00edas verticales y superficiales. Observamos que la l\u00ednea trazada en el cuadro revela que el color de la superficie est\u00e1 en la cima de una historia profunda \u2013una arqueolog\u00eda\u2013 de decisiones, de la que s\u00f3lo sabemos que Ross cambi\u00f3 los colores muchas veces. S\u00f3lo \u00e9l sabe qu\u00e9 m\u00e1s ha sucedido y qu\u00e9 ha sido purgado de esta superficie a lo largo de su largo proceso para convertirse en lo que ha decidido terminar.<\/span><br \/>\n<span style=\"font-family: Arial, Helvetica, sans-serif;\"><br \/><\/span><br \/>\n<span style=\"font-family: Arial, Helvetica, sans-serif;\">Para Ross, la importancia y el placer de pintar es el proceso. Tiene un gran estudio en la casa que comparte con su esposa. Pero incluso eso est\u00e1 estrictamente prohibido cuando est\u00e1 trabajando, porque su concentraci\u00f3n es demasiado intensa. <\/span><\/p>\n<table cellpadding=\"0\" cellspacing=\"0\" class=\"tr-caption-container\" style=\"float: right; text-align: right;\">\n<tbody>\n<tr>\n<td style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" border=\"0\" height=\"400\" src=\"http:\/\/1.bp.blogspot.com\/-MloGvcwZ7yM\/VeWN8NLU_aI\/AAAAAAAAHOo\/VN6YG4LWIJY\/s400\/Make%2BMe%2BThat%2BHappy%2B.jpg\" width=\"351\"\/><\/td>\n<\/tr>\n<tr>\n<td class=\"tr-caption\" style=\"text-align: center;\"><span style=\"font-family: Arial, Helvetica, sans-serif; font-size: xx-small;\">Marcos Ross, <i>Me hacen tan feliz, <\/i>68x60.\u201d<\/span><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><span style=\"font-family: Arial, Helvetica, sans-serif;\"\/><br \/><span style=\"font-family: Arial, Helvetica, sans-serif;\"\/><br \/>\n<span style=\"font-family: Arial, Helvetica, sans-serif;\">Sin embargo, cuando intenta explicar lo que <i>lo hace <\/i>En el estudio, no te equivocar\u00edas al describir el proceso como un juego. Aunque su tiempo est\u00e1 estrictamente reservado, no est\u00e1 exactamente concentrado: no sabe lo que va a pasar y no tiene ninguna estrategia. El proceso es ver qu\u00e9 <i>Puedo <\/i>suceder; Perm\u00edtete el tiempo, el espacio y el vac\u00edo mental para estar relajado y receptivo. <\/span><br \/>\n<span style=\"font-family: Arial, Helvetica, sans-serif;\"><br \/><\/span><br \/>\n<span style=\"font-family: Arial, Helvetica, sans-serif;\">\u00bfNo es este el estado de un ni\u00f1o, que puede hacer algo de la nada en cualquier momento, generando grandes ideas tan f\u00e1cilmente como una golondrina, cuya imaginaci\u00f3n es un \u00f3rgano tan vital como sus pulmones? <\/span><br \/>\n<span style=\"font-family: Arial, Helvetica, sans-serif;\"><br \/><\/span><br \/>\n<span style=\"font-family: Arial, Helvetica, sans-serif;\">Lo que hace este artista es invisible para nosotros porque todos los meses que pasa en el estudio son esfuerzos que est\u00e1n pintados. Tu trabajo se elimina constantemente y solo se permite una vez. Si consideramos la idea de que nuestros cuerpos se reemplazan continuamente a medida que las c\u00e9lulas mueren y se descomponen, las pinturas de Ross son cuerpos que se renuevan a s\u00ed mismos, pero sin p\u00e9rdida de material. Acumulan sus historias, volvi\u00e9ndose m\u00e1s y m\u00e1s pesadas con cada aplicaci\u00f3n de material. <\/span><br \/>\n<span style=\"font-family: Arial, Helvetica, sans-serif;\"\/><br \/><span style=\"font-family: Arial, Helvetica, sans-serif;\"\/><\/p>\n<table cellpadding=\"0\" cellspacing=\"0\" class=\"tr-caption-container\" style=\"float: left; text-align: left;\">\n<tbody>\n<tr>\n<td style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" border=\"0\" height=\"320\" src=\"http:\/\/4.bp.blogspot.com\/-LHTOhTrqvl4\/VeWe7DF0wNI\/AAAAAAAAHPY\/YYPvwD9pj3U\/s320\/Make%2BMe%2BThat%2BHappy%2Bdetail.jpg\" width=\"212\"\/><\/td>\n<\/tr>\n<tr>\n<td class=\"tr-caption\" style=\"text-align: center;\"><span style=\"font-family: Arial, Helvetica, sans-serif; font-size: xx-small;\">Marcos Ross, <i>Me hacen tan feliz, <\/i>Detalle <br \/>mostrando dibujo de superficie<\/span><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><span style=\"font-family: Arial, Helvetica, sans-serif;\">Como muchas veces imaginamos el prop\u00f3sito art\u00edstico, durante su abducci\u00f3n el artista estar\u00e1 concentrado en su tema o pasi\u00f3n. Esto podr\u00eda ser hacer avanzar un sue\u00f1o, resolver una angustia personal o apoyar una causa social o pol\u00edtica en el mundo. Nos desanima un poco escuchar a Ross decirnos que no piensa en nada en particular mientras trabaja.<\/span><br \/>\n<span style=\"font-family: Arial, Helvetica, sans-serif;\"><br \/><\/span><br \/>\n<span style=\"font-family: Arial, Helvetica, sans-serif;\">Lo que quiero decir es que nunca hay forma de saber qu\u00e9 est\u00e1 pasando por la mente de un artista mientras trabaja. \u00bfPensamientos \u201cgrandes\u201d u \u201cordinarios\u201d? \u00bfQui\u00e9n deber\u00eda juzgar? Despu\u00e9s de todo, \u00bfa qui\u00e9n le importa? Lo que Ross puso en estas pinturas que podemos ver y experimentar como espectadores es <i>Tiempo.<\/i> <\/span><br \/>\n<span style=\"font-family: Arial, Helvetica, sans-serif;\"><br \/><\/span><br \/>\n<span style=\"font-family: Arial, Helvetica, sans-serif;\">Marc Ross es un artista contemplativo, un tipo de artista por el que nunca se puede respetar lo suficiente. Saber que s\u00f3lo vemos las etapas finales del trabajo realizado durante meses deber\u00eda ralentizar nuestra respiraci\u00f3n y decirnos que hagamos una pausa antes de realizar cualquier parte de este trabajo. un espect\u00e1culo como <i>No se necesita explicaci\u00f3n<\/i> es, de hecho, un conjunto de riquezas \u2013casi demasiadas\u2013 como cada pintura nos llama, y cada una deber\u00eda exigir horas de contemplaci\u00f3n.<\/span><br \/>\n<span style=\"font-family: Arial, Helvetica, sans-serif;\"><br \/><\/span><br \/>\n<span style=\"font-family: Arial, Helvetica, sans-serif;\">Las superficies de estas obras son historias de lo que vivi\u00f3 y enterr\u00f3 el artista; son historias inscritas con conclusiones organizadas, aunque no articuladas, basadas en la experiencia. Estos resultados, presentes en la superficie, satisfacen al artista que cree que no necesita explicarlos ni a s\u00ed mismo. Acept\u00e9moslos por la belleza, el inter\u00e9s, la tonter\u00eda o el significado que encontramos o atribuimos al explorarlos. El artista no dice lo que hay ah\u00ed; el artista no nos dice lo que pens\u00f3: como dice Ross, puede que ni siquiera lo sepa. Lo importante es que <i>El gasto de tiempo es inherente al trabajo, y ahora nos toca a nosotros contemplarlo.<\/i><\/span><\/p>\n<table cellpadding=\"0\" cellspacing=\"0\" class=\"tr-caption-container\" style=\"float: right; text-align: right;\">\n<tbody>\n<tr>\n<td style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" border=\"0\" height=\"640\" src=\"http:\/\/1.bp.blogspot.com\/-f1p4ORreC98\/VeWN0jpjy2I\/AAAAAAAAHOg\/vY9mHfypQ9A\/s640\/Epiphany%2B%2B.jpg\" width=\"430\"\/><\/td>\n<\/tr>\n<tr>\n<td class=\"tr-caption\" style=\"text-align: center;\"><span style=\"font-family: Arial, Helvetica, sans-serif; font-size: xx-small;\">Marcos Ross, <i>Epifan\u00eda, <\/i>72 x 41\u2033, acr\u00edlico, pastel, l\u00e1pices de colores.<\/span><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>\n<span style=\"font-family: Arial, Helvetica, sans-serif;\">Estas pinturas est\u00e1n impregnadas de los cientos de horas de estudio que Ross pas\u00f3 mirando e interactuando con estas superficies, tomando decisiones estrat\u00e9gicas y espont\u00e1neas sobre lo que pod\u00eda hacer con ellas. Estas decisiones son exc\u00e9ntricas hasta donde sabemos o nos importa: si sigue procedimientos acad\u00e9micos, industriales o de guarder\u00eda, no importa lo que veamos, excepto en la medida en que quiera revelarlos.<\/span><br \/>\n<span style=\"font-family: Arial, Helvetica, sans-serif;\"><br \/><\/span><br \/>\n<span style=\"font-family: Arial, Helvetica, sans-serif;\">Las pinturas de Ross documentan el valor del tiempo dedicado a uno mismo; de ser libre y elegir la conciencia frente al olvido; de la experimentaci\u00f3n rutinaria (sin resultados prometidos) como suficiente para tener sentido privado, ya sea que el cosmos lo proporcione o no. Sugieren que la belleza puede surgir \u2013y brillar\u2013 de meses y meses de esfuerzos realizados en silencio y sin inspiraci\u00f3n. Vemos c\u00f3mo el orden y la visi\u00f3n se imponen silenciosamente sobre pacientes per\u00edodos de pruebas y pruebas sin fines capitalistas. Consideramos que trabajar por nuestros propios fines y comprensi\u00f3n puede crear belleza y satisfacci\u00f3n.<\/span><br \/>\n<span style=\"font-family: Arial, Helvetica, sans-serif;\"><br \/><\/span><br \/>\n<span style=\"font-family: Arial, Helvetica, sans-serif;\">La historia del tiempo, la paciencia y los pensamientos del artista inscritos en esta obra de arte se nos presentan de una manera muy directa. Si nos comprometemos a escuchar y mirar, la comunicaci\u00f3n es tan inmediata como una conversaci\u00f3n sin conversaciones triviales: sorprendentemente familiar y liberadora mental y f\u00edsicamente. Si dedicamos un poco de tiempo, nos generar\u00e1 m\u00e1s. El tiempo dedicado a observar crea en el observador mucho m\u00e1s de lo que necesita, aport\u00e1ndonos tiempo, espacio y visiones olvidadas, si no nuevas.<\/span><br \/>\n<span style=\"font-family: Arial, Helvetica, sans-serif;\"><br \/><\/span><br \/>\n<span style=\"font-family: Arial, Helvetica, sans-serif;\">\u00bfLa creatividad art\u00edstica siempre producir\u00e1 algo nuevo, fresco o \u201csignificativo\u201d? A veces, el artista nos regala algo tan antiguo como la tierra y la naturaleza humana, record\u00e1ndonos nuestra necesidad de silencio, de tiempos de barbecho, de grandes preguntas o de contemplaci\u00f3n del paisaje interior en contraposici\u00f3n al paisaje social.<\/span><br \/>\n<span style=\"font-family: Arial, Helvetica, sans-serif;\"><br \/><\/span><br \/>\n<span style=\"font-family: Arial, Helvetica, sans-serif;\">Ross pinta con una vena inquisitiva que se destaca en un mundo ajetreado y ego\u00edsta. Su trabajo lento y silencioso est\u00e1 refrescantemente lleno de vida y conversaci\u00f3n profunda. Sin embargo <i>No se necesita explicaci\u00f3n <\/i>est\u00e1 cerrado, espere m\u00e1s trabajo de Ross en los pr\u00f3ximos meses <\/span><span style=\"background-color: white; font-family: HelveticaNeue, 'Helvetica Neue', Helvetica, Arial, 'Lucida Grande', sans-serif;\">en la sucursal de Chillicothe de la Universidad de Ohio, Bennett Hall Gallery (septiembre-octubre); Y en <\/span><span style=\"background-color: white; font-family: HelveticaNeue, 'Helvetica Neue', Helvetica, Arial, 'Lucida Grande', sans-serif;\">\u201cExposici\u00f3n Inaugural del Jurado\u201d en Galer\u00eda Riffe, de noviembre de 2015 al 10 de enero de 2016.<\/span><br \/>\n<span style=\"background-color: white; font-family: HelveticaNeue, 'Helvetica Neue', Helvetica, Arial, 'Lucida Grande', sans-serif; font-size: 16px;\"><br \/><\/span><br \/>\n<span style=\"font-family: Arial, Helvetica, sans-serif;\"\/><\/p>\n<table align=\"center\" cellpadding=\"0\" cellspacing=\"0\" class=\"tr-caption-container\" style=\"margin-left: auto; margin-right: auto; text-align: center;\">\n<tbody>\n<tr>\n<td style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" border=\"0\" height=\"265\" src=\"http:\/\/4.bp.blogspot.com\/-_KTlTMWGpPQ\/VeW96lFTETI\/AAAAAAAAHPo\/4nLTe7T1yt4\/s400\/CCAC%2B4.jpg\" width=\"400\"\/><\/td>\n<\/tr>\n<tr>\n<td class=\"tr-caption\" style=\"text-align: center;\"><span style=\"font-family: Arial, Helvetica, sans-serif; font-size: xx-small;\">Marcos Ross, <i>No se necesita explicaci\u00f3n <\/i>instalado en el Centro de Artes Culturales, verano de 2015.<\/span><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><span style=\"font-family: Arial, Helvetica, sans-serif; font-size: x-small;\">Fotograf\u00edas cortes\u00eda de Marc Ross.<\/span><\/p>\n<\/div>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Marc Ross, No se necesita explicaci\u00f3n instalado en el Centro de Artes Culturales, agosto de 2015 El Centro de Artes Culturales de Columbus parec\u00eda\u2026 <\/p>","protected":false},"author":1,"featured_media":610,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"fifu_image_url":"http:\/\/2.bp.blogspot.com\/-ige99U1PXT0\/VeRvPyB9ngI\/AAAAAAAAHOM\/YqJAGAzXGLQ\/w1200-h630-p-k-no-nu\/CCAC+1-1.jpg","fifu_image_alt":"","footnotes":""},"categories":[34],"tags":[],"class_list":["post-609","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-arte","latest_post"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Muito tempo: Marc Ross no trabalho - Tirinha.com<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/tirinha.com\/es\/609\/muito-tempo-marc-ross-no-trabalho\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Muito tempo: Marc Ross no trabalho - Tirinha.com\" \/>\n<meta property=\"og:description\" content=\"Marc Ross, Nenhuma explica\u00e7\u00e3o necess\u00e1ria instalado no Centro Cultural de Artes, agosto de 2015 O Columbus Cultural Arts Center parecia &hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/tirinha.com\/es\/609\/muito-tempo-marc-ross-no-trabalho\/\" \/>\n<meta property=\"og:site_name\" content=\"Tirinha.com\" \/>\n<meta property=\"article:published_time\" content=\"2022-06-23T21:34:58+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-12-27T12:08:03+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/2.bp.blogspot.com\/-ige99U1PXT0\/VeRvPyB9ngI\/AAAAAAAAHOM\/YqJAGAzXGLQ\/w1200-h630-p-k-no-nu\/CCAC+1-1.jpg\" \/>\n<meta name=\"author\" content=\"Admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"http:\/\/2.bp.blogspot.com\/-ige99U1PXT0\/VeRvPyB9ngI\/AAAAAAAAHOM\/YqJAGAzXGLQ\/w1200-h630-p-k-no-nu\/CCAC+1-1.jpg\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/tirinha.com\\\/609\\\/muito-tempo-marc-ross-no-trabalho\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/tirinha.com\\\/609\\\/muito-tempo-marc-ross-no-trabalho\\\/\"},\"author\":{\"name\":\"Admin\",\"@id\":\"https:\\\/\\\/tirinha.com\\\/hr\\\/#\\\/schema\\\/person\\\/e22bdfbe17e0461f7e927e6a1208d4d9\"},\"headline\":\"Muito tempo: Marc Ross no trabalho\",\"datePublished\":\"2022-06-23T21:34:58+00:00\",\"dateModified\":\"2022-12-27T12:08:03+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/tirinha.com\\\/609\\\/muito-tempo-marc-ross-no-trabalho\\\/\"},\"wordCount\":1394,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/tirinha.com\\\/hr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/tirinha.com\\\/609\\\/muito-tempo-marc-ross-no-trabalho\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/2.bp.blogspot.com\\\/-ige99U1PXT0\\\/VeRvPyB9ngI\\\/AAAAAAAAHOM\\\/YqJAGAzXGLQ\\\/w1200-h630-p-k-no-nu\\\/CCAC+1-1.jpg\",\"articleSection\":[\"Arte\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/tirinha.com\\\/609\\\/muito-tempo-marc-ross-no-trabalho\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/tirinha.com\\\/609\\\/muito-tempo-marc-ross-no-trabalho\\\/\",\"url\":\"https:\\\/\\\/tirinha.com\\\/609\\\/muito-tempo-marc-ross-no-trabalho\\\/\",\"name\":\"Muito tempo: Marc Ross no trabalho - Tirinha.com\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/tirinha.com\\\/hr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/tirinha.com\\\/609\\\/muito-tempo-marc-ross-no-trabalho\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/tirinha.com\\\/609\\\/muito-tempo-marc-ross-no-trabalho\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/2.bp.blogspot.com\\\/-ige99U1PXT0\\\/VeRvPyB9ngI\\\/AAAAAAAAHOM\\\/YqJAGAzXGLQ\\\/w1200-h630-p-k-no-nu\\\/CCAC+1-1.jpg\",\"datePublished\":\"2022-06-23T21:34:58+00:00\",\"dateModified\":\"2022-12-27T12:08:03+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/tirinha.com\\\/609\\\/muito-tempo-marc-ross-no-trabalho\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/tirinha.com\\\/609\\\/muito-tempo-marc-ross-no-trabalho\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/tirinha.com\\\/609\\\/muito-tempo-marc-ross-no-trabalho\\\/#primaryimage\",\"url\":\"http:\\\/\\\/2.bp.blogspot.com\\\/-ige99U1PXT0\\\/VeRvPyB9ngI\\\/AAAAAAAAHOM\\\/YqJAGAzXGLQ\\\/w1200-h630-p-k-no-nu\\\/CCAC+1-1.jpg\",\"contentUrl\":\"http:\\\/\\\/2.bp.blogspot.com\\\/-ige99U1PXT0\\\/VeRvPyB9ngI\\\/AAAAAAAAHOM\\\/YqJAGAzXGLQ\\\/w1200-h630-p-k-no-nu\\\/CCAC+1-1.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/tirinha.com\\\/609\\\/muito-tempo-marc-ross-no-trabalho\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/tirinha.com\\\/hr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Muito tempo: Marc Ross no trabalho\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/tirinha.com\\\/hr\\\/#website\",\"url\":\"https:\\\/\\\/tirinha.com\\\/hr\\\/\",\"name\":\"Tirinha.com\",\"description\":\"Arte e livros resenhas\",\"publisher\":{\"@id\":\"https:\\\/\\\/tirinha.com\\\/hr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/tirinha.com\\\/hr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/tirinha.com\\\/hr\\\/#organization\",\"name\":\"Tirinha.com\",\"url\":\"https:\\\/\\\/tirinha.com\\\/hr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/tirinha.com\\\/hr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/tirinha.com\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/cropped-Logo-Tirinha.webp\",\"contentUrl\":\"https:\\\/\\\/tirinha.com\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/cropped-Logo-Tirinha.webp\",\"width\":512,\"height\":512,\"caption\":\"Tirinha.com\"},\"image\":{\"@id\":\"https:\\\/\\\/tirinha.com\\\/hr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/tirinha.com\\\/hr\\\/#\\\/schema\\\/person\\\/e22bdfbe17e0461f7e927e6a1208d4d9\",\"name\":\"Admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/tirinha.com\\\/wp-content\\\/litespeed\\\/avatar\\\/394da628e0e367b1790570a93fe58e9b.jpg?ver=1787755741\",\"url\":\"https:\\\/\\\/tirinha.com\\\/wp-content\\\/litespeed\\\/avatar\\\/394da628e0e367b1790570a93fe58e9b.jpg?ver=1787755741\",\"contentUrl\":\"https:\\\/\\\/tirinha.com\\\/wp-content\\\/litespeed\\\/avatar\\\/394da628e0e367b1790570a93fe58e9b.jpg?ver=1787755741\",\"caption\":\"Admin\"},\"url\":\"https:\\\/\\\/tirinha.com\\\/es\\\/author\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Mucho tiempo: Marc Ross en el trabajo - Comic Strip.com","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/tirinha.com\/es\/609\/muito-tempo-marc-ross-no-trabalho\/","og_locale":"es_MX","og_type":"article","og_title":"Muito tempo: Marc Ross no trabalho - Tirinha.com","og_description":"Marc Ross, Nenhuma explica\u00e7\u00e3o necess\u00e1ria instalado no Centro Cultural de Artes, agosto de 2015 O Columbus Cultural Arts Center parecia &hellip;","og_url":"https:\/\/tirinha.com\/es\/609\/muito-tempo-marc-ross-no-trabalho\/","og_site_name":"Tirinha.com","article_published_time":"2022-06-23T21:34:58+00:00","article_modified_time":"2022-12-27T12:08:03+00:00","og_image":[{"url":"http:\/\/2.bp.blogspot.com\/-ige99U1PXT0\/VeRvPyB9ngI\/AAAAAAAAHOM\/YqJAGAzXGLQ\/w1200-h630-p-k-no-nu\/CCAC+1-1.jpg","type":"","width":"","height":""}],"author":"Admin","twitter_card":"summary_large_image","twitter_image":"http:\/\/2.bp.blogspot.com\/-ige99U1PXT0\/VeRvPyB9ngI\/AAAAAAAAHOM\/YqJAGAzXGLQ\/w1200-h630-p-k-no-nu\/CCAC+1-1.jpg","twitter_misc":{"Escrito por":"Admin","Tiempo de lectura":"7 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/tirinha.com\/609\/muito-tempo-marc-ross-no-trabalho\/#article","isPartOf":{"@id":"https:\/\/tirinha.com\/609\/muito-tempo-marc-ross-no-trabalho\/"},"author":{"name":"Admin","@id":"https:\/\/tirinha.com\/hr\/#\/schema\/person\/e22bdfbe17e0461f7e927e6a1208d4d9"},"headline":"Muito tempo: Marc Ross no trabalho","datePublished":"2022-06-23T21:34:58+00:00","dateModified":"2022-12-27T12:08:03+00:00","mainEntityOfPage":{"@id":"https:\/\/tirinha.com\/609\/muito-tempo-marc-ross-no-trabalho\/"},"wordCount":1394,"commentCount":0,"publisher":{"@id":"https:\/\/tirinha.com\/hr\/#organization"},"image":{"@id":"https:\/\/tirinha.com\/609\/muito-tempo-marc-ross-no-trabalho\/#primaryimage"},"thumbnailUrl":"http:\/\/2.bp.blogspot.com\/-ige99U1PXT0\/VeRvPyB9ngI\/AAAAAAAAHOM\/YqJAGAzXGLQ\/w1200-h630-p-k-no-nu\/CCAC+1-1.jpg","articleSection":["Arte"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/tirinha.com\/609\/muito-tempo-marc-ross-no-trabalho\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/tirinha.com\/609\/muito-tempo-marc-ross-no-trabalho\/","url":"https:\/\/tirinha.com\/609\/muito-tempo-marc-ross-no-trabalho\/","name":"Mucho tiempo: Marc Ross en el trabajo - Comic Strip.com","isPartOf":{"@id":"https:\/\/tirinha.com\/hr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/tirinha.com\/609\/muito-tempo-marc-ross-no-trabalho\/#primaryimage"},"image":{"@id":"https:\/\/tirinha.com\/609\/muito-tempo-marc-ross-no-trabalho\/#primaryimage"},"thumbnailUrl":"http:\/\/2.bp.blogspot.com\/-ige99U1PXT0\/VeRvPyB9ngI\/AAAAAAAAHOM\/YqJAGAzXGLQ\/w1200-h630-p-k-no-nu\/CCAC+1-1.jpg","datePublished":"2022-06-23T21:34:58+00:00","dateModified":"2022-12-27T12:08:03+00:00","breadcrumb":{"@id":"https:\/\/tirinha.com\/609\/muito-tempo-marc-ross-no-trabalho\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/tirinha.com\/609\/muito-tempo-marc-ross-no-trabalho\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/tirinha.com\/609\/muito-tempo-marc-ross-no-trabalho\/#primaryimage","url":"http:\/\/2.bp.blogspot.com\/-ige99U1PXT0\/VeRvPyB9ngI\/AAAAAAAAHOM\/YqJAGAzXGLQ\/w1200-h630-p-k-no-nu\/CCAC+1-1.jpg","contentUrl":"http:\/\/2.bp.blogspot.com\/-ige99U1PXT0\/VeRvPyB9ngI\/AAAAAAAAHOM\/YqJAGAzXGLQ\/w1200-h630-p-k-no-nu\/CCAC+1-1.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/tirinha.com\/609\/muito-tempo-marc-ross-no-trabalho\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/tirinha.com\/hr\/"},{"@type":"ListItem","position":2,"name":"Muito tempo: Marc Ross no trabalho"}]},{"@type":"WebSite","@id":"https:\/\/tirinha.com\/hr\/#website","url":"https:\/\/tirinha.com\/hr\/","name":"c\u00f3mics.com","description":"Rese\u00f1as de arte y libros.","publisher":{"@id":"https:\/\/tirinha.com\/hr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/tirinha.com\/hr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/tirinha.com\/hr\/#organization","name":"c\u00f3mics.com","url":"https:\/\/tirinha.com\/hr\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/tirinha.com\/hr\/#\/schema\/logo\/image\/","url":"https:\/\/tirinha.com\/wp-content\/uploads\/2023\/08\/cropped-Logo-Tirinha.webp","contentUrl":"https:\/\/tirinha.com\/wp-content\/uploads\/2023\/08\/cropped-Logo-Tirinha.webp","width":512,"height":512,"caption":"Tirinha.com"},"image":{"@id":"https:\/\/tirinha.com\/hr\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/tirinha.com\/hr\/#\/schema\/person\/e22bdfbe17e0461f7e927e6a1208d4d9","name":"Admin","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/tirinha.com\/wp-content\/litespeed\/avatar\/394da628e0e367b1790570a93fe58e9b.jpg?ver=1787755741","url":"https:\/\/tirinha.com\/wp-content\/litespeed\/avatar\/394da628e0e367b1790570a93fe58e9b.jpg?ver=1787755741","contentUrl":"https:\/\/tirinha.com\/wp-content\/litespeed\/avatar\/394da628e0e367b1790570a93fe58e9b.jpg?ver=1787755741","caption":"Admin"},"url":"https:\/\/tirinha.com\/es\/author\/"}]}},"_links":{"self":[{"href":"https:\/\/tirinha.com\/es\/wp-json\/wp\/v2\/posts\/609","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tirinha.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tirinha.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tirinha.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/tirinha.com\/es\/wp-json\/wp\/v2\/comments?post=609"}],"version-history":[{"count":0,"href":"https:\/\/tirinha.com\/es\/wp-json\/wp\/v2\/posts\/609\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tirinha.com\/es\/wp-json\/wp\/v2\/media\/610"}],"wp:attachment":[{"href":"https:\/\/tirinha.com\/es\/wp-json\/wp\/v2\/media?parent=609"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tirinha.com\/es\/wp-json\/wp\/v2\/categories?post=609"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tirinha.com\/es\/wp-json\/wp\/v2\/tags?post=609"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}