{"id":609,"date":"2022-06-23T21:34:58","date_gmt":"2022-06-23T21:34:58","guid":{"rendered":"https:\/\/tirinha.com\/revisao-de-starr-muito-tempo-marc-ross-no-trabalho\/"},"modified":"2022-12-27T12:08:03","modified_gmt":"2022-12-27T12:08:03","slug":"muito-tempo-marc-ross-no-trabalho","status":"publish","type":"post","link":"https:\/\/tirinha.com\/de\/609\/muito-tempo-marc-ross-no-trabalho\/","title":{"rendered":"Eine lange Zeit: Marc Ross bei der Arbeit"},"content":{"rendered":"<div id=\"post-body-8552530608944071443\">\n<div dir=\"ltr\" style=\"text-align: left;\" trbidi=\"on\">\n<table cellpadding=\"0\" cellspacing=\"0\" class=\"tr-caption-container\" style=\"float: left; margin-right: 1em; text-align: left;\">\n<tbody>\n<tr>\n<td style=\"text-align: center;\"><img fetchpriority=\"high\" decoding=\"async\" border=\"0\" height=\"265\" src=\"http:\/\/2.bp.blogspot.com\/-ige99U1PXT0\/VeRvPyB9ngI\/AAAAAAAAHOM\/YqJAGAzXGLQ\/s400\/CCAC%2B1-1.jpg\" width=\"400\"\/><\/td>\n<\/tr>\n<tr>\n<td class=\"tr-caption\" style=\"text-align: center;\"><span style=\"font-family: Arial, Helvetica, sans-serif; font-size: xx-small;\">Mark Ross, <i>Keine Erkl\u00e4rung n\u00f6tig<\/i> installiert im Cultural Arts Center, August 2015<\/span><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><span style=\"font-family: Arial, Helvetica, sans-serif;\">Das Columbus Cultural Arts Center sah aus wie das Innere einer Schmuckschatulle, als ich die Gem\u00e4ldeausstellung von Marc Ross besuchte, die am 29. August endete. Der Raum eignete sich perfekt f\u00fcr die Ausstellung gro\u00dfformatiger, leuchtender Gem\u00e4lde, in denen einzigartige Farben vorherrschen. Jeder hatte Raum zum Atmen und Raum zum Leuchten, f\u00fcr Ross&#039; Gem\u00e4lde beides, wie lebende Organismen.<\/span><br \/>\n<span style=\"font-family: Arial, Helvetica, sans-serif;\"><br \/><\/span><br \/>\n<span style=\"font-family: Arial, Helvetica, sans-serif;\">Was ist der Unterschied zwischen etwas Lebendigem und etwas, das nicht lebt? Das ist ein <i>Sesamstra\u00dfe<\/i> Konzept, nicht wahr, eine grundlegende Unterscheidung, die wir in unseren fr\u00fchen Jahren lernen? Die Gem\u00e4lde fallen in die unbelebte Kategorie, ungeachtet der Metaphern, die jeder Kunstautor oder Galeriebesucher erfinden k\u00f6nnte. <\/span><span style=\"font-family: Arial, Helvetica, sans-serif;\">Aber das Werk von Marc Ross l\u00e4dt zu einer ernsthaften Neubetrachtung des Raums zwischen Belebtem und Unbelebtem in der Kunst ein. <\/span><br \/>\n<span style=\"font-family: Arial, Helvetica, sans-serif;\"><br \/><\/span><\/p>\n<table align=\"center\" cellpadding=\"0\" cellspacing=\"0\" class=\"tr-caption-container\" style=\"margin-left: auto; margin-right: auto; text-align: center;\">\n<tbody>\n<tr>\n<td style=\"text-align: center;\"><img decoding=\"async\" border=\"0\" height=\"478\" src=\"http:\/\/1.bp.blogspot.com\/-GzTY4g7Rfdg\/VeWN_odpIbI\/AAAAAAAAHOs\/Cmfy2WEx-j0\/s640\/Memento%2B%25231%2B.jpg\" width=\"640\"\/><\/td>\n<\/tr>\n<tr>\n<td class=\"tr-caption\" style=\"text-align: center;\"><span style=\"font-family: Arial, Helvetica, sans-serif; font-size: xx-small;\">Mark Ross, <i>Erinnerung Nr. 1, <\/i>62 x 84.\u201c Acryl-, Pastell- und Buntstifte.<\/span><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><span style=\"font-family: Arial, Helvetica, sans-serif;\">Im Galeriegespr\u00e4ch, das diese Ausstellung abschloss, <i>Keine Erkl\u00e4rung n\u00f6tig, <\/i>Der K\u00fcnstler gestand mir, dass er es hasse, Vortr\u00e4ge zu halten, weil er sehr wenig zu sagen habe. Er wurde von der Notwendigkeit befreit, sich zu \u00e4u\u00dfern, indem er seinem Publikum Fragen stellte, die viel verrieten. <\/span><br \/>\n<span style=\"font-family: Arial, Helvetica, sans-serif;\"><br \/><\/span><\/p>\n<table cellpadding=\"0\" cellspacing=\"0\" class=\"tr-caption-container\" style=\"float: left; text-align: left;\">\n<tbody>\n<tr>\n<td style=\"text-align: center;\"><img decoding=\"async\" border=\"0\" height=\"212\" src=\"http:\/\/4.bp.blogspot.com\/-HBC66TCVdMM\/VeWSMYvtFVI\/AAAAAAAAHPI\/4ImOtbf998U\/s320\/Memento%2B%25231%2BDetail.jpg\" width=\"320\"\/><\/td>\n<\/tr>\n<tr>\n<td class=\"tr-caption\" style=\"text-align: center;\"><span style=\"font-size: xx-small;\"><span style=\"font-family: Arial, Helvetica, sans-serif;\">Mark Ross, <\/span><span style=\"font-family: Arial, Helvetica, sans-serif;\"><i>Erinnerung Nr. 1, <\/i>Detail<i>.<\/i><\/span><\/span><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><span style=\"font-family: Arial, Helvetica, sans-serif;\">Das Wichtigste, was Ross uns sagte, ist, dass die Fertigstellung jedes dieser Werke lange dauert und dass die Fertigstellung auf einfache und praktische Weise gekennzeichnet ist: Sie ist erledigt, wenn er sieht, dass er nichts mehr hinzuzuf\u00fcgen hat. <\/span><br \/>\n<span style=\"font-family: Arial, Helvetica, sans-serif;\"><br \/><\/span><br \/>\n<span style=\"font-family: Arial, Helvetica, sans-serif;\">Bei genauerem Hinsehen wird deutlich, wie sehr er sich die M\u00fche gemacht hat, t\u00e4uschend einfache Werke zu schaffen. In diesem Detail von <i>Erinnerung Nr. 1, <\/i>man sieht die unendliche Vielfalt vertikaler und oberfl\u00e4chlicher Streifen. Wir stellen fest, dass die im Gem\u00e4lde gezeichnete Linie offenbart, dass die Oberfl\u00e4chenfarbe an der Spitze einer tiefen Geschichte \u2013 einer Arch\u00e4ologie \u2013 von Entscheidungen steht, von denen wir nur wissen, dass Ross die Farben viele Male ge\u00e4ndert hat. Nur er wei\u00df, was sonst noch passiert ist und was im Laufe seines langen Prozesses, zu dem zu werden, wof\u00fcr er sich entschieden hat, von dieser Oberfl\u00e4che entfernt wurde.<\/span><br \/>\n<span style=\"font-family: Arial, Helvetica, sans-serif;\"><br \/><\/span><br \/>\n<span style=\"font-family: Arial, Helvetica, sans-serif;\">F\u00fcr Ross liegt die Bedeutung und Freude am Malen im Prozess. Er hat ein gro\u00dfes Atelier in dem Haus, das er mit seiner Frau teilt. Aber auch das ist ihm bei der Arbeit strengstens untersagt, weil seine Konzentration zu hoch ist. <\/span><\/p>\n<table cellpadding=\"0\" cellspacing=\"0\" class=\"tr-caption-container\" style=\"float: right; text-align: right;\">\n<tbody>\n<tr>\n<td style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" border=\"0\" height=\"400\" src=\"http:\/\/1.bp.blogspot.com\/-MloGvcwZ7yM\/VeWN8NLU_aI\/AAAAAAAAHOo\/VN6YG4LWIJY\/s400\/Make%2BMe%2BThat%2BHappy%2B.jpg\" width=\"351\"\/><\/td>\n<\/tr>\n<tr>\n<td class=\"tr-caption\" style=\"text-align: center;\"><span style=\"font-family: Arial, Helvetica, sans-serif; font-size: xx-small;\">Mark Ross, <i>Mach mich so gl\u00fccklich, <\/i>68x60.\u201d<\/span><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><span style=\"font-family: Arial, Helvetica, sans-serif;\"\/><br \/><span style=\"font-family: Arial, Helvetica, sans-serif;\"\/><br \/>\n<span style=\"font-family: Arial, Helvetica, sans-serif;\">Wenn er jedoch versucht zu erkl\u00e4ren, was er <i>das tut er <\/i>Im Studio w\u00e4re es nicht falsch, den Prozess als Spiel zu bezeichnen. Obwohl seine Zeit streng geh\u00fctet wird, ist er nicht gerade konzentriert \u2013 er wei\u00df nicht, was passieren wird und hat keine Strategie. Der Prozess besteht darin, zu sehen, was <i>kann ich <\/i>passieren; G\u00f6nnen Sie sich Zeit, Raum und geistige Leere, um entspannt und empf\u00e4nglich zu sein. <\/span><br \/>\n<span style=\"font-family: Arial, Helvetica, sans-serif;\"><br \/><\/span><br \/>\n<span style=\"font-family: Arial, Helvetica, sans-serif;\">Ist das nicht der Zustand eines Kindes, das jederzeit aus dem Nichts etwas machen kann und dabei so leicht gro\u00dfartige Ideen hervorbringt wie eine Schwalbenfliege, dessen Vorstellungskraft ein ebenso lebenswichtiges Organ ist wie seine Lunge? <\/span><br \/>\n<span style=\"font-family: Arial, Helvetica, sans-serif;\"><br \/><\/span><br \/>\n<span style=\"font-family: Arial, Helvetica, sans-serif;\">Was dieser K\u00fcnstler tut, ist f\u00fcr uns unsichtbar, denn alle Monate, die er im Atelier verbringt, sind gemalte Werke. Ihre Arbeit wird st\u00e4ndig gel\u00f6scht und ist nur einmal erlaubt. Wenn wir die Ansicht ber\u00fccksichtigen, dass sich unsere K\u00f6rper st\u00e4ndig selbst ersetzen, wenn Zellen absterben und zerfallen, sind Ross\u2018 Gem\u00e4lde sich selbst erneuernde K\u00f6rper, jedoch ohne Materialverlust. Sie h\u00e4ufen ihre Geschichten an und werden mit jedem Materialauftrag immer schwerer. <\/span><br \/>\n<span style=\"font-family: Arial, Helvetica, sans-serif;\"\/><br \/><span style=\"font-family: Arial, Helvetica, sans-serif;\"\/><\/p>\n<table cellpadding=\"0\" cellspacing=\"0\" class=\"tr-caption-container\" style=\"float: left; text-align: left;\">\n<tbody>\n<tr>\n<td style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" border=\"0\" height=\"320\" src=\"http:\/\/4.bp.blogspot.com\/-LHTOhTrqvl4\/VeWe7DF0wNI\/AAAAAAAAHPY\/YYPvwD9pj3U\/s320\/Make%2BMe%2BThat%2BHappy%2Bdetail.jpg\" width=\"212\"\/><\/td>\n<\/tr>\n<tr>\n<td class=\"tr-caption\" style=\"text-align: center;\"><span style=\"font-family: Arial, Helvetica, sans-serif; font-size: xx-small;\">Mark Ross, <i>Mach mich so gl\u00fccklich, <\/i>Detail <br \/>Zeigt eine Oberfl\u00e4chenzeichnung<\/span><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><span style=\"font-family: Arial, Helvetica, sans-serif;\">Wie wir uns den k\u00fcnstlerischen Zweck oft vorstellen, konzentriert sich der K\u00fcnstler w\u00e4hrend seiner Entf\u00fchrung auf sein Thema oder seine Leidenschaft. Dabei kann es sich um die Verwirklichung eines Traums, die L\u00f6sung eines pers\u00f6nlichen Kummers oder die Unterst\u00fctzung einer sozialen oder politischen Sache in der Welt handeln. Wir sind ein wenig entmutigt, als Ross uns erz\u00e4hlt, dass er bei der Arbeit an nichts Besonderes denkt.<\/span><br \/>\n<span style=\"font-family: Arial, Helvetica, sans-serif;\"><br \/><\/span><br \/>\n<span style=\"font-family: Arial, Helvetica, sans-serif;\">Mein Punkt ist, dass es nie eine M\u00f6glichkeit gibt, zu wissen, was im Kopf eines K\u00fcnstlers vorgeht, w\u00e4hrend er arbeitet. \u201eGro\u00dfe\u201c oder \u201egew\u00f6hnliche\u201c Gedanken? Wer soll urteilen? Wen interessiert das schlie\u00dflich? Was Ross in diese Gem\u00e4lde gesteckt hat, k\u00f6nnen wir als Betrachter sehen und erleben <i>Zeit.<\/i> <\/span><br \/>\n<span style=\"font-family: Arial, Helvetica, sans-serif;\"><br \/><\/span><br \/>\n<span style=\"font-family: Arial, Helvetica, sans-serif;\">Marc Ross ist ein kontemplativer K\u00fcnstler, ein K\u00fcnstlertyp, dem man gar nicht genug Respekt entgegenbringen kann. Zu wissen, dass wir nur die letzten Phasen der Arbeit sehen, die \u00fcber Monate hinweg erledigt wurde, sollte unseren Atem verlangsamen und uns sagen, dass wir vor dieser Arbeit innehalten sollen. Eine Show wie <i>Keine Erkl\u00e4rung n\u00f6tig<\/i> Es ist in der Tat eine Peinlichkeit des Reichtums \u2013 fast zu viel \u2013, wie jedes Gem\u00e4lde uns ruft, und jedes einzelne sollte stundenlange Betrachtung erfordern.<\/span><br \/>\n<span style=\"font-family: Arial, Helvetica, sans-serif;\"><br \/><\/span><br \/>\n<span style=\"font-family: Arial, Helvetica, sans-serif;\">Die Oberfl\u00e4chen dieser Werke sind Geschichten dar\u00fcber, was der K\u00fcnstler lebte und begrub; Es sind Geschichten mit organisierten \u2013 wenn auch unartikulierten \u2013 Schlussfolgerungen, die auf Erfahrungen basieren. Diese oberfl\u00e4chlich vorliegenden Ergebnisse stellen den K\u00fcnstler zufrieden, der glaubt, sie und sich selbst nicht erkl\u00e4ren zu m\u00fcssen. Akzeptieren wir sie f\u00fcr die Sch\u00f6nheit, das Interesse, die Albernheit oder die Bedeutung, die wir bei der Erforschung finden oder ihnen zuschreiben. Der K\u00fcnstler sagt nicht, was da ist; Der K\u00fcnstler sagt uns nicht, was er dachte: Wie Ross sagt, wei\u00df er es vielleicht nicht einmal. Das Wichtige ist das <i>Der Zeitaufwand ist mit der Arbeit verbunden, und jetzt liegt es an uns, dar\u00fcber nachzudenken.<\/i><\/span><\/p>\n<table cellpadding=\"0\" cellspacing=\"0\" class=\"tr-caption-container\" style=\"float: right; text-align: right;\">\n<tbody>\n<tr>\n<td style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" border=\"0\" height=\"640\" src=\"http:\/\/1.bp.blogspot.com\/-f1p4ORreC98\/VeWN0jpjy2I\/AAAAAAAAHOg\/vY9mHfypQ9A\/s640\/Epiphany%2B%2B.jpg\" width=\"430\"\/><\/td>\n<\/tr>\n<tr>\n<td class=\"tr-caption\" style=\"text-align: center;\"><span style=\"font-family: Arial, Helvetica, sans-serif; font-size: xx-small;\">Mark Ross, <i>Epiphanie, <\/i>72 x 41\u2033, Acryl-, Pastell- und Buntstifte.<\/span><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>\n<span style=\"font-family: Arial, Helvetica, sans-serif;\">Diese Gem\u00e4lde sind durchdrungen von den Hunderten von Atelierstunden, die Ross damit verbracht hat, diese Oberfl\u00e4chen zu betrachten und mit ihnen zu interagieren und strategische und spontane Entscheidungen dar\u00fcber zu treffen, was er mit ihnen machen k\u00f6nnte. Soweit wir wissen oder uns interessieren, sind diese Entscheidungen exzentrisch: Ob er akademischen, industriellen oder Kindertagesst\u00e4ttenverfahren folgt, spielt keine Rolle, was wir sehen, es sei denn, er m\u00f6chte sie offenbaren.<\/span><br \/>\n<span style=\"font-family: Arial, Helvetica, sans-serif;\"><br \/><\/span><br \/>\n<span style=\"font-family: Arial, Helvetica, sans-serif;\">Ross\u2018 Gem\u00e4lde dokumentieren den Wert der Zeit, die er mit sich selbst verbringt; frei zu sein und Bewusstsein dem Vergessen vorzuziehen; von Routineexperimenten (ohne versprochene Ergebnisse) als ausreichend, um einen pers\u00f6nlichen Sinn zu ergeben, unabh\u00e4ngig davon, ob der Kosmos ihn bereitstellt oder nicht. Sie deuten darauf hin, dass Sch\u00f6nheit aus monatelangen uninspirierten, stillschweigenden Bem\u00fchungen entstehen und strahlen kann. Wir sehen, wie Ordnung und Vision sich stillschweigend \u00fcber geduldige Zeiten der Pr\u00fcfungen und Pr\u00fcfungen ohne kapitalistische Ziele aufdr\u00e4ngen. Wir sind davon \u00fcberzeugt, dass die Arbeit an unseren eigenen Zielen und unserem Verst\u00e4ndnis Sch\u00f6nheit und Zufriedenheit schaffen kann.<\/span><br \/>\n<span style=\"font-family: Arial, Helvetica, sans-serif;\"><br \/><\/span><br \/>\n<span style=\"font-family: Arial, Helvetica, sans-serif;\">Die in diesem Kunstwerk eingeschriebene Geschichte der Zeit, Geduld und Gedanken des K\u00fcnstlers wird uns auf sehr direkte Weise pr\u00e4sentiert. Wenn wir uns darauf festlegen, zuzuh\u00f6ren und zu schauen, ist die Kommunikation so unmittelbar wie ein Gespr\u00e4ch ohne Smalltalk \u2013 \u00fcberraschend vertraut und geistig und k\u00f6rperlich befreiend. Wenn wir ein wenig Zeit investieren, wird es mehr f\u00fcr uns generieren. Die mit dem Beobachten verbrachte Zeit erzeugt im Beobachter viel mehr, als er braucht, und bringt uns Zeit und Raum und vergessene, wenn nicht sogar neue Ansichten.<\/span><br \/>\n<span style=\"font-family: Arial, Helvetica, sans-serif;\"><br \/><\/span><br \/>\n<span style=\"font-family: Arial, Helvetica, sans-serif;\">Wird k\u00fcnstlerische Kreativit\u00e4t immer etwas Neues, Frisches oder \u201eSinnvolles\u201c hervorbringen? Manchmal schenkt uns der K\u00fcnstler etwas, das so alt ist wie die Erde und die menschliche Natur, und erinnert uns an unser Bed\u00fcrfnis nach Stille, nach stillen Zeiten, nach gro\u00dfen Fragen oder nach der Betrachtung des Inneren statt der sozialen Landschaft.<\/span><br \/>\n<span style=\"font-family: Arial, Helvetica, sans-serif;\"><br \/><\/span><br \/>\n<span style=\"font-family: Arial, Helvetica, sans-serif;\">Ross malt mit einer fragenden Art, die in einer gesch\u00e4ftigen, selbsts\u00fcchtigen Welt auff\u00e4llt. Sein langsames, ruhiges Werk ist erfrischend voller Leben und tiefgr\u00fcndiger Konversation. Jedoch <i>Keine Erkl\u00e4rung n\u00f6tig <\/i>geschlossen ist, erwarten Sie in den kommenden Monaten weitere Arbeiten von Ross <\/span><span style=\"background-color: white; font-family: HelveticaNeue, 'Helvetica Neue', Helvetica, Arial, 'Lucida Grande', sans-serif;\">in der Chillicothe-Zweigstelle der Ohio University, Bennett Hall Gallery (September-Oktober); Und rein <\/span><span style=\"background-color: white; font-family: HelveticaNeue, 'Helvetica Neue', Helvetica, Arial, 'Lucida Grande', sans-serif;\">\u201eEr\u00f6ffnungsausstellung der Jury\u201c in der Galeria Riffe, von November 2015 bis 10. Januar 2016.<\/span><br \/>\n<span style=\"background-color: white; font-family: HelveticaNeue, 'Helvetica Neue', Helvetica, Arial, 'Lucida Grande', sans-serif; font-size: 16px;\"><br \/><\/span><br \/>\n<span style=\"font-family: Arial, Helvetica, sans-serif;\"\/><\/p>\n<table align=\"center\" cellpadding=\"0\" cellspacing=\"0\" class=\"tr-caption-container\" style=\"margin-left: auto; margin-right: auto; text-align: center;\">\n<tbody>\n<tr>\n<td style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" border=\"0\" height=\"265\" src=\"http:\/\/4.bp.blogspot.com\/-_KTlTMWGpPQ\/VeW96lFTETI\/AAAAAAAAHPo\/4nLTe7T1yt4\/s400\/CCAC%2B4.jpg\" width=\"400\"\/><\/td>\n<\/tr>\n<tr>\n<td class=\"tr-caption\" style=\"text-align: center;\"><span style=\"font-family: Arial, Helvetica, sans-serif; font-size: xx-small;\">Mark Ross, <i>Keine Erkl\u00e4rung n\u00f6tig <\/i>installiert im Cultural Arts Center, Sommer 2015.<\/span><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><span style=\"font-family: Arial, Helvetica, sans-serif; font-size: x-small;\">Fotos mit freundlicher Genehmigung von Marc Ross<\/span><\/p>\n<\/div>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Marc Ross, Keine Erkl\u00e4rung erforderlich, installiert im Cultural Arts Center, August 2015 Das Columbus Cultural Arts Center sah aus\u2026 <\/p>","protected":false},"author":1,"featured_media":610,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"fifu_image_url":"http:\/\/2.bp.blogspot.com\/-ige99U1PXT0\/VeRvPyB9ngI\/AAAAAAAAHOM\/YqJAGAzXGLQ\/w1200-h630-p-k-no-nu\/CCAC+1-1.jpg","fifu_image_alt":"","footnotes":""},"categories":[34],"tags":[],"class_list":["post-609","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-arte","latest_post"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Muito tempo: Marc Ross no trabalho - Tirinha.com<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/tirinha.com\/de\/609\/muito-tempo-marc-ross-no-trabalho\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Muito tempo: Marc Ross no trabalho - Tirinha.com\" \/>\n<meta property=\"og:description\" content=\"Marc Ross, Nenhuma explica\u00e7\u00e3o necess\u00e1ria instalado no Centro Cultural de Artes, agosto de 2015 O Columbus Cultural Arts Center parecia &hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/tirinha.com\/de\/609\/muito-tempo-marc-ross-no-trabalho\/\" \/>\n<meta property=\"og:site_name\" content=\"Tirinha.com\" \/>\n<meta property=\"article:published_time\" content=\"2022-06-23T21:34:58+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-12-27T12:08:03+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/2.bp.blogspot.com\/-ige99U1PXT0\/VeRvPyB9ngI\/AAAAAAAAHOM\/YqJAGAzXGLQ\/w1200-h630-p-k-no-nu\/CCAC+1-1.jpg\" \/>\n<meta name=\"author\" content=\"Admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"http:\/\/2.bp.blogspot.com\/-ige99U1PXT0\/VeRvPyB9ngI\/AAAAAAAAHOM\/YqJAGAzXGLQ\/w1200-h630-p-k-no-nu\/CCAC+1-1.jpg\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"7\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/tirinha.com\\\/609\\\/muito-tempo-marc-ross-no-trabalho\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/tirinha.com\\\/609\\\/muito-tempo-marc-ross-no-trabalho\\\/\"},\"author\":{\"name\":\"Admin\",\"@id\":\"https:\\\/\\\/tirinha.com\\\/hr\\\/#\\\/schema\\\/person\\\/e22bdfbe17e0461f7e927e6a1208d4d9\"},\"headline\":\"Muito tempo: Marc Ross no trabalho\",\"datePublished\":\"2022-06-23T21:34:58+00:00\",\"dateModified\":\"2022-12-27T12:08:03+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/tirinha.com\\\/609\\\/muito-tempo-marc-ross-no-trabalho\\\/\"},\"wordCount\":1394,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/tirinha.com\\\/hr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/tirinha.com\\\/609\\\/muito-tempo-marc-ross-no-trabalho\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/2.bp.blogspot.com\\\/-ige99U1PXT0\\\/VeRvPyB9ngI\\\/AAAAAAAAHOM\\\/YqJAGAzXGLQ\\\/w1200-h630-p-k-no-nu\\\/CCAC+1-1.jpg\",\"articleSection\":[\"Arte\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/tirinha.com\\\/609\\\/muito-tempo-marc-ross-no-trabalho\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/tirinha.com\\\/609\\\/muito-tempo-marc-ross-no-trabalho\\\/\",\"url\":\"https:\\\/\\\/tirinha.com\\\/609\\\/muito-tempo-marc-ross-no-trabalho\\\/\",\"name\":\"Muito tempo: Marc Ross no trabalho - Tirinha.com\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/tirinha.com\\\/hr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/tirinha.com\\\/609\\\/muito-tempo-marc-ross-no-trabalho\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/tirinha.com\\\/609\\\/muito-tempo-marc-ross-no-trabalho\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/2.bp.blogspot.com\\\/-ige99U1PXT0\\\/VeRvPyB9ngI\\\/AAAAAAAAHOM\\\/YqJAGAzXGLQ\\\/w1200-h630-p-k-no-nu\\\/CCAC+1-1.jpg\",\"datePublished\":\"2022-06-23T21:34:58+00:00\",\"dateModified\":\"2022-12-27T12:08:03+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/tirinha.com\\\/609\\\/muito-tempo-marc-ross-no-trabalho\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/tirinha.com\\\/609\\\/muito-tempo-marc-ross-no-trabalho\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/tirinha.com\\\/609\\\/muito-tempo-marc-ross-no-trabalho\\\/#primaryimage\",\"url\":\"http:\\\/\\\/2.bp.blogspot.com\\\/-ige99U1PXT0\\\/VeRvPyB9ngI\\\/AAAAAAAAHOM\\\/YqJAGAzXGLQ\\\/w1200-h630-p-k-no-nu\\\/CCAC+1-1.jpg\",\"contentUrl\":\"http:\\\/\\\/2.bp.blogspot.com\\\/-ige99U1PXT0\\\/VeRvPyB9ngI\\\/AAAAAAAAHOM\\\/YqJAGAzXGLQ\\\/w1200-h630-p-k-no-nu\\\/CCAC+1-1.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/tirinha.com\\\/609\\\/muito-tempo-marc-ross-no-trabalho\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/tirinha.com\\\/hr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Muito tempo: Marc Ross no trabalho\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/tirinha.com\\\/hr\\\/#website\",\"url\":\"https:\\\/\\\/tirinha.com\\\/hr\\\/\",\"name\":\"Tirinha.com\",\"description\":\"Arte e livros resenhas\",\"publisher\":{\"@id\":\"https:\\\/\\\/tirinha.com\\\/hr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/tirinha.com\\\/hr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/tirinha.com\\\/hr\\\/#organization\",\"name\":\"Tirinha.com\",\"url\":\"https:\\\/\\\/tirinha.com\\\/hr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/tirinha.com\\\/hr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/tirinha.com\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/cropped-Logo-Tirinha.webp\",\"contentUrl\":\"https:\\\/\\\/tirinha.com\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/cropped-Logo-Tirinha.webp\",\"width\":512,\"height\":512,\"caption\":\"Tirinha.com\"},\"image\":{\"@id\":\"https:\\\/\\\/tirinha.com\\\/hr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/tirinha.com\\\/hr\\\/#\\\/schema\\\/person\\\/e22bdfbe17e0461f7e927e6a1208d4d9\",\"name\":\"Admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/tirinha.com\\\/wp-content\\\/litespeed\\\/avatar\\\/394da628e0e367b1790570a93fe58e9b.jpg?ver=1787755741\",\"url\":\"https:\\\/\\\/tirinha.com\\\/wp-content\\\/litespeed\\\/avatar\\\/394da628e0e367b1790570a93fe58e9b.jpg?ver=1787755741\",\"contentUrl\":\"https:\\\/\\\/tirinha.com\\\/wp-content\\\/litespeed\\\/avatar\\\/394da628e0e367b1790570a93fe58e9b.jpg?ver=1787755741\",\"caption\":\"Admin\"},\"url\":\"https:\\\/\\\/tirinha.com\\\/de\\\/author\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Lange Zeit: Marc Ross bei der Arbeit \u2013 Comic Strip.com","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/tirinha.com\/de\/609\/muito-tempo-marc-ross-no-trabalho\/","og_locale":"de_DE","og_type":"article","og_title":"Muito tempo: Marc Ross no trabalho - Tirinha.com","og_description":"Marc Ross, Nenhuma explica\u00e7\u00e3o necess\u00e1ria instalado no Centro Cultural de Artes, agosto de 2015 O Columbus Cultural Arts Center parecia &hellip;","og_url":"https:\/\/tirinha.com\/de\/609\/muito-tempo-marc-ross-no-trabalho\/","og_site_name":"Tirinha.com","article_published_time":"2022-06-23T21:34:58+00:00","article_modified_time":"2022-12-27T12:08:03+00:00","og_image":[{"url":"http:\/\/2.bp.blogspot.com\/-ige99U1PXT0\/VeRvPyB9ngI\/AAAAAAAAHOM\/YqJAGAzXGLQ\/w1200-h630-p-k-no-nu\/CCAC+1-1.jpg","type":"","width":"","height":""}],"author":"Admin","twitter_card":"summary_large_image","twitter_image":"http:\/\/2.bp.blogspot.com\/-ige99U1PXT0\/VeRvPyB9ngI\/AAAAAAAAHOM\/YqJAGAzXGLQ\/w1200-h630-p-k-no-nu\/CCAC+1-1.jpg","twitter_misc":{"Verfasst von":"Admin","Gesch\u00e4tzte Lesezeit":"7\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/tirinha.com\/609\/muito-tempo-marc-ross-no-trabalho\/#article","isPartOf":{"@id":"https:\/\/tirinha.com\/609\/muito-tempo-marc-ross-no-trabalho\/"},"author":{"name":"Admin","@id":"https:\/\/tirinha.com\/hr\/#\/schema\/person\/e22bdfbe17e0461f7e927e6a1208d4d9"},"headline":"Muito tempo: Marc Ross no trabalho","datePublished":"2022-06-23T21:34:58+00:00","dateModified":"2022-12-27T12:08:03+00:00","mainEntityOfPage":{"@id":"https:\/\/tirinha.com\/609\/muito-tempo-marc-ross-no-trabalho\/"},"wordCount":1394,"commentCount":0,"publisher":{"@id":"https:\/\/tirinha.com\/hr\/#organization"},"image":{"@id":"https:\/\/tirinha.com\/609\/muito-tempo-marc-ross-no-trabalho\/#primaryimage"},"thumbnailUrl":"http:\/\/2.bp.blogspot.com\/-ige99U1PXT0\/VeRvPyB9ngI\/AAAAAAAAHOM\/YqJAGAzXGLQ\/w1200-h630-p-k-no-nu\/CCAC+1-1.jpg","articleSection":["Arte"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/tirinha.com\/609\/muito-tempo-marc-ross-no-trabalho\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/tirinha.com\/609\/muito-tempo-marc-ross-no-trabalho\/","url":"https:\/\/tirinha.com\/609\/muito-tempo-marc-ross-no-trabalho\/","name":"Lange Zeit: Marc Ross bei der Arbeit \u2013 Comic Strip.com","isPartOf":{"@id":"https:\/\/tirinha.com\/hr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/tirinha.com\/609\/muito-tempo-marc-ross-no-trabalho\/#primaryimage"},"image":{"@id":"https:\/\/tirinha.com\/609\/muito-tempo-marc-ross-no-trabalho\/#primaryimage"},"thumbnailUrl":"http:\/\/2.bp.blogspot.com\/-ige99U1PXT0\/VeRvPyB9ngI\/AAAAAAAAHOM\/YqJAGAzXGLQ\/w1200-h630-p-k-no-nu\/CCAC+1-1.jpg","datePublished":"2022-06-23T21:34:58+00:00","dateModified":"2022-12-27T12:08:03+00:00","breadcrumb":{"@id":"https:\/\/tirinha.com\/609\/muito-tempo-marc-ross-no-trabalho\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/tirinha.com\/609\/muito-tempo-marc-ross-no-trabalho\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/tirinha.com\/609\/muito-tempo-marc-ross-no-trabalho\/#primaryimage","url":"http:\/\/2.bp.blogspot.com\/-ige99U1PXT0\/VeRvPyB9ngI\/AAAAAAAAHOM\/YqJAGAzXGLQ\/w1200-h630-p-k-no-nu\/CCAC+1-1.jpg","contentUrl":"http:\/\/2.bp.blogspot.com\/-ige99U1PXT0\/VeRvPyB9ngI\/AAAAAAAAHOM\/YqJAGAzXGLQ\/w1200-h630-p-k-no-nu\/CCAC+1-1.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/tirinha.com\/609\/muito-tempo-marc-ross-no-trabalho\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/tirinha.com\/hr\/"},{"@type":"ListItem","position":2,"name":"Muito tempo: Marc Ross no trabalho"}]},{"@type":"WebSite","@id":"https:\/\/tirinha.com\/hr\/#website","url":"https:\/\/tirinha.com\/hr\/","name":"Tirinha.com","description":"Kunst- und Buchrezensionen","publisher":{"@id":"https:\/\/tirinha.com\/hr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/tirinha.com\/hr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/tirinha.com\/hr\/#organization","name":"Tirinha.com","url":"https:\/\/tirinha.com\/hr\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/tirinha.com\/hr\/#\/schema\/logo\/image\/","url":"https:\/\/tirinha.com\/wp-content\/uploads\/2023\/08\/cropped-Logo-Tirinha.webp","contentUrl":"https:\/\/tirinha.com\/wp-content\/uploads\/2023\/08\/cropped-Logo-Tirinha.webp","width":512,"height":512,"caption":"Tirinha.com"},"image":{"@id":"https:\/\/tirinha.com\/hr\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/tirinha.com\/hr\/#\/schema\/person\/e22bdfbe17e0461f7e927e6a1208d4d9","name":"Admin","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/tirinha.com\/wp-content\/litespeed\/avatar\/394da628e0e367b1790570a93fe58e9b.jpg?ver=1787755741","url":"https:\/\/tirinha.com\/wp-content\/litespeed\/avatar\/394da628e0e367b1790570a93fe58e9b.jpg?ver=1787755741","contentUrl":"https:\/\/tirinha.com\/wp-content\/litespeed\/avatar\/394da628e0e367b1790570a93fe58e9b.jpg?ver=1787755741","caption":"Admin"},"url":"https:\/\/tirinha.com\/de\/author\/"}]}},"_links":{"self":[{"href":"https:\/\/tirinha.com\/de\/wp-json\/wp\/v2\/posts\/609","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tirinha.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tirinha.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tirinha.com\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/tirinha.com\/de\/wp-json\/wp\/v2\/comments?post=609"}],"version-history":[{"count":0,"href":"https:\/\/tirinha.com\/de\/wp-json\/wp\/v2\/posts\/609\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tirinha.com\/de\/wp-json\/wp\/v2\/media\/610"}],"wp:attachment":[{"href":"https:\/\/tirinha.com\/de\/wp-json\/wp\/v2\/media?parent=609"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tirinha.com\/de\/wp-json\/wp\/v2\/categories?post=609"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tirinha.com\/de\/wp-json\/wp\/v2\/tags?post=609"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}