{"id":774,"date":"2023-03-03T13:08:52","date_gmt":"2023-03-03T13:08:52","guid":{"rendered":"https:\/\/tirinha.com\/a-exposicao-no-museu-carmen-thyssen-em-malaga-que-o-comprova\/"},"modified":"2023-03-03T13:08:52","modified_gmt":"2023-03-03T13:08:52","slug":"a-exposicao-no-museu-carmen-thyssen-em-malaga-que-o-comprova","status":"publish","type":"post","link":"https:\/\/tirinha.com\/bn\/774\/a-exposicao-no-museu-carmen-thyssen-em-malaga-que-o-comprova\/","title":{"rendered":"\u09ae\u09be\u09b2\u09be\u0997\u09be\u09b0 \u0995\u09be\u09b0\u09ae\u09c7\u09a8 \u09a5\u09be\u0987\u09b8\u09c7\u09a8 \u099c\u09be\u09a6\u09c1\u0998\u09b0\u09c7\u09b0 \u09aa\u09cd\u09b0\u09a6\u09b0\u09cd\u09b6\u09a8\u09c0 \u098f\u099f\u09bf \u09aa\u09cd\u09b0\u09ae\u09be\u09a3 \u0995\u09b0\u09c7"},"content":{"rendered":"<p> [ad_1]<br \/>\n<\/p>\n<div id=\"article-body-content\" data-action=\"toggle\" data-status=\"on\">\n<p class=\"paragraph\" id=\"paragraph_1\">\u00c0 exce\u00e7\u00e3o do surrealista Ren\u00e9 Magritte e de alguns simbolistas, a tradi\u00e7\u00e3o pict\u00f3rica belga moderna \u00e9 pouco conhecida no nosso pa\u00eds, embora a situa\u00e7\u00e3o geopol\u00edtica de Bruxelas, com as suas idas e vindas a Paris, tenha facilitado que se tornasse uma cidade de destaque na Europa durante o s\u00e9c. per\u00edodo vanguardista.  Esta exposi\u00e7\u00e3o, comissariada por <strong>Claire LeBlanc<\/strong>diretor do Mus\u00e9e d&#8217;Ixelles de Bruxelas, agora em reforma, nos aproxima de oitenta obras de cinquenta pintores para resenhar um s\u00e9culo, a partir de 1860, em correspond\u00eancia com a cronologia do museu anfitri\u00e3o, acabando por considerar se havia acentos caracter\u00edsticos entre Belga.<\/p>\n<p class=\"paragraph\" id=\"paragraph_2\">O passeio come\u00e7a na Sala Nobre do primeiro andar, com tecidos que lembram o romantismo como o primeiro movimento ap\u00f3s a independ\u00eancia da B\u00e9lgica da Holanda em 1830. Aqui \u00e9 apresentada a import\u00e2ncia da influ\u00eancia de Courbet ap\u00f3s sua exposi\u00e7\u00e3o em Bruxelas em 1851, em paisagens de ervas ricas como as de <strong>Hyppolyte Boulenger<\/strong>, versus a pintura mais fluida do franc\u00eas de Barbizon.  Junto com eles, um realismo social com cunho pr\u00f3prio, com <strong>Constantino Meunier<\/strong> e <strong>Eug\u00e8ne Laermans<\/strong>.<\/p>\n<div class=\"article-media \" itemscope=\"\" itemtype=\"http:\/\/schema.org\/ImageObject\">\n<p><img fetchpriority=\"high\" decoding=\"async\" alt=\"Vista da exposi\u00e7\u00e3o.  Foto: Museu Carmen Thyssen\" height=\"1030\" src=\"https:\/\/s1.eestatic.com\/2022\/12\/12\/actualidad\/725437940_229414231_1706x1030.jpg\" width=\"1706\" data-lazy-status=\"processed\" data-lazy-info=\"remove loading item 1\"\/><\/p>\n<div class=\"article-media__caption\">\n<p>\n                    <span class=\"article-media__caption-description\"><\/p>\n<p>                                    Vista da exposi\u00e7\u00e3o.  Foto: Museu Carmen Thyssen<br \/>\n                            <\/span><\/p>\n<\/div><\/div>\n<p class=\"paragraph\" id=\"paragraph_3\">J\u00e1 na habitual sala de exposi\u00e7\u00f5es do terceiro piso, s\u00e3o abordados os v\u00e1rios movimentos, incentivados por <strong>Oitava Maus<\/strong>advogado e cr\u00edtico de arte que promoveu a funda\u00e7\u00e3o de Les XX e La Libre Esth\u00e9tique, em cujos sal\u00f5es exibiu o melhor dos impressionistas e p\u00f3s-impressionistas franceses, beneficiando de um mercado florescente mantido por uma burguesia poderosa na vanguarda da revolu\u00e7\u00e3o industrial .<\/p>\n<p class=\"paragraph\" id=\"paragraph_4\"><em>[La magia cotidiana de Magritte]<\/em><\/p>\n<p class=\"paragraph\" id=\"paragraph_5\">Por meio de paisagens e retratos de mulheres em estilo impressionista, como <em>mulher em um interior<\/em>1886, de <strong>Guillaume van Strydonck<\/strong>chegamos \u00e0 peculiar absor\u00e7\u00e3o do pontilhismo de Seurat com obras muito poderosas, como a grande tela de <strong>Theo Van Rysselberghe<\/strong>, <em>ch\u00e1 no jardim<\/em>1901, retratando tr\u00eas mulheres, o poeta belga <strong>Marie Closet<\/strong>conhecido sob o pseud\u00f4nimo de Jean Dominique, e o cantor <strong>Laura Fle<\/strong> com a esposa do pintor.  Tamb\u00e9m \u00e9 interessante <em>dunas ao sol<\/em>, h.  1903, de <strong>Anna Boch<\/strong>\u00fanico integrante do grupo vanguardista Les XX, que como colecionador tamb\u00e9m foi a \u00fanica pessoa que comprou um quadro de Vincent van Gogh em vida.<\/p>\n<div class=\"article-media \" itemscope=\"\" itemtype=\"http:\/\/schema.org\/ImageObject\">\n<p><img loading=\"lazy\" decoding=\"async\" alt=\"Anna Boch: 'Dunas ao sol', c.  1903\" height=\"1072\" loading=\"lazy\" width=\"1706\" data-lazy-status=\"processed\" id=\"a8e26b4f50\" src=\"https:\/\/www.elespanol.com\/el-cultural\/arte\/20221213\/belga-magritte-exposicion-carmen-thyssen-malaga-demuestra\/[\" https:=\"\" data-lazy-info=\"changed src\"\/><\/p>\n<div class=\"article-media__caption\">\n<p>\n                    <span class=\"article-media__caption-description\"><\/p>\n<p>                                    Anna Boch: &#8216;Dunas ao sol&#8217;, c.  1903<br \/>\n                            <\/span><\/p>\n<\/div><\/div>\n<p class=\"paragraph\" id=\"paragraph_6\">A proposta do Nabis teve um representante muito original em<strong> Georges Lemen<\/strong>.  Assim como o Fauvismo, no qual se destaca <strong>jos alberto<\/strong> com <em>o grande interior<\/em>1914. Por outro lado, o importante <em>arte Nova<\/em> capitaneado por <strong>Henry van de Velde<\/strong> e Victor Horta em Bruxelas, aqui com uma \u00fanica tela sobre o ideal do andr\u00f3gino.  Como a presen\u00e7a, apenas no papel, dos simbolistas fica aqu\u00e9m <strong>Felicien Rops<\/strong> e <strong>Fernand Khnopff<\/strong>.  E da Ensor, sempre impressionante.<\/p>\n<div class=\"article-media \" itemscope=\"\" itemtype=\"http:\/\/schema.org\/ImageObject\">\n<p><img loading=\"lazy\" decoding=\"async\" alt=\"Jos Albert: 'O grande interior', 1914 (detalhe)\" height=\"2302\" loading=\"lazy\" width=\"1706\" data-lazy-status=\"processed\" id=\"17433f5468\" src=\"https:\/\/www.elespanol.com\/el-cultural\/arte\/20221213\/belga-magritte-exposicion-carmen-thyssen-malaga-demuestra\/[\" https:=\"\" data-lazy-info=\"changed src\"\/><\/p>\n<div class=\"article-media__caption\">\n<p>\n                    <span class=\"article-media__caption-description\"><\/p>\n<p>                                    Jos Albert: &#8216;O grande interior&#8217;, 1914 (detalhe)<br \/>\n                            <\/span><\/p>\n<\/div><\/div>\n<p class=\"paragraph\" id=\"paragraph_7\">A festa final vem com os surrealistas Paul Delvaux e Magritte, que foram fortemente influenciados por De Chirico no in\u00edcio, juntamente com <strong>Gustave DeSmet<\/strong> que, com suas cores planas, aponta para a tradi\u00e7\u00e3o marcante da arte gr\u00e1fica na B\u00e9lgica.<\/p>\n<h3 class=\"follow-topics-title\"><span class=\"follow-topics-title__icon\"\/>Siga os t\u00f3picos que lhe interessam<\/h3>\n<\/p><\/div>\n","protected":false},"excerpt":{"rendered":"<p>[ad_1] \u00c0 exce\u00e7\u00e3o do surrealista Ren\u00e9 Magritte e de alguns simbolistas, a tradi\u00e7\u00e3o pict\u00f3rica belga moderna \u00e9 pouco conhecida no &hellip; <\/p>\n","protected":false},"author":1,"featured_media":775,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"fifu_image_url":"https:\/\/s1.eestatic.com\/2022\/12\/12\/el-cultural\/arte\/725437928_229430175_600x315.jpg","fifu_image_alt":"","footnotes":""},"categories":[34],"tags":[],"class_list":["post-774","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-arte","latest_post"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>a exposi\u00e7\u00e3o no museu Carmen Thyssen em M\u00e1laga que o comprova - Tirinha.com<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/tirinha.com\/bn\/774\/a-exposicao-no-museu-carmen-thyssen-em-malaga-que-o-comprova\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"a exposi\u00e7\u00e3o no museu Carmen Thyssen em M\u00e1laga que o comprova - Tirinha.com\" \/>\n<meta property=\"og:description\" content=\"[ad_1] \u00c0 exce\u00e7\u00e3o do surrealista Ren\u00e9 Magritte e de alguns simbolistas, a tradi\u00e7\u00e3o pict\u00f3rica belga moderna \u00e9 pouco conhecida no &hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/tirinha.com\/bn\/774\/a-exposicao-no-museu-carmen-thyssen-em-malaga-que-o-comprova\/\" \/>\n<meta property=\"og:site_name\" content=\"Tirinha.com\" \/>\n<meta property=\"article:published_time\" content=\"2023-03-03T13:08:52+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/s1.eestatic.com\/2022\/12\/12\/el-cultural\/arte\/725437928_229430175_600x315.jpg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/s1.eestatic.com\/2022\/12\/12\/el-cultural\/arte\/725437928_229430175_600x315.jpg\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 \u09ae\u09bf\u09a8\u09bf\u099f\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/tirinha.com\\\/774\\\/a-exposicao-no-museu-carmen-thyssen-em-malaga-que-o-comprova\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/tirinha.com\\\/774\\\/a-exposicao-no-museu-carmen-thyssen-em-malaga-que-o-comprova\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/tirinha.com\\\/#\\\/schema\\\/person\\\/e22bdfbe17e0461f7e927e6a1208d4d9\"},\"headline\":\"a exposi\u00e7\u00e3o no museu Carmen Thyssen em M\u00e1laga que o comprova\",\"datePublished\":\"2023-03-03T13:08:52+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/tirinha.com\\\/774\\\/a-exposicao-no-museu-carmen-thyssen-em-malaga-que-o-comprova\\\/\"},\"wordCount\":534,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/tirinha.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/tirinha.com\\\/774\\\/a-exposicao-no-museu-carmen-thyssen-em-malaga-que-o-comprova\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/s1.eestatic.com\\\/2022\\\/12\\\/12\\\/el-cultural\\\/arte\\\/725437928_229430175_600x315.jpg\",\"articleSection\":[\"Arte\"],\"inLanguage\":\"bn-BD\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/tirinha.com\\\/774\\\/a-exposicao-no-museu-carmen-thyssen-em-malaga-que-o-comprova\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/tirinha.com\\\/774\\\/a-exposicao-no-museu-carmen-thyssen-em-malaga-que-o-comprova\\\/\",\"url\":\"https:\\\/\\\/tirinha.com\\\/774\\\/a-exposicao-no-museu-carmen-thyssen-em-malaga-que-o-comprova\\\/\",\"name\":\"a exposi\u00e7\u00e3o no museu Carmen Thyssen em M\u00e1laga que o comprova - Tirinha.com\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/tirinha.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/tirinha.com\\\/774\\\/a-exposicao-no-museu-carmen-thyssen-em-malaga-que-o-comprova\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/tirinha.com\\\/774\\\/a-exposicao-no-museu-carmen-thyssen-em-malaga-que-o-comprova\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/s1.eestatic.com\\\/2022\\\/12\\\/12\\\/el-cultural\\\/arte\\\/725437928_229430175_600x315.jpg\",\"datePublished\":\"2023-03-03T13:08:52+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/tirinha.com\\\/774\\\/a-exposicao-no-museu-carmen-thyssen-em-malaga-que-o-comprova\\\/#breadcrumb\"},\"inLanguage\":\"bn-BD\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/tirinha.com\\\/774\\\/a-exposicao-no-museu-carmen-thyssen-em-malaga-que-o-comprova\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"bn-BD\",\"@id\":\"https:\\\/\\\/tirinha.com\\\/774\\\/a-exposicao-no-museu-carmen-thyssen-em-malaga-que-o-comprova\\\/#primaryimage\",\"url\":\"https:\\\/\\\/s1.eestatic.com\\\/2022\\\/12\\\/12\\\/el-cultural\\\/arte\\\/725437928_229430175_600x315.jpg\",\"contentUrl\":\"https:\\\/\\\/s1.eestatic.com\\\/2022\\\/12\\\/12\\\/el-cultural\\\/arte\\\/725437928_229430175_600x315.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/tirinha.com\\\/774\\\/a-exposicao-no-museu-carmen-thyssen-em-malaga-que-o-comprova\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/tirinha.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"a exposi\u00e7\u00e3o no museu Carmen Thyssen em M\u00e1laga que o comprova\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/tirinha.com\\\/#website\",\"url\":\"https:\\\/\\\/tirinha.com\\\/\",\"name\":\"Tirinha.com\",\"description\":\"Arte e livros resenhas\",\"publisher\":{\"@id\":\"https:\\\/\\\/tirinha.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/tirinha.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"bn-BD\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/tirinha.com\\\/#organization\",\"name\":\"Tirinha.com\",\"url\":\"https:\\\/\\\/tirinha.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"bn-BD\",\"@id\":\"https:\\\/\\\/tirinha.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/tirinha.com\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/cropped-Logo-Tirinha.webp\",\"contentUrl\":\"https:\\\/\\\/tirinha.com\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/cropped-Logo-Tirinha.webp\",\"width\":512,\"height\":512,\"caption\":\"Tirinha.com\"},\"image\":{\"@id\":\"https:\\\/\\\/tirinha.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/tirinha.com\\\/#\\\/schema\\\/person\\\/e22bdfbe17e0461f7e927e6a1208d4d9\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"bn-BD\",\"@id\":\"https:\\\/\\\/tirinha.com\\\/wp-content\\\/litespeed\\\/avatar\\\/d0068f7931cc87d7274eb0c3db1deb4b.jpg?ver=1778039150\",\"url\":\"https:\\\/\\\/tirinha.com\\\/wp-content\\\/litespeed\\\/avatar\\\/d0068f7931cc87d7274eb0c3db1deb4b.jpg?ver=1778039150\",\"contentUrl\":\"https:\\\/\\\/tirinha.com\\\/wp-content\\\/litespeed\\\/avatar\\\/d0068f7931cc87d7274eb0c3db1deb4b.jpg?ver=1778039150\",\"caption\":\"admin\"},\"sameAs\":[\"https:\\\/\\\/tirinha.com\"],\"url\":\"https:\\\/\\\/tirinha.com\\\/bn\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"a exposi\u00e7\u00e3o no museu Carmen Thyssen em M\u00e1laga que o comprova - Tirinha.com","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/tirinha.com\/bn\/774\/a-exposicao-no-museu-carmen-thyssen-em-malaga-que-o-comprova\/","og_locale":"en_US","og_type":"article","og_title":"a exposi\u00e7\u00e3o no museu Carmen Thyssen em M\u00e1laga que o comprova - Tirinha.com","og_description":"[ad_1] \u00c0 exce\u00e7\u00e3o do surrealista Ren\u00e9 Magritte e de alguns simbolistas, a tradi\u00e7\u00e3o pict\u00f3rica belga moderna \u00e9 pouco conhecida no &hellip;","og_url":"https:\/\/tirinha.com\/bn\/774\/a-exposicao-no-museu-carmen-thyssen-em-malaga-que-o-comprova\/","og_site_name":"Tirinha.com","article_published_time":"2023-03-03T13:08:52+00:00","og_image":[{"url":"https:\/\/s1.eestatic.com\/2022\/12\/12\/el-cultural\/arte\/725437928_229430175_600x315.jpg","type":"","width":"","height":""}],"author":"admin","twitter_card":"summary_large_image","twitter_image":"https:\/\/s1.eestatic.com\/2022\/12\/12\/el-cultural\/arte\/725437928_229430175_600x315.jpg","twitter_misc":{"Written by":"admin","Est. reading time":"3 \u09ae\u09bf\u09a8\u09bf\u099f"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/tirinha.com\/774\/a-exposicao-no-museu-carmen-thyssen-em-malaga-que-o-comprova\/#article","isPartOf":{"@id":"https:\/\/tirinha.com\/774\/a-exposicao-no-museu-carmen-thyssen-em-malaga-que-o-comprova\/"},"author":{"name":"admin","@id":"https:\/\/tirinha.com\/#\/schema\/person\/e22bdfbe17e0461f7e927e6a1208d4d9"},"headline":"a exposi\u00e7\u00e3o no museu Carmen Thyssen em M\u00e1laga que o comprova","datePublished":"2023-03-03T13:08:52+00:00","mainEntityOfPage":{"@id":"https:\/\/tirinha.com\/774\/a-exposicao-no-museu-carmen-thyssen-em-malaga-que-o-comprova\/"},"wordCount":534,"commentCount":0,"publisher":{"@id":"https:\/\/tirinha.com\/#organization"},"image":{"@id":"https:\/\/tirinha.com\/774\/a-exposicao-no-museu-carmen-thyssen-em-malaga-que-o-comprova\/#primaryimage"},"thumbnailUrl":"https:\/\/s1.eestatic.com\/2022\/12\/12\/el-cultural\/arte\/725437928_229430175_600x315.jpg","articleSection":["Arte"],"inLanguage":"bn-BD","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/tirinha.com\/774\/a-exposicao-no-museu-carmen-thyssen-em-malaga-que-o-comprova\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/tirinha.com\/774\/a-exposicao-no-museu-carmen-thyssen-em-malaga-que-o-comprova\/","url":"https:\/\/tirinha.com\/774\/a-exposicao-no-museu-carmen-thyssen-em-malaga-que-o-comprova\/","name":"a exposi\u00e7\u00e3o no museu Carmen Thyssen em M\u00e1laga que o comprova - Tirinha.com","isPartOf":{"@id":"https:\/\/tirinha.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/tirinha.com\/774\/a-exposicao-no-museu-carmen-thyssen-em-malaga-que-o-comprova\/#primaryimage"},"image":{"@id":"https:\/\/tirinha.com\/774\/a-exposicao-no-museu-carmen-thyssen-em-malaga-que-o-comprova\/#primaryimage"},"thumbnailUrl":"https:\/\/s1.eestatic.com\/2022\/12\/12\/el-cultural\/arte\/725437928_229430175_600x315.jpg","datePublished":"2023-03-03T13:08:52+00:00","breadcrumb":{"@id":"https:\/\/tirinha.com\/774\/a-exposicao-no-museu-carmen-thyssen-em-malaga-que-o-comprova\/#breadcrumb"},"inLanguage":"bn-BD","potentialAction":[{"@type":"ReadAction","target":["https:\/\/tirinha.com\/774\/a-exposicao-no-museu-carmen-thyssen-em-malaga-que-o-comprova\/"]}]},{"@type":"ImageObject","inLanguage":"bn-BD","@id":"https:\/\/tirinha.com\/774\/a-exposicao-no-museu-carmen-thyssen-em-malaga-que-o-comprova\/#primaryimage","url":"https:\/\/s1.eestatic.com\/2022\/12\/12\/el-cultural\/arte\/725437928_229430175_600x315.jpg","contentUrl":"https:\/\/s1.eestatic.com\/2022\/12\/12\/el-cultural\/arte\/725437928_229430175_600x315.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/tirinha.com\/774\/a-exposicao-no-museu-carmen-thyssen-em-malaga-que-o-comprova\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/tirinha.com\/"},{"@type":"ListItem","position":2,"name":"a exposi\u00e7\u00e3o no museu Carmen Thyssen em M\u00e1laga que o comprova"}]},{"@type":"WebSite","@id":"https:\/\/tirinha.com\/#website","url":"https:\/\/tirinha.com\/","name":"\u0995\u09ae\u09bf\u0995 \u09b8\u09cd\u099f\u09cd\u09b0\u09bf\u09aa.\u0995\u09ae","description":"\u09b6\u09bf\u09b2\u09cd\u09aa\u0995\u09b2\u09be \u098f\u09ac\u0982 \u09ac\u0987 \u09aa\u09b0\u09cd\u09af\u09be\u09b2\u09cb\u099a\u09a8\u09be","publisher":{"@id":"https:\/\/tirinha.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/tirinha.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"bn-BD"},{"@type":"Organization","@id":"https:\/\/tirinha.com\/#organization","name":"\u0995\u09ae\u09bf\u0995 \u09b8\u09cd\u099f\u09cd\u09b0\u09bf\u09aa.\u0995\u09ae","url":"https:\/\/tirinha.com\/","logo":{"@type":"ImageObject","inLanguage":"bn-BD","@id":"https:\/\/tirinha.com\/#\/schema\/logo\/image\/","url":"https:\/\/tirinha.com\/wp-content\/uploads\/2023\/08\/cropped-Logo-Tirinha.webp","contentUrl":"https:\/\/tirinha.com\/wp-content\/uploads\/2023\/08\/cropped-Logo-Tirinha.webp","width":512,"height":512,"caption":"Tirinha.com"},"image":{"@id":"https:\/\/tirinha.com\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/tirinha.com\/#\/schema\/person\/e22bdfbe17e0461f7e927e6a1208d4d9","name":"\u0985\u09cd\u09af\u09be\u09a1\u09ae\u09bf\u09a8","image":{"@type":"ImageObject","inLanguage":"bn-BD","@id":"https:\/\/tirinha.com\/wp-content\/litespeed\/avatar\/d0068f7931cc87d7274eb0c3db1deb4b.jpg?ver=1778039150","url":"https:\/\/tirinha.com\/wp-content\/litespeed\/avatar\/d0068f7931cc87d7274eb0c3db1deb4b.jpg?ver=1778039150","contentUrl":"https:\/\/tirinha.com\/wp-content\/litespeed\/avatar\/d0068f7931cc87d7274eb0c3db1deb4b.jpg?ver=1778039150","caption":"admin"},"sameAs":["https:\/\/tirinha.com"],"url":"https:\/\/tirinha.com\/bn\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/tirinha.com\/bn\/wp-json\/wp\/v2\/posts\/774","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tirinha.com\/bn\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tirinha.com\/bn\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tirinha.com\/bn\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/tirinha.com\/bn\/wp-json\/wp\/v2\/comments?post=774"}],"version-history":[{"count":0,"href":"https:\/\/tirinha.com\/bn\/wp-json\/wp\/v2\/posts\/774\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tirinha.com\/bn\/wp-json\/wp\/v2\/media\/775"}],"wp:attachment":[{"href":"https:\/\/tirinha.com\/bn\/wp-json\/wp\/v2\/media?parent=774"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tirinha.com\/bn\/wp-json\/wp\/v2\/categories?post=774"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tirinha.com\/bn\/wp-json\/wp\/v2\/tags?post=774"}],"curies":[{"name":"\u09a1\u09ac\u09cd\u09b2\u09bf\u0989\u09aa\u09bf","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}